{"id":29840,"date":"2014-05-29T11:44:16","date_gmt":"2014-05-29T09:44:16","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=29840"},"modified":"2014-05-29T11:44:16","modified_gmt":"2014-05-29T09:44:16","slug":"la-tradinnovazione-dei-mascarimiri-approda-a-pechino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/29\/la-tradinnovazione-dei-mascarimiri-approda-a-pechino\/","title":{"rendered":"LA TRADINNOVAZIONE DEI MASCARIMIR\u00cc APPRODA A PECHINO"},"content":{"rendered":"<div align=\"justify\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/BodyPart7.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/BodyPart7.jpeg\" alt=\"\" title=\"BodyPart\" width=\"600\" height=\"284\" class=\"alignleft size-full wp-image-29841\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/BodyPart7.jpeg 600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/BodyPart7-300x142.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a>Prosegue in Italia e all&#8217;estero il tour di presentazione di\u00a0<strong>Tam!<\/strong>, nuovo progetto discografico dei salentini\u00a0<strong>Mascarimir\u00ec<\/strong>, prodotto da\u00a0<strong>Dilin\u00f2<\/strong>\u00a0e promosso con il sostegno di\u00a0<strong>Puglia Sounds Record<\/strong>.\u00a0<strong>Venerd\u00ec 30 maggio<\/strong>\u00a0il gruppo salentino sar\u00e0 in concerto presso l&#8217;<strong>Ambasciata italiana a Pechino<\/strong>\u00a0per un concerto organizzato dall&#8217;Istituto di Cultura italiana della capitale cinese in occasione delle celebrazioni per la\u00a0<strong>Festa della Repubblica Italiana<\/strong>. Inoltre la band \u00e8 attualmente seconda (dopo essere stata a lungo in vetta) nella classifica del prestigioso sito giapponese di vendita on line dedicato alla worl music El Sur Records (<a href=\"http:\/\/www.elsurrecords.com\/\" target=\"_blank\">www.elsurrecords.com<\/a>).<\/p>\n<p><strong>Luned\u00ec 2 giugn<\/strong><strong>o<\/strong>\u00a0la band far\u00e0 poi ritorno in Italia per la\u00a0<strong>Festa dei Popoli\u00a0<\/strong>di\u00a0<strong>Bari<\/strong>. Nuove date in Francia a giugno (7 a St Michele de Lan\u00e8s, 8 a La Ciotat, 13 a Montlu\u00e7on e 20 a Montreuil) prima dell&#8217;importante appuntamento di\u00a0<strong>Parigi<\/strong>\u00a0in occasione della\u00a0<strong>Festa della musica\u00a0<\/strong>che si celebra ogni anno il 21 giugno.<\/p>\n<\/div>\n<div align=\"justify\">Nati tra il 1997 e il 1998 come progetto di musica tradizionale salentina, i Mascarimir\u00ec sono\u00a0<a href=\"https:\/\/webmaildomini.aruba.it\/ext_aruba\/classic\/html\/mainframe.html?_v_=v4r2b24pl1m1.20140409_1715?lang=it&amp;flavour=orange&amp;theme=ext_aruba\/classic&amp;useSprite=0\">oggi<\/a>\u00a0tra i gruppi pi\u00f9 rappresentativi della scena world italiana. Guidati da Claudio Cavallo Giagnotti, musicista di origini Rom, negli anni hanno sperimentato innesti tra suoni tradizionali e sonorit\u00e0 dub sino ad arrivare al punk-dub tarantolato. Si sono esibiti in importanti festival e manifestazioni musicali tra i quali Womex, Fira de Manresa, La Notte della Taranta, Sziget Festival, Medimex, Total Festume\u00a0 e Womad. I Mascarimir\u00ec hanno collaborato, tra gli altri, con Joe Zawinul, Buena Vista Social Club, Les Negresses Vertes, Massilia Sound System, Mauro Pagani, Ludovico Einaudi e molti altri. Sul palco Claudio \u201cCavallo\u201d Giagnotti (voce, fiati etnici, tamburreddhu, tamburi) \u00e8 affiancato da Vito Giannone (voce, mandolino elettrico, tres), Alessio Amato (voce, programmazioni, syinth) e Dario Stefanizzi (fiati).<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/29\/la-tradinnovazione-dei-mascarimiri-approda-a-pechino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/29\/la-tradinnovazione-dei-mascarimiri-approda-a-pechino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Prosegue in Italia e all&#8217;estero il tour di presentazione di\u00a0Tam!, nuovo progetto discografico dei salentini\u00a0Mascarimir\u00ec, prodotto da\u00a0Dilin\u00f2\u00a0e promosso con il sostegno di\u00a0Puglia Sounds Record.\u00a0Venerd\u00ec 30 maggio\u00a0il gruppo salentino sar\u00e0 in concerto presso l&#8217;Ambasciata italiana a Pechino\u00a0per un concerto organizzato dall&#8217;Istituto di Cultura italiana della capitale cinese in occasione delle celebrazioni per la\u00a0Festa della Repubblica Italiana. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29841,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29840"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=29840"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29840\/revisions"}],"predecessor-version":[{"id":29844,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29840\/revisions\/29844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/29841"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=29840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=29840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=29840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}