{"id":29931,"date":"2014-05-31T09:03:00","date_gmt":"2014-05-31T07:03:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=29931"},"modified":"2014-05-31T09:06:19","modified_gmt":"2014-05-31T07:06:19","slug":"turno-di-ballottaggio-a-copertino-la-posizione-di-fratelli-ditalia-alleanza-nazionale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/31\/turno-di-ballottaggio-a-copertino-la-posizione-di-fratelli-ditalia-alleanza-nazionale\/","title":{"rendered":"Turno di ballottaggio a Copertino: la posizione di Fratelli d&#8217;Italia &#8211; Alleanza Nazionale"},"content":{"rendered":"<div style=\"text-align: left;\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Giuseppe-Pede-amministrative-2014.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Giuseppe-Pede-amministrative-2014.jpg\" alt=\"\" title=\"Giuseppe Pede - amministrative 2014\" width=\"775\" height=\"973\" class=\"alignleft size-full wp-image-29932\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Giuseppe-Pede-amministrative-2014.jpg 775w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/05\/Giuseppe-Pede-amministrative-2014-238x300.jpg 238w\" sizes=\"(max-width: 775px) 100vw, 775px\" \/><\/a>&#8220;Premesso che al turno di ballottaggio ogni lista \u00e8 autonoma e indipendente nelle scelta di apparentarsi o meno con le coalizioni sfidanti (ammesso che quest&#8217;ultime accettino) o di sostenerle dall&#8217;esterno, Fratelli d&#8217;Italia ha una posizione chiara a riguardo: non sosterr\u00e0 nessuno dei candidati sindaco che andranno al ballottaggio domenica 8 giugno semplicemente perch\u00e8 non ci rappresentano.&#8221; lo dichiara Giuseppe Pede, portavoce di Fratelli d&#8217;Italia &#8211; Alleanza Nazionale. &#8220;Il mio auspicio \u00e8 che anche le altre forze della coalizione di Vincenzo De Giorgi facciano la nostra stessa scelta. Oltretutto mi auguro che anche le liste facenti capo al candidato sindaco Dott. Pierluigi Pando, essendo forze di centro destra, non facciano da stampella alla sinistra con apparentamenti strani e incomprensibili, anche se legittimi, pur di avere una poltrona in pi\u00f9. Lasciamo al Nuovo Centro Destra (NCD) di Alfano e di Mazzotta questi strani inciuci. Non replichiamo a livello locale la schifosa maggioranza dei governi Monti e Letta.&#8221;<\/div>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/31\/turno-di-ballottaggio-a-copertino-la-posizione-di-fratelli-ditalia-alleanza-nazionale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/31\/turno-di-ballottaggio-a-copertino-la-posizione-di-fratelli-ditalia-alleanza-nazionale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&#8220;Premesso che al turno di ballottaggio ogni lista \u00e8 autonoma e indipendente nelle scelta di apparentarsi o meno con le coalizioni sfidanti (ammesso che quest&#8217;ultime accettino) o di sostenerle dall&#8217;esterno, Fratelli d&#8217;Italia ha una posizione chiara a riguardo: non sosterr\u00e0 nessuno dei candidati sindaco che andranno al ballottaggio domenica 8 giugno semplicemente perch\u00e8 non ci [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29932,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29931"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=29931"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29931\/revisions"}],"predecessor-version":[{"id":29938,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29931\/revisions\/29938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/29932"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=29931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=29931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=29931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}