{"id":29963,"date":"2014-05-31T19:19:25","date_gmt":"2014-05-31T17:19:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=29963"},"modified":"2014-05-31T19:28:38","modified_gmt":"2014-05-31T17:28:38","slug":"on-the-road-nel-salento-per-la-bellezza-dei-libri-paola-bisconti-si-racconta","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/31\/on-the-road-nel-salento-per-la-bellezza-dei-libri-paola-bisconti-si-racconta\/","title":{"rendered":"On the road nel Salento per la bellezza dei libri\/ PAOLA BISCONTI SI RACCONTA"},"content":{"rendered":"<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: small;\"><strong>(Rdl) Si \u00e8 appena conclusa l&#8217;esperienza di \u201cPianissimo\u201d, il giro del Salento, a bordo di\u00a0 un furgone, durato otto giorni, per promuovere il piacere della lettura.<\/strong><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: small;\"><strong>La consideriamo un&#8217;iniziativa nobile, concreta e spontanea, per la diffusione della cultura popolare. <\/strong><\/span><\/span><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: small;\"><strong>Per questo motivo, abbiamo chiesto a Paola Bisconti, che l&#8217;ha organizzata, di parlarci della sua esperienza. <\/strong><\/span><\/span><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: small;\"><strong>Con le foto di Cristian Tondo, quello che segue\u00a0 \u00e8 il suo racconto in esclusiva, di cui la ringraziamo: come \u00e8 nata l&#8217;avventura, che cosa significa, con chi l&#8217;ha condivisa&#8230;E con un po&#8217; della sua vita. <\/strong><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: small;\"><span style=\"font-size: medium;\">Quello che sto per raccontarvi \u00e8 un capitolo della mia vita che potrebbe non interessare a nessuno se non fosse per il fatto che riguarda tutti. <\/span><\/span><\/span><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Era l\u2019estate dei miei 12 anni, quella in cui tutto cambi\u00f2. No! Non solo perch\u00e9 conobbi l\u2019uomo che \u00e8 diventato mio marito, ma soprattutto perch\u00e9 non trascorse giorno senza che leggessi 10, 20, 30 pagine di un libro. Fu &#8211; a tutti gli effetti &#8211; la stagione dell\u2019amore. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Tanto quanto mangiare, bere, dormire, anche l\u2019azione del leggere era diventata un\u2019esigenza, un bisogno al quale corpo e mente non potevano pi\u00f9 sottrarsi. Da allora niente e nessuno mi ha separato dai libri &#8211; e neanche da quell\u2019uomo che \u00e8 diventato mio marito.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Arrivarono gli anni del liceo e come per magia iniziai a ricevere ottimi voti nelle materie letterarie. Stimolata per giunta da una professoressa amante della lettura, noi alunne eravamo costantemente nutrite dai libri\u00a0 come fossero pane quotidiano. Una volta diplomata pensai fosse arrivato il momento di realizzare quel sogno nel cassetto, tenuto l\u00ec ben custodito. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Decidere di aprire una libreria in un piccolo paese come Cavallino, avviare un\u2019attivit\u00e0 commerciale senza avere alcuna esperienza alle spalle e per giunta nel settore <\/span><\/span><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">culturale significava andare incontro ad un vero e proprio suicidio. Almeno questo era quello che pensavano gli altri, io ero &#8211; e lo sono ancora &#8211; determinata, entusiasta, ottimista. Ma si sa \u2026 l\u2019affitto, le bollette e tutto il resto non si possono certo pagare con i buoni sentimenti. Cos\u00ec a malincuore abbandonai ogni pianificazione convinta che mai pi\u00f9 sarei riuscita a risollevarmi da quell\u2019amara delusione.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">L\u2019introito ricavato da lavori, lavoretti, impiegucci rimargin\u00f2 la ferita aperta del mio cuore che soffriva ancora per la prima vera sconfitta presentatami dalla vita. Rinunciare all\u2019apertura di una libreria significava perdere l\u2019occasione di offrire a un\u2019intera comunit\u00e0 la possibilit\u00e0 di ritrovarsi in un luogo che non fosse il bar della piazza dove la massima offerta di socializzazione era giocare a carte; di incontrarsi in un luogo alternativo alla biblioteca dove poter studiare magari con un sottofondo musicale; di poter vivere un luogo inteso come crogiuolo di energie, creativit\u00e0, entusiasmi giovanili e non.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Con i piedi di piombo attraversai le strade che il destino aveva scritto per me, percorsi con impegno e dedizione tragitti che colmarono quel dispiacere grazie alle meravigliose esperienze professionali che mi hanno permesso di raggiungere piccoli e grandi traguardi, tutti appuntati nel libro della mia vita. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Diventai cos\u00ec giornalista riuscendo con mia profonda soddisfazione e con non poco sacrificio ad operare nel settore culturale. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Ed \u00e8 stato mentre svolgevo il mio lavoro che sono venuta a conoscenza di un progetto che ho sempre definito tanto semplice quanto rivoluzionario. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Si chiama \u201cLittle Free Library\u201d, il movimento culturale americano che nell\u2019arco di pochi mesi \u00e8 diventato internazionale approdando anche in Italia. L\u2019iniziativa consiste nell\u2019installare piccole casette di legno in ville, parchi e piazze contenenti dei libri che possono essere presi in prestito da chiunque. Adulti e bambini, infatti, hanno la possibilit\u00e0 di tenere con s\u00e9 il testo che ritiene pi\u00f9 interessante, leggerlo e riportarlo indietro senza alcuna scadenza temporale. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Valutando l\u2019idea a dir poco eccezionale mi sono armata di sano ottimismo e ho ragionato sulla possibilit\u00e0 di proporla nel mio paese. Lo stesso nel quale anni prima avrei voluto aprire una libreria. Questa volta per\u00f2 nonostante gli avvertimenti del tipo \u201cMa tu davvero credi che tutti potranno apprezzare la proposta?\u201d oppure \u201cI vandali la distruggerebbero subito\u201d e ancora \u201cDi certo nessuno riporter\u00e0 i libri indietro\u201d. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Questa volta per\u00f2 a differenza della precedente esperienza ho voluto far di testa mia e con tenacia ho seguito l\u2019iter che mi ha permesso di realizzare ci\u00f2 che oggi \u00e8 una felice realt\u00e0. Sostenuta economicamente dall\u2019amministrazione comunale di Cavallino che ha coperto le spese del materiale e coadiuvata<\/span><\/span> <span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">dall\u2019appoggio dell\u2019uomo conosciuto nell\u2019estate dei miei 12 anni che \u00e8 poi diventato mio marito, ho portato a compimento il sogno di una vita.\u00a0 <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">L\u20198 maggio 2013 sono state inaugurate insieme agli alunni dell\u2019Istituto Comprensivo L. Da Vinci di Cavallino, ben cinque mini biblioteche \u2013 su ognuna delle quali \u00e8<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">affissa una targhetta con un numero di matricola che consente di visualizzarle sulla Google Maps -. In quella felice circostanza sono stati raccolti oltre duecento libri donati dagli alunni dei plessi di Cavallino e Castromediano. Questa generosit\u00e0 \u00e8 stata solo una delle tante dimostrazioni di entusiasmo da parte dei miei concittadini che a dispetto di ogni convinzione hanno saputo accogliere l\u2019iniziativa con\u00a0 gioia.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Nonostante la prima notte siano state semi distrutte due casette per mezzo di alcuni incivili che come zombi brancolano nel buio dell\u2019ignoranza, io e mio marito abbiamo riparato le mini biblioteche e ricollocate in zone molto pi\u00f9 controllate. Ora le casette sono diventate un punto di ritrovo per le famiglie, i bambini usufruiscono del servizio con un entusiasmo indescrivibile, i genitori consultano i testi riordinandoli come se fosse la propria libreria. Sono stati in molti a consegnarmi dei libri da posizionare all\u2019interno delle varie casette, sono stata contattata dalle case editrici cos\u00ec come dai librai che con una generosit\u00e0 inverosimile hanno messo a disposizione numerosi volumi per contribuire a tenere costantemente rifornite le mini biblioteche. Gli organi di informazione si sono soffermati sul caso mettendo in risalto un progetto che contribuisce a valorizzare il libro inteso come strumento di socializzazione, dialogo, condivisione. Con la \u201cLittle Free Library\u201d ci siamo resi conto che tutto ci\u00f2 \u00e8 possibile e finalmente ho potuto dire a me stessa di essere riuscita a realizzare un sogno che credevo fosse stato infranto da un pessimismo che abbrutiva una realt\u00e0 forse non cos\u00ec deleteria come molti si ostinano a vedere.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Sulla scia di queste riflessioni, sempre grazie al mio mestiere, ho conosciuto una persona che forse \u2013 anzi senza ombra di dubbio &#8211; in un modo pi\u00f9 avventuroso del mio ha deciso di portare i libri l\u00ec dove si legge<\/span><\/span> <span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">molto poco. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Lui \u00e8 Filippo Nicosia e a bordo di Leggiu, un Fiat 900 Panorama, la scorsa estate ha attraversato la Sicilia. Il suo progetto si chiama \u201cPianissimo, libri sulla strada\u201d e altro non \u00e8 che una libreria itinerante perch\u00e9 se le persone non vanno dai libri, sono i libri ad andare dalle persone. Il trentenne siciliano ha inventato un nuovo modo di offrire la cultura, andando nelle piazze, incontrando la gente e offrendo l\u2019opportunit\u00e0 di confrontarsi attraverso un dialogo che pu\u00f2 scaturire dal brano di un libro. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Mi sembrava quindi che Pianissimo riproponesse in una versione meno statica ci\u00f2 che io avevo elaborato con le mini biblioteche, con una differenza sostanziale per\u00f2 &#8230; con la Little Free Library i libri si prendono in prestito, da Filippo invece i libri si comprano. Bisognava cos\u00ec soffermarsi su alcune considerazioni che pensavamo fossero scontate ma che poi in realt\u00e0 non lo erano. Il primo vero valore da attribuire al libro \u00e8 anzitutto quello economico. Ecco allora che due modi di diffondere la cultura e promuovere la lettura si sono incontrati. E\u2019 cos\u00ec che \u00e8 nato il tour nel Salento di Pianissimo svoltosi nella settimana che ha preceduto il primo anniversario della \u201cLittle Free Library\u201d di Cavallino. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Otto intense giornate trascorse insieme a Filippo Nicosia e a Chiara Baffa mi hanno consentito di fare un viaggio nel viaggio. Con loro ho<br \/>\nattraversato paesi e citt\u00e0 del nostro amato sud e ho potuto osservarli da una prospettiva diversa cogliendo ci\u00f2 che fino ad allora non ero riuscita a notare. Siamo stati a Lecce, nel cuore della Grec\u00eca Salentina, abbiamo incontrato gli alunni delle scuole e ricevuto una calorosa accoglienza da parte delle amministrazioni comunali. \u00c8 stato un tour intenso che si \u00e8 concluso con la festa del primo anniversario delle mini biblioteche nel parco della Casina Vernazza a Cavallino dove i bambini hanno partecipato alle letture ad alta voce eseguite da Filippo e insieme a me hanno ricordato i momenti dell\u2019inaugurazione avvenuta lo scorso anno per poi festeggiare la ricorrenza con un rinfresco offerto da un panificio del paese.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Ho ancora negli occhi i volti di tutti coloro che si sono avvicinati a \u201cLeggiu\u201d con aria incuriosita, di certo un po\u2019 divertiti nel vedere quella graziosa libreria ambulante ammaccata dalla ruggine, ma cos\u00ec affascinante.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Termina quindi il mio racconto forse troppo lungo ma mi auguro non altrettanto tedioso. \u201cPianissimo\u201d \u00e8 ritornato in Sicilia dove continua a svolgere la sua missione come del resto faccio io nel mio Salento, seppur in modo differente.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">L\u2019augurio pi\u00f9 sincero che possa fare a chi pazientemente \u00e8 riuscito ad arrivare alla fine di questo articolo \u2013 e anche a chi si \u00e8 fermato al decimo rigo &#8211; \u00e8 quello di lasciarvi sorprendere dalla meraviglia della lettura e da tutto ci\u00f2 che pu\u00f2 scaturire dalla bellezza di un libro. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><strong>Paola Bisconti<\/strong><\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\">\n<p>&nbsp;<\/p>\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\">\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/31\/on-the-road-nel-salento-per-la-bellezza-dei-libri-paola-bisconti-si-racconta\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/05\/31\/on-the-road-nel-salento-per-la-bellezza-dei-libri-paola-bisconti-si-racconta\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) Si \u00e8 appena conclusa l&#8217;esperienza di \u201cPianissimo\u201d, il giro del Salento, a bordo di\u00a0 un furgone, durato otto giorni, per promuovere il piacere della lettura. La consideriamo un&#8217;iniziativa nobile, concreta e spontanea, per la diffusione della cultura popolare. Per questo motivo, abbiamo chiesto a Paola Bisconti, che l&#8217;ha organizzata, di parlarci della sua esperienza. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29974,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29963"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=29963"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29963\/revisions"}],"predecessor-version":[{"id":29967,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/29963\/revisions\/29967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/29974"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=29963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=29963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=29963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}