{"id":30020,"date":"2014-06-01T15:02:18","date_gmt":"2014-06-01T13:02:18","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30020"},"modified":"2014-06-01T15:02:18","modified_gmt":"2014-06-01T13:02:18","slug":"gallipoli-ritirate-7-patenti-per-guida-in-stato-di-ebbrezza","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/01\/gallipoli-ritirate-7-patenti-per-guida-in-stato-di-ebbrezza\/","title":{"rendered":"GALLIPOLI: RITIRATE 7 PATENTI PER GUIDA IN STATO DI EBBREZZA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/Piantine-Web.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/Piantine-Web-300x178.jpg\" alt=\"\" title=\"Piantine-Web\" width=\"300\" height=\"178\" class=\"alignnone size-medium wp-image-30021\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/Piantine-Web-300x178.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/Piantine-Web.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Nei giorni del 31 maggio e 1 giugno i carabinieri della compagnia di Gallipoli, sono stati impegnati su tutto il territorio di loro competenza, con un capillare servizio coordinato a largo raggio.<br \/>\nIn sintesi, sono stati eseguiti controlli, principalmente finalizzati a contrastare il perpetrarsi di reati in genere, nonche\u2019 il fenomeno della guida in stato di ebbrezza, approfittando del fatto che questo weekend. l\u2019apertura dei lidi e di alcune discoteche della giursidizione, avrebbe certamente invogliato qualcuno ad alzare il gomito o ad approfittare degli assembramenti per commettere reati.<br \/>\nAll\u2019attivita\u2019 di controllo hanno partecipato pattuglie della dipendente aliquota radiomobile, nonche\u2019 militari della tenenza di copertino e delle stazioni dipendenti, per un totale di n.29 militari e n. 11 automezzi, coordinati dal comandante del nucleo operativo e radiomobile. Il dispositivo e\u2019 stato dispiegato principalmente nelle aree cittadine e periferiche di Gallipoli, Galatone, Nardo\u2019 e Copertino anche con l\u2019impiego di militari in abiti civili ed un\u2019unita\u2019 cinofila del nucleo cinofili di Modugno che si sono frammischiati alla gente che ha affollato il litorale di Gallipoli e le discoteche della giurisdizione<br \/>\nComplessivamente, i controlli hanno permesso di ottenere i seguenti risultati:<br \/>\nquattro soggetti sono stati deferiti in stato di liberta\u2019 per detenzione ai fini di spaccio di sostazne stupefacenti.<br \/>\nIl primo t.m. classe 1986, membro di una nota band salentina, e\u2019 stato trovato, a seguito di perquisizione domiciliare, in possesso di otto piantine di marijuana di un\u2019altezza media di 35 cm oltre ad un involucro con altri due grammi della medesima sostanza.<br \/>\nb.l., classe 1970, di Gallipoli, a seguito del controllo e della perquisizione veicolare, durante la quale aveva mostrato parecchio nervosismo, e\u2019 stato trovato con indosso un involucro con oltre 10 grammi di marijuana.<br \/>\np.f.g. classe 1995 di Nardo\u2019, invece, e\u2019 stata fermata e spontaneamente ha consegnato un involucro contenente 0,5 grammi di marijuana. risultando tuttavia molto nervosa, i militari hanno proseguito nella perquisizione veicolare, trovando un altro involucro contenente 2,5 grammi di eroina. vista la duplicita\u2019 della sostanza e le circostanze del ritrovamento, la giovane e\u2019 stata deferita in stato di liberta\u2019<br \/>\np.m. classe 1984, invece, a seguito della perquisizone veicolare e domiciliare e\u2019 stato trovato in possesso di oltre 20 grammi di marijuana in diversi involucri.<br \/>\nA Copertino i militari dell\u2019arma locale, durante un controllo, hanno fermato g.g.c. classe 1968 il quale, nonostante nella sua autovettura non fosse stato trovato nulla, appariva eccessivamente nervoso al controllo dei militari i quali hanno voluto estendere la perquisizione all\u2019abitazione. li\u2019 hanno ritrovato una miccia infiammabile incombusta della lunghezza di oltre mezzo metro. il possesso di questo oggetto, non giustificato dal copertinese e nemmeno dalla sua attivita\u2019 lavorativa, ha fatto scattare per lui il deferimento per omessa denuncia di materiale esplodente.<br \/>\nI controlli a tappeto in tutto il territorio della compagnia hanno altresi\u2019 permesso di reprimere anche una serie di reati contro il patrimonio.<br \/>\nA Sannicola, i militari dell\u2019arma locale hanno deferito in stato di liberta\u2019 un casertano classe 1962, m.c. con l\u2019accusa di truffa. con il solito, ed ormai collaudato, schema, il 52enne ha messo in vendita un telefono cellulare di ultima generazione facendosi mandare i soldi per poi scomparire.<br \/>\nDue persone sono state deferite in stato di liberta\u2019 per furto.<br \/>\nb.a. classe 1992, di Gallipoli, e\u2019 stato trovato in possesso di due botti da vino rubate due settimane fa in un noto lounge bar di Gallipoli. confrontando i caratteri somatici del b.a. con quelli all\u2019epoca estratti dalle immagini dell\u2019impianto di videosorveglianza dell\u2019esercizio pubblico, e\u2019 stato possibile identificare il soggetto quale l\u2019effettivo autore del furto.<br \/>\np.a. classe 1963 di Galatone, invece, e\u2019 stato deferito in stato di liberta\u2019 per il furto di una bibbia dall\u2019interno della caritas diocesana di galatone. il responsabile della struttura, accortosi dell\u2019ammanco, ha immediatamente chiamato i carabinieri i quali, visionando gli impianti di videosorveglianza delle strade limitrofe e di alcuni locali della caritas hanno potuto smascherare il p.a. durante la successiva perquisizione domiciliare, effettivamente, la bibbia rubata e\u2019 stata ritrovata.<br \/>\nAltro deferimento a Galatone per d.c., classe 1975, fermato alla guida di un mezzo sul quale aveva abusivamente raccolto del ferro. lo stesso, peraltro, era anche privo della patente perche\u2019 mai conseguita. e\u2019 stato quindi deferito in stato di liberta\u2019 er raccolta non autorizzata di materiali ferrosi e guida senza patente. da notare, peraltro, che per il d.c. e\u2019 il secondo deferimento in due mesi per le medesime mancanze.<br \/>\nIl servizio a largo raggio attuato ha altresi\u2019 visto i militari impegnati nel contrasto alla guida in stato di ebbrezza e nei controlli alla circolazione stradale..<br \/>\nPer quattro automobilisti e\u2019 scattato il deferimento in stato di liberta\u2019 per guida in stato di ebbrezza per l\u2019alto tasso alcolemico presente nel sangue, superiore alla soglia minima di 0,80 g\/l. in un caso si sono raggiunti 1.49 g\/l quindi oltre due volte superiore alla soglia minima. in un caso, addirittura, il conducente sorpreso ubriaco aveva anche provocato un incidente con un\u2019altra autovettura, fortunatamente con ferite lievi per entrambi i conducenti. sette le patenti ritirate, 50 le contravvenzioni al codice della strada elevate, per violazioni che vanno dalla guida senza cinture di sicurezza all\u2019uso del telefono cellulare alla guida. circa 150 i punti tolti alle patenti dei malcapitati guidatori.<br \/>\nUn soggetto e\u2019 stato deferito in stato di liberta\u2019 per essersi rifiutato di sottoporsi al controllo sulle sostanze stupefacenti. lo stesso, fermato e visibilmente in stato di alterazione derivante da assunzione di sostanze stupefacente, e\u2019 stato invitato a sottoporsi al controllo, ricevendone in cambio un rifiuto<br \/>\nChi invece si e\u2019 sottoposto al controllo in ospedale, a seguito di un sinistro stradale e\u2019 p.g. classe 1989 di Galatina. a seguito del controllo e\u2019 stato trovato con un tasso di cannabinoidi nel sangue eccessivo e quindi e\u2019 stato deferito in stato di liberta\u2019 per guida sotto l\u2019effetto di sostanze stupefacenti.<br \/>\nQuindici i segnalati alla prefettura per uso non terapeutico di sostanze stupefacenti. si tratta perlopiu\u2019 di  ragazzi, molti dei quali minorenni, trovati in possesso di sostanze stupefacenti, soprattutto marijuana. ad uno di questi, un copertinese minorenne, e\u2019 stata trovata perfino una piantina di marijuana nell\u2019abitazione, dell\u2019altezza di 20 cm.<br \/>\nNel corso del servizio, infine, sono stati identificati due soggetti georgiani, con precedenti per furto, nelle zone di Gallipoli. su uno di essi pendeva un provvedimento di espulsione della questura di Taranto ed e\u2019 stato pertanto accompagnato presso la questura di Lecce per gli adempimenti del caso. per il suo \u201ccollega\u201d, invece, e\u2019 scattata la richiesta di foglio di via obbligatorio dal comune di Gallipoli.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/01\/gallipoli-ritirate-7-patenti-per-guida-in-stato-di-ebbrezza\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/01\/gallipoli-ritirate-7-patenti-per-guida-in-stato-di-ebbrezza\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nei giorni del 31 maggio e 1 giugno i carabinieri della compagnia di Gallipoli, sono stati impegnati su tutto il territorio di loro competenza, con un capillare servizio coordinato a largo raggio. In sintesi, sono stati eseguiti controlli, principalmente finalizzati a contrastare il perpetrarsi di reati in genere, nonche\u2019 il fenomeno della guida in stato [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30021,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30020"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30020"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30020\/revisions"}],"predecessor-version":[{"id":30022,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30020\/revisions\/30022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/30021"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}