{"id":30023,"date":"2014-06-01T15:13:04","date_gmt":"2014-06-01T13:13:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30023"},"modified":"2014-06-01T15:13:04","modified_gmt":"2014-06-01T13:13:04","slug":"gli-italiani-hanno-ormai-le-tasche-vuote","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/01\/gli-italiani-hanno-ormai-le-tasche-vuote\/","title":{"rendered":"Gli italiani hanno ormai le tasche vuote!"},"content":{"rendered":"<p> <a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/bancarella-abiti.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/bancarella-abiti-300x198.jpg\" alt=\"\" title=\"bancarella abiti\" width=\"300\" height=\"198\" class=\"alignnone size-medium wp-image-30024\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/bancarella-abiti-300x198.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/bancarella-abiti.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Il reddito reale \u00e8 diminuito dell&#8217;1,1% e i consumi si sono contratti del 2,6%. Mentre si moltiplicano e crescono i mercati degli indumenti usati<br \/>\nQuesta la fotografia scattata dalla Banca d&#8217;Italia nell&#8217;ultima relazione annuale. Una ulteriore conferma della gravissima situazione in cui si trova l&#8217;Italia che evidenzia come tutte le misure sino ad oggi attuate sono state inefficaci ed inadeguate. Infatti \u00e8 sceso ancora, in termini reali, il reddito disponibile delle famiglie italiane nel 2013, ma i consumi sono diminuiti ancora di pi\u00f9, perch\u00e9 si cerca di risparmiare qualcosa per rimettere insieme il gruzzoletto eroso negli anni peggiori della crisi. In dettaglio, il reddito reale \u00e8 diminuito dell&#8217;1,1% (sempre meglio del -4,6% del 2012) e i consumi si sono contratti del 2,6%. La propensione al risparmio \u00e8 invece salita di 1,4 punti. Il reddito lordo disponibile ha registrato un lievissimo incremento (+0,3%), ma \u00e8 quello in termini reali risulta ancora in contrazione. A scendere sono in particolare i redditi da lavoro, sia quello dipendente (-0,5%), ma soprattutto quello degli autonomi (-1,3%). Ma in flessione sono anche i redditi netti da propriet\u00e0, come per esempio gli affitti percepiti dai proprietari di immobili o le rendite finanziarie, che subiscono una diminuzione dell&#8217;1,8% soprattutto a causa, spiega Bankitalia, di &#8220;minori interessi, dividendi e altri utili distribuiti&#8221;. Il reddito disponibile \u00e8 stato invece sostenuto dall&#8217;azione delle Amministrazioni pubbliche, che aveva largamente concorso alla sua contrazione nel 2012: sono scese le imposte correnti sul reddito e sul patrimonio e al tempo stesso hanno accelerato i trasferimenti e le prestazioni sociali (al 3,1 dal 2,2%). Tornando invece ai consumi, la contrazione \u00e8 stata del 2,6%, quindi sensibilmente superiore a quella dei redditi. Un fenomeno del genere, fa notare il rapporto della Banca d&#8217;Italia, &#8220;non si era registrato nemmeno in occasione di recessioni particolarmente pronunciate, come quelle dei primi anni Novanta e del 2008-2009&#8221;. Le famiglie, quindi, hanno decisamente ridotto i propri acquisti (rinunciando soprattutto a prodotti considerati non essenziali, come abbigliamento, scarpe, mobili, elettrodomestici), ma l&#8217;hanno fatto anche per rimettere qualcosa da parte. La propensione al risparmio \u00e8 infatti aumentata di 1,4 punti arrivando al 9,5% e tornando cos\u00ec ai livelli precedenti la crisi del debito sovrano. &#8220;All&#8217;aumento avrebbe contribuito oltre all&#8217;adeguamento dei consumi alle ridotte prospettive reddituali, anche il tentativo di ricostituire il livello di ricchezza desiderato, compensando l&#8217;erosione subita nel corso della crisi&#8221;.Saranno solo dati empirici, sar\u00e0 solo l\u2019osservazione della realt\u00e0, ma passeggiando per i mercati settimanali si pu\u00f2 assistere ad uno spettacolo incredibile: crescono e si moltiplicano le bancarelle degli indumenti usati e migliaia di cittadini si recano a frugare a cercare l\u2019occasione. Si trova di tutto, proprio di tutto, ma ci\u00f2 che colpisce che oltre ai classici capi d\u2019abbigliamento quali pantaloni, t-shirt, camice, gonne ed accessori, come borse e borselli, si trova qua e l\u00e0 anche sola biancheria intima. Il tutto a 1, 2 massimo 5 euro. E pensare, che dove c\u2019era un mese prima una bancarella con abiti nuovi oggi se ne trova una che espone merce usata. Sono i segni tangibili della crisi che avanza e che travolge anche cittadini e famiglie che solo un paio d\u2019anni fa non avrebbero mai pensato di essere costretti a rivolgersi a questo tipo d\u2019acquisti. \u00c8 giunta finalmente l\u2019ora che il Paese cambi marcia.<\/p>\n<p>                                                                                                                                                                                       Giovanni D\u2019AGATA<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/01\/gli-italiani-hanno-ormai-le-tasche-vuote\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/01\/gli-italiani-hanno-ormai-le-tasche-vuote\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il reddito reale \u00e8 diminuito dell&#8217;1,1% e i consumi si sono contratti del 2,6%. Mentre si moltiplicano e crescono i mercati degli indumenti usati Questa la fotografia scattata dalla Banca d&#8217;Italia nell&#8217;ultima relazione annuale. Una ulteriore conferma della gravissima situazione in cui si trova l&#8217;Italia che evidenzia come tutte le misure sino ad oggi attuate [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30024,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30023"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30023"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30023\/revisions"}],"predecessor-version":[{"id":30025,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30023\/revisions\/30025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/30024"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}