{"id":3003,"date":"2012-07-23T17:26:04","date_gmt":"2012-07-23T17:26:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=3003"},"modified":"2012-07-23T17:26:06","modified_gmt":"2012-07-23T17:26:06","slug":"approvato-il-fiscal-compact-che-cosa-significa-davvero","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/23\/approvato-il-fiscal-compact-che-cosa-significa-davvero\/","title":{"rendered":"Approvato il Fiscal compact. Che cosa significa davvero"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/23\/approvato-il-fiscal-compact-che-cosa-significa-davvero\/fiscal-compact-bilancio\/\" rel=\"attachment wp-att-3004\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/fiscal-compact-bilancio-300x204.jpg\" alt=\"\" title=\"fiscal-compact-bilancio\" width=\"300\" height=\"204\" class=\"alignnone size-medium wp-image-3004\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/fiscal-compact-bilancio-300x204.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/fiscal-compact-bilancio.jpg 625w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong>MACELLERIA SOCIALE<\/strong><\/p>\n<p>Autore: Paolo Becchi &#8211; Fonte: Byoblu.com<\/p>\n<p>Il Parlamento ha approvato la ratifica del cosiddetto\u00a0<strong>fiscal compact<\/strong>, ossia il trattato che introduce i meccanismi di stabilit\u00e0, coordinamento e\u00a0governance\u00a0nell\u2019unione economica e monetaria, e che mira \u2013 cos\u00ec si dice \u2013 \u00aba salvaguardare la stabilit\u00e0 di tutta la zona Euro\u00bb.<\/p>\n<p>In realt\u00e0, dubbi ed incertezze sulla bont\u00e0 del \u201cfiscal compact\u201d sono stati espressi in tutta Europa: la Germania per prima ha rinviato l\u2019approvazione del trattato, e sar\u00e0 la Corte Costituzionale a decidere, il prossimo 12 settembre, se il fondo di salvataggio ed il patto fiscale europeo potranno entrare in vigore. In Italia, invece, si \u00e8 assistito ad un \u201callineamento\u201d non solo degli organi di stampa \u2013 che evitano quasi di dare notizia dell\u2019avvenuta approvazione \u2013 ma dello stesso Parlamento, il quale ha ratificato,\u00a0<strong>senza discussione<\/strong>, senza neppure che sia stato necessario al Governo porre la questione di fiducia, il Trattato:\u00a0<strong>maggioranza bulgara oggi alla Camera, 368 s\u00ec contro 65 no<\/strong>. In Italia tutto accade ormai in un\u2019atmosfera grigia e silenziosa, quasi spettrale.<\/p>\n<p>Ma cosa significa l\u2019approvazione del \u201cfiscal compact\u201d? Il \u201cpatto\u201d prevede che i Paesi che detengono un\u00a0<strong>debito pubblico superiore al 60% del PIL di rientrare entro tale soglia nell&#8217;arco di 20 anni<\/strong>, ad un ritmo pari ad un ventesimo dell&#8217;eccedenza in ciascuna annualit\u00e0. Gli Stati si obbligano a\u00a0<strong>mantenere il deficit pubblico sempre sotto al 3% del PIL<\/strong>, a pena di sanzioni. Tutto ci\u00f2 significa n\u00e9 pi\u00f9 n\u00e9 meno la semplice rinuncia ad ogni possibilit\u00e0 di intraprendere una politica fiscale capace di stimolare la domanda. Significa condannarsi ad una rigidit\u00e0 ulteriore di politica economica che va ad aggiungersi a quella del cambio fisso dettato dalla moneta unica. L\u2019Italia, la nazione prima al mondo per pressione fiscale, si impegna oggi a sostenere\u00a0<strong>50 miliardi di Euro all\u2019anno di tasse e tagli per 20 anni<\/strong>. Rispettare parametri fiscali sempre pi\u00f9 rigidi e stringenti, rinunziando ad ogni spazio possibile di manovra, vorr\u00e0 dire dover imporre agli italiani, per i prossimi vent\u2019anni, un regime di austerit\u00e0 radicale: si colpiranno ancora\u00a0<strong>salari, stipendi e prestazioni del Welfare<\/strong>, si aggraveranno le condizioni di vita delle classi sociale medio-basse, si assister\u00e0 a nuove tasse. Gli italiani devono sapere che il prezzo imposto dall\u2019Europa \u00e8 una<strong>\u00a0<\/strong><strong>macelleria sociale<\/strong>: tagli dappertutto, dalla sanit\u00e0 alla scuola, dall\u2019universit\u00e0 ai trasporti.<\/p>\n<p>Tutto questo avviene, ed avverr\u00e0,\u00a0<strong>senza alcuna consultazione diretta o indiretta del popolo italiano<\/strong>, ma unicamente per rispettare decisioni prese al di fuori del Paese. Siamo passati senza accorgercene da un sistema politico democratico ad un sistema oligarchico, in cui il Governo \u00e8 nelle mani di un gruppo di \u201ctecnici\u201d che rappresentano interessi esterni. Il Parlamento obbedisce, senza neppure un minimo accenno di protesta.\u00a0<strong>Il Paese \u00e8 stato \u201cpacificato\u201d<\/strong>: niente pi\u00f9 aspri scontri politici, disinteresse diffuso per la politica, tensione sociale apparentemente sotto controllo. Eppure si annuncia, per i prossimi vent\u2019anni, una sanguinosa e violenta \u201ceconomia di guerra\u201d: la\u00a0<strong>guerra senza guerra<\/strong>, ossia la pi\u00f9 terrificante delle possibilit\u00e0.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/23\/approvato-il-fiscal-compact-che-cosa-significa-davvero\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/23\/approvato-il-fiscal-compact-che-cosa-significa-davvero\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>MACELLERIA SOCIALE Autore: Paolo Becchi &#8211; Fonte: Byoblu.com Il Parlamento ha approvato la ratifica del cosiddetto\u00a0fiscal compact, ossia il trattato che introduce i meccanismi di stabilit\u00e0, coordinamento e\u00a0governance\u00a0nell\u2019unione economica e monetaria, e che mira \u2013 cos\u00ec si dice \u2013 \u00aba salvaguardare la stabilit\u00e0 di tutta la zona Euro\u00bb. In realt\u00e0, dubbi ed incertezze sulla bont\u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3003"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=3003"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3003\/revisions"}],"predecessor-version":[{"id":3006,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3003\/revisions\/3006"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=3003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=3003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=3003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}