{"id":30283,"date":"2014-06-06T16:51:00","date_gmt":"2014-06-06T14:51:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30283"},"modified":"2014-06-06T16:51:00","modified_gmt":"2014-06-06T14:51:00","slug":"riccardo-sinigaglia-sergio-armaroli-tecrit-dodicilune-ird","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/06\/riccardo-sinigaglia-sergio-armaroli-tecrit-dodicilune-ird\/","title":{"rendered":"RICCARDO SINIGAGLIA &#038; SERGIO ARMAROLI TECRIT DODICILUNE \/ IRD"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/BodyPart.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/BodyPart-300x269.jpg\" alt=\"\" title=\"ED321\" width=\"300\" height=\"269\" class=\"alignnone size-medium wp-image-30284\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/BodyPart-300x269.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/BodyPart.jpeg 827w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Dal 7 giugno \u00e8 in distribuzione in Italia e all\u2019estero nel circuito IRD e nei principali store digitali\u00a0<strong>Tecrit<\/strong>, nuovo lavoro discografico del duo composto da\u00a0<strong>Sergio Armaroli<\/strong>(vibrafono e talking drum) e\u00a0<strong>Riccardo Sinigaglia<\/strong>\u00a0(santur elettrico, flauti barocchi ed elettronica) prodotto dall\u2019etichetta pugliese Dodicilune.<\/p>\n<p>&nbsp;<\/p>\n<p>Il lavoro si basa sull\u2019uso esteso di scale non temperate unite al suono del vibrafono \u201ctemperato\u201d che creano battimenti e volute dissonanze \u201cinterne al suono\u201d che rendono il dialogo improvvisativo interessante e dialetticamente acceso anche se non privo di spigolosit\u00e0 e necessarie asprezze espressive. I sei brani (quattro registrati in studio, due durante un live al Loft21 di Milano) si alternano secondo un tracciato ben preciso, un viaggio tra alcune lunghe improvvisazioni in forma estesa e tre brevi intermezzi con montaggi di suoni di varia natura che servono a rompere l\u2019atmosfera ipnotica che caratterizza il flusso sonoro.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cNella nostra musica seguiamo un flusso di energie che ci attraversano e noi siamo solo i catalizzatori che permettono a tale flusso sonoro di manifestarsi\u201d, sottolineano i due musicisti. \u201cTale flusso, come tutto ci\u00f2 che \u00e8 organico, non \u00e8 mai rigido; il ritmo respira, rallenta ed accelera, a volte impercettibilmente e marcatamente, mentre le melodie evolvono con continue variazioni fino ad allontanarsi dalla modalit\u00e0 di base: questa \u00e8 per noi\u00a0<em>improvvisazione organica<\/em>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Two E<\/strong>\u00a0\u00e8 un montaggio di suoni concreti registrati in un pascolo inteso come un \u201cconcerto naturale di campane\u201d uniti ai suoni del santur e del vibrafono come un\u2019eco evocativa. Il brano\u00a0<strong>Three A<\/strong>\u00a0si basa su di una scala pitagorica in la.\u00a0<strong>Tecrit<\/strong>\u00a0\u00e8 realizzato a partire da un loop creato con un Moog Sonic Six i cui oscillatori sono modulati da due low frequency in salpe and cold.\u00a0<strong>Five<\/strong>\u00a0porta il titolo segreto di \u201cUccellini\u201d ed \u00e8 un montaggio di suoni in cui i canti degli uccelli sono mescolati con interventi percussivi del talking drum e del flauto.\u00a0<strong>One F<\/strong>\u00a0e\u00a0<strong>Four D<\/strong>\u00a0sono due brani registrati live e utilizzano una scala pura in fa e una scala pitagorica in re.<\/p>\n<p>&nbsp;<\/p>\n<p>La poetica di\u00a0<strong>Sergio Armaroli<\/strong>\u00a0abbraccia molteplici ambiti espressivi alla costante ricerca di un\u2019unit\u00e0 dell&#8217;esperienza. Si dichiara pittore, percussionista concreto, poeta frammentario e artista sonoro oltre a fondare il proprio operare all&#8217;interno del &#8220;linguaggio del jazz&#8221; e dell&#8217;improvvisazione come &#8220;estensione del concetto di arte&#8221;. Concentrato su una scritturalit\u00e0 diffusa, consapevole di essere produttore &#8220;di-segni&#8221;, dove l&#8217;invenzione verbale \u00e8 &#8220;gesto poetico&#8221;, nella vita \u00e8 costretto ad uno sforzo pedagogico costante (<a href=\"http:\/\/www.sergioarmaroli.com\/\" target=\"_blank\">www.sergioarmaroli.com<\/a>). Svolge una intensa attivit\u00e0 artistica caratterizzata da un eclettismo stilistico accentuato con una tendenza alla dispersione linguistica come alla rinuncia e ad una forte predilizione per il &#8220;silenzio&#8221;. Si \u00e8 esibito in qualit\u00e0 di &#8220;attore musicale&#8221; e percussionista concreto in prestigiosi teatri e sale da concerto internazionali esponendo come artista in ambito off e sperimentale. Ha al proprio attivo numerose pubblicazioni in campo teorico musicale e poetico.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Riccardo Sinigaglia<\/strong>\u00a0nei suoi brani cerca l&#8217;integrazione tra gli elementi che sono alla base della sua formazione e che ha vissuto spesso con difficolt\u00e0 in quanto contraddittori, come culture estranee tra loro. Cos\u00ec si potranno ascoltare parti completamente scritte ed altre con elementi improvvisativi, e un mescolarsi continuo di linguaggi, quello della musica elettronica e d&#8217;avanguardia, il minimalismo, il jazz, la musica araba ed ebraica, le poliritmie dell&#8217;estremo oriente e il richiamo della musica classico sinfonica che \u00e8 stata il mio primo amore (<a href=\"http:\/\/www.riccardosinigaglia.com\/\" target=\"_blank\">www.riccardosinigaglia.com<\/a>). Il Santur elettrico \u00e8 un suono che ha realizzato con un misto di componenti Fm che danno un fondo sonoro evolutivo e un attacco con caratteristiche metalliche miste ad un campionamento del bellissimo strumento iraniano Santur, un piccolo cimbalon le cui corde si percuotono e il cui suono amo molto, lo uso suonando su una tastiera pesata come fosse un pianoforte solo che ho la possibilit\u00e0 di accordarlo ad hoc per ogni brano e scala che uso.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dodicilune<\/strong>\u00a0\u00e8 attiva dal 1996 e riconosciuta dal Jazzit Award tra le prime tre etichette discografiche italiane (dati 2010\/2013). Dispone di un catalogo di oltre 150 produzioni di artisti italiani e stranieri, ed \u00e8 distribuita in Italia e all&#8217;estero da IRD presso 400 punti vendita tra negozi di dischi, Feltrinelli, Fnac, Ricordi, Messaggerie, Melbookstore. I dischi Dodicilune possono essere acquistati anche online (Amazon, Ibs, LaFeltrinelli, Jazzos) o scaricati in formato liquido su 56 tra le maggiori piattaforme del mondo (iTunes, Napster, Fnacmusic, Virginmega, Deezer, eMusic, RossoAlice, LastFm, Amazon, etc). Info su\u00a0<a href=\"http:\/\/www.dodiciluneshop.it\/\" target=\"_blank\">www.dodiciluneshop.it<\/a><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/06\/riccardo-sinigaglia-sergio-armaroli-tecrit-dodicilune-ird\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/06\/riccardo-sinigaglia-sergio-armaroli-tecrit-dodicilune-ird\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Dal 7 giugno \u00e8 in distribuzione in Italia e all\u2019estero nel circuito IRD e nei principali store digitali\u00a0Tecrit, nuovo lavoro discografico del duo composto da\u00a0Sergio Armaroli(vibrafono e talking drum) e\u00a0Riccardo Sinigaglia\u00a0(santur elettrico, flauti barocchi ed elettronica) prodotto dall\u2019etichetta pugliese Dodicilune. &nbsp; Il lavoro si basa sull\u2019uso esteso di scale non temperate unite al suono del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30284,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30283"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30283"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30283\/revisions"}],"predecessor-version":[{"id":30286,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30283\/revisions\/30286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/30284"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}