{"id":30492,"date":"2014-06-10T19:17:19","date_gmt":"2014-06-10T17:17:19","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30492"},"modified":"2014-06-10T19:17:19","modified_gmt":"2014-06-10T17:17:19","slug":"le-notti-di-kalos","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/10\/le-notti-di-kalos\/","title":{"rendered":"LE NOTTI DI KAL\u00d2S"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/la-notte-del-mito.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/la-notte-del-mito-200x300.jpg\" alt=\"\" title=\"la notte del mito\" width=\"200\" height=\"300\" class=\"alignnone size-medium wp-image-30493\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/la-notte-del-mito-200x300.jpg 200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/la-notte-del-mito-682x1024.jpg 682w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/la-notte-del-mito.jpg 1000w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>UN VIAGGIO NEL TEMPO\u2026 ALLE ORIGINI DEL SALENTO\u201d:\u00a0<\/strong><strong>DOMANI LA PRESENTAZIONE DELL\u2019EVENTO\u00a0<\/strong><strong>CHE ANIMERA\u2019\u00a0 L\u2019ARCHEODROMO DEL SALENTO A CAPRARICA.<\/strong><\/p>\n<p style=\"text-align: left;\">\u00a0\u201cLe notti di Kal\u00f2s. Un viaggio nel tempo\u2026 alle origini del Salento\u201d: \u00e8 questo l\u2019evento che verr\u00e0 presentato in conferenza stampa domani, marted\u00ec 10 giugno, alle ore 11, a Palazzo Adorno a Lecce.<\/p>\n<p>\u00a0L\u2019appuntamento con visite guidate nel parco, la pizzica dei Terramara e stand gastronomici sar\u00e0 a Kal\u00f2s-l\u2019Archeodromo del Salento, a Caprarica di Lecce, \u00a0venerd\u00ec 13 giugno, ore 21, e verr\u00e0 riproposto tutti i gioved\u00ec sera, a giugno e luglio.<\/p>\n<p>Una iniziativa settimanale, dunque, che accompagner\u00e0 fino alla III edizione di \u201cLe notti del Mito\u201d, ideate dall\u2019archeologo Alessandro Quarta e previste per luned\u00ec 11, marted\u00ec 12 e mercoled\u00ec 13 agosto, con un programma che quest\u2019anno sar\u00e0 ancora pi\u00f9 ricco e suggestivo con rappresentazioni di compagnie teatrali, danzatori, musicisti.<\/p>\n<p>A raccontare tutti i particolari degli eventi in programma interverranno il presidente della Provincia di Lecce <strong>Antonio Gabellone<\/strong>, l\u2019assessore provinciale al Turismo e al Marketing territoriale <strong>Francesco Pacella<\/strong>, l\u2019ideatore e promotore dell\u2019evento <strong>Alessandro Quarta<\/strong> e il giornalista <strong>Elio Paiano<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/10\/le-notti-di-kalos\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/10\/le-notti-di-kalos\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>UN VIAGGIO NEL TEMPO\u2026 ALLE ORIGINI DEL SALENTO\u201d:\u00a0DOMANI LA PRESENTAZIONE DELL\u2019EVENTO\u00a0CHE ANIMERA\u2019\u00a0 L\u2019ARCHEODROMO DEL SALENTO A CAPRARICA. \u00a0\u201cLe notti di Kal\u00f2s. Un viaggio nel tempo\u2026 alle origini del Salento\u201d: \u00e8 questo l\u2019evento che verr\u00e0 presentato in conferenza stampa domani, marted\u00ec 10 giugno, alle ore 11, a Palazzo Adorno a Lecce. \u00a0L\u2019appuntamento con visite guidate nel [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30493,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30492"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30492"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30492\/revisions"}],"predecessor-version":[{"id":30494,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30492\/revisions\/30494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/30493"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}