{"id":30545,"date":"2014-06-11T13:35:26","date_gmt":"2014-06-11T11:35:26","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30545"},"modified":"2014-06-11T13:35:26","modified_gmt":"2014-06-11T11:35:26","slug":"ladra-dappartamento-arrestata-in-flagranza-di-reato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/11\/ladra-dappartamento-arrestata-in-flagranza-di-reato\/","title":{"rendered":"LADRA D\u2019APPARTAMENTO ARRESTATA IN FLAGRANZA DI REATO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/PELUSO_MONICA.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/PELUSO_MONICA-221x300.jpg\" alt=\"\" title=\"PELUSO_MONICA\" width=\"221\" height=\"300\" class=\"alignnone size-medium wp-image-30546\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/PELUSO_MONICA-221x300.jpg 221w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/PELUSO_MONICA.jpg 335w\" sizes=\"(max-width: 221px) 100vw, 221px\" \/><\/a>I militari della Stazione Carabinieri di Tricase hanno tratto in arresto nella flagranza del reato di furto in abitazione la tricasina PELUSO Monica. La donna gi\u00e0 conosciuta ai militari dell\u2019Arma per reati dello stesso genere, nel tardo pomeriggio di ieri approfittando dell\u2019assenza dei proprietari di un\u2019abitazione del centro di Tricase, si introduceva furtivamente all\u2019interno della stessa e asportava la somma contante di euro 22 (ventidue). Mentre rovistava nelle stanze la PELUSO veniva colta \u201cin castagna\u201d dalla proprietaria di casa che immediatamente chiedeva l\u2019intervento dei Carabinieri della locale Stazione. la ladra si dava ovviamente alla fuga, ma grazie alla sommaria descrizione fatta ai Carabinieri da parte della vittima, i militari subito comprendevano chi potesse essere il malfattore atteso che la proprietaria dell\u2019abitazione non era in grado di identificarla compiutamente. Mentre i Carabinieri ricercavano e bloccavano nelle immediatezze dei fatti la PELUSO, la proprietaria si recava in caserma ove grazie all\u2019applicativo WEBLASE in uso all\u2019Arma dei Carabinieri, ove sono censiti tutti i soggetti sottoposti a fotosegnalamento, veniva riprodotto elettronicamente l\u2019identikit, grazie alla descrizione del viso fatta dalla vittima veniva riconosciuta con certezza dalla vittima la ladra nella PELUSO, confermando cos\u00ec il giusto intuito dei militari operanti. Stante gli elementi raccolti la PELUSO veniva tratta in arresto e tradotta in regime degli arresti domiciliari in atteso del rito direttissimo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/11\/ladra-dappartamento-arrestata-in-flagranza-di-reato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/11\/ladra-dappartamento-arrestata-in-flagranza-di-reato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I militari della Stazione Carabinieri di Tricase hanno tratto in arresto nella flagranza del reato di furto in abitazione la tricasina PELUSO Monica. La donna gi\u00e0 conosciuta ai militari dell\u2019Arma per reati dello stesso genere, nel tardo pomeriggio di ieri approfittando dell\u2019assenza dei proprietari di un\u2019abitazione del centro di Tricase, si introduceva furtivamente all\u2019interno della [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30546,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30545"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30545"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30545\/revisions"}],"predecessor-version":[{"id":30547,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30545\/revisions\/30547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/30546"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}