{"id":30603,"date":"2014-06-12T18:26:40","date_gmt":"2014-06-12T16:26:40","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30603"},"modified":"2014-06-12T18:29:07","modified_gmt":"2014-06-12T16:29:07","slug":"avallino-giovani-stilisti-in-passella","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/12\/avallino-giovani-stilisti-in-passella\/","title":{"rendered":"CAVALLINO: GIOVANI STILISTI IN PASSELLA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/modella-giulia-ingrosso.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/modella-giulia-ingrosso.jpg\" alt=\"\" title=\"modella giulia ingrosso\" width=\"640\" height=\"960\" class=\"alignnone size-full wp-image-21048\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/modella-giulia-ingrosso.jpg 640w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/modella-giulia-ingrosso-200x300.jpg 200w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>Ritorna \u201cGiovani Stilisti in passerella\u201d, l\u2019artistico d\u00e9fil\u00e9 siglato da<br \/>\nCentro Studi Moda \u201cCosimo Cordella\u201d, Istituto Cordella International<br \/>\nFashion School e Citt\u00e0 di Cavallino, con il patrocinio di Regione<br \/>\nPuglia, Provincia di Lecce e Universit\u00e0 del Salento. L\u2019evento, in<br \/>\nprogramma in piazza Castromediano a Cavallino domenica 15 giugno alle<br \/>\nore 20.30, aprir\u00e0 il cartellone dell\u2019\u201dEstate Cavallinese 2014\u201d.<br \/>\nA ricevere il premio \u00abRever d\u2019oro\u00bb sar\u00e0 quest\u2019anno il giornalista Rai<br \/>\nAntonio Caprarica, mentre la prima edizione del premio \u00abRever d\u2019oro<br \/>\njunior\u00bb andr\u00e0 alla giovanissima attrice Anna Luisa Capasa, tra gli<br \/>\ninterpreti del film \u00abLa grande bellezza\u00bb<\/p>\n<p>Venerd\u00ec 13 giugno 2014 alle ore 11 la conferenza stampa di<br \/>\npresentazione dell\u2019evento e della rassegna nella Galleria del Palazzo<br \/>\nDucale dei Castromediano<\/p>\n<p>Si terr\u00e0 venerd\u00ec 13 giugno 2014 alle ore 11, nella Galleria del Palazzo<br \/>\nDucale dei Castromediano a Cavallino, la conferenza stampa con cui sar\ufffd<br \/>\npresentata la XVIII edizione di \u201cGiovani stilisti in passerella\u201d,<br \/>\nevento<br \/>\norganizzato da Centro Studi Moda \u201cCosimo Cordella\u201d, Istituto Cordella<br \/>\nInternational Fashion School e Citt\u00e0 di Cavallino, con il patrocinio di<br \/>\nRegione Puglia, Provincia di Lecce e Universit\u00e0 del Salento in<br \/>\nprogramma<br \/>\nin Piazza Castromediano domenica 15 giugno alle ore 20.30 che proporr\ufffd<br \/>\nl\u2019artistico defil\u00e9 di Giovani Fashion Designer dell\u2019Istituto Cordella<br \/>\nFashion School. Nel corso della serata, l\u2019Istituto assegner\u00e0 il Premio<br \/>\n\u201cRever d\u2019oro \u2013 Cosimo Cordella\u201d al giornalista Rai e scrittore Antonio<br \/>\nCaprarica. La prima edizione del premio \u00abRever d\u2019oro junior\u00bb andr\ufffd<br \/>\ninvece alla giovanissima attrice Anna Luisa Capasa, tra gli interpreti<br \/>\ndel film \u00abLa grande bellezza\u00bb<br \/>\nAlla conferenza stampa saranno presenti, tra gli altri, il Sindaco<br \/>\ndella Citt\u00e0 di Cavallino Avv. Michele Lombardi, l\u2019Assessore alla<br \/>\nCultura<br \/>\nOn. Avv. Gaetano Gorgoni e la dottoressa Carol Cordella, direttrice<br \/>\ndell\u2019Istituto Cordella. Durante la conferenza stampa, inoltre, sar\ufffd<br \/>\nillustrato il cartellone degli appuntamenti dell\u2019\u201cEstate Cavallinese<br \/>\n2014\u201d, rassegna organizzata dall\u2019Amministrazione Comunale della quale<br \/>\n\u201cGiovani Stilisti in passerella\u201d \u00e8 l\u2019appuntamento inaugurale.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/12\/avallino-giovani-stilisti-in-passella\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/12\/avallino-giovani-stilisti-in-passella\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Ritorna \u201cGiovani Stilisti in passerella\u201d, l\u2019artistico d\u00e9fil\u00e9 siglato da Centro Studi Moda \u201cCosimo Cordella\u201d, Istituto Cordella International Fashion School e Citt\u00e0 di Cavallino, con il patrocinio di Regione Puglia, Provincia di Lecce e Universit\u00e0 del Salento. L\u2019evento, in programma in piazza Castromediano a Cavallino domenica 15 giugno alle ore 20.30, aprir\u00e0 il cartellone dell\u2019\u201dEstate Cavallinese [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21048,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30603"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30603"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30603\/revisions"}],"predecessor-version":[{"id":30605,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30603\/revisions\/30605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/21048"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}