{"id":30609,"date":"2014-06-12T21:55:33","date_gmt":"2014-06-12T19:55:33","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30609"},"modified":"2014-06-12T21:55:33","modified_gmt":"2014-06-12T19:55:33","slug":"evviva-i-barboni-evviva-i-vandali-e-gli-estremisti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/12\/evviva-i-barboni-evviva-i-vandali-e-gli-estremisti\/","title":{"rendered":"EVVIVA I BARBONI EVVIVA I VANDALI E GLI ESTREMISTI"},"content":{"rendered":"<p><em>Riceviamo e volentieri pubblichiamo \u2026ma riflettiamo.<br \/>\nUn tetto va assicurato a tutti, ma \u2026.<\/em><\/p>\n<p><strong>Chiodi anti barbone. La catena dei supermercati inglese Tesco\u00a0<\/strong><strong>dopo le proteste di questi giorni\u00a0<\/strong><strong>ha rimosso i pungiglioni anti-senzatetto dai negozi di Regent Street. Anche il sindaco di Londra ha richiesto la rimozione delle borchie\u00a0 metalliche che sono stati installate all&#8217;ingresso delle abitazioni di Southwark.<\/strong><\/p>\n<p>Tesco ha deciso di rimuovere le borchie appuntite anti-senzatetto dall&#8217;esterno dei suoi negozi del centro di Londra dopo giorni di protesta. Le borchie in acciaio hanno provocto indignazione quando essi sono stati posizionati all&#8217;esterno del supermercato di Regent Street e all&#8217;ingresso di lussuose abitazioni vicino a London Bridge. Le borchie erano state posizionate a Southwark Bridge Road, Londra, per scoraggiare la sosta sulle traversine da parte di sbandati e barboni.Un manager di Tesco, per giustificare la decisione aziendale di utilizzare queste borchie dinanzi alla crescente protesta intorno al caso, ha insistito sul fatto che sono stati progettati per prevenire comportamenti antisociali piuttosto che per scoraggiare i senzatetto a dormire nelle vicinanze.Tuttavia, Tesco ha comunicato ieri che rimuover\u00e0 le punte anche per eliminare qualsiasi equivoco. Intanto un gruppo di attivisti hanno protestato contro il negozio di Regent Street, che \u00e8 stato preso di mira mercoled\u00ec sera. Alcuni uomini travestiti per non farsi riconoscere sono stati ripresi mentre versavano una miscela di cemento sopra i pungiglioni di una strada laterale mentre su Facebook \u00e8 stata promossa una petizione che ha gi\u00e0 raccolto 600 firme. Un sito Change.org che ha lanciato un&#8217;altra petizione on line ha raccolto 113.000 firme dall&#8217;inizio del suo lancio nel fine settimana.Il sindaco di Londra Boris Johnson e il ministro delle politiche sociali, Kris Hopkins, si sono uniti alla protesta di\u00a0<a href=\"http:\/\/webmaildomini.aruba.it\/ext_aruba\/classic\/html\/mainframe.html?_v_=v4r2b24pl1m1.20140409_1715?lang=it&amp;flavour=orange&amp;theme=ext_aruba\/classic&amp;useSprite=0\">questa settimana<\/a>. Johnson ha chiesto la rimozione immediata. Tuttavia, le organizzazioni di beneficenza non si dicono affatto stupite. \u201cSimili chiodi di metallo vengono installati contro i senzatetto da pi\u00f9 di dieci anni\u201d, ha spiegato Katharine Sacks-Jones della struttura che accoglie gli homeless Crisis. Le Associazioni Nazionali con finalit\u00e0 Assistenziali hanno descritto le borchie come disumane. Le persone senza fissa dimora non sopresidente dell&#8217;associazione Homeless Link, ha detto: &#8220;il numero delle borchie anti barbone ha evidenziato la cruda realt\u00e0 di quanto il problema \u00e8 grave in questo paese. Mentre accogliamo con piacere che si stanno per rimuovere i pungiglioni, in primo luogo la vera soluzione \u00e8 quello di assicurarsi che nessuno abbia a passare la notte per le strade.Giovanni D&#8217;Agata, presidente dello \u201c<a href=\"http:\/\/giovannidagata.voxmail.it\/nl\/zvbmr\/qxqmw7\/1?_t=90c53d65\" target=\"_blank\">Sportello dei Diritti<\/a>\u201d, l&#8217;associazione no profit che ha lanciato per prima in Italia la campagna contro i chiodi anti barbone, chiede che in via preventiva in Italia venga vietata dai sindaci questa prassi per evitare che si vedano spettacoli di livello cos\u00ec basso anche nelle nostre citt\u00e0. Recentemente anche in Italia il Comune di Bergamo ha fatto installare lungo viale Papa Giovanni, la strada principale della citt\u00e0, una serie di panchine subito ribattezzate \u2018anti clochard\u2019.<\/p>\n<p><em><strong>Giovanni D\u2019AGATA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/strong><\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/12\/evviva-i-barboni-evviva-i-vandali-e-gli-estremisti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/12\/evviva-i-barboni-evviva-i-vandali-e-gli-estremisti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo \u2026ma riflettiamo. Un tetto va assicurato a tutti, ma \u2026. Chiodi anti barbone. La catena dei supermercati inglese Tesco\u00a0dopo le proteste di questi giorni\u00a0ha rimosso i pungiglioni anti-senzatetto dai negozi di Regent Street. Anche il sindaco di Londra ha richiesto la rimozione delle borchie\u00a0 metalliche che sono stati installate all&#8217;ingresso delle [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30609"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30609"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30609\/revisions"}],"predecessor-version":[{"id":30610,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30609\/revisions\/30610"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}