{"id":30775,"date":"2014-06-16T13:30:38","date_gmt":"2014-06-16T11:30:38","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30775"},"modified":"2014-06-16T13:30:38","modified_gmt":"2014-06-16T11:30:38","slug":"la-nuova-piazza-partigiani","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/16\/la-nuova-piazza-partigiani\/","title":{"rendered":"LA \u201cNUOVA\u201d PIAZZA PARTIGIANI"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-30775 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/16\/la-nuova-piazza-partigiani\/piazza-partigiani2\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/piazza-Partigiani2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/16\/la-nuova-piazza-partigiani\/piazza-partigiani3\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/piazza-Partigiani3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>E\u2019 stata presentata questa mattina alla citt\u00e0 la nuova veste di piazza Partigiani in seguito alla riqualificazione urbanistica cui \u00e8 stata sottoposta dall\u2019Amministrazione Comunale. Il progetto \u00e8 stato condiviso con gli stessi residenti del quartiere che si sono costituti in un Comitato per offrire il proprio contributo di idee e suggerimenti per la riqualificazione della piazza.<\/p>\n<p>&nbsp;<\/p>\n<p>All\u2019iniziativa hanno preso parte il sindaco <strong>Paolo Perrone<\/strong>, l\u2019assessore ai Lavori Pubblici, <strong>Gaetano Messuti, <\/strong>l\u2019assessore al Patrimonio,<strong> Attilio Monosi <\/strong>e<strong> <\/strong>il dirigente del settore Lavori Pubblici, <strong>Claudia Branca<\/strong>, oltre ad alcuni bambini frequentanti la vicina scuola materna.<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u201cIl nuovo look disegnato per questa piazza &#8211; <\/em>ha sottolineato il sindaco <strong>Paolo Perrone<\/strong> &#8211; <em>si integra perfettamente con le strutture gi\u00e0 esistenti in questo quartiere che si trova a ridosso del centro cittadino.\u00a0 La presenza dei bambini oggi, ad esempio, non \u00e8 stata affatto casuale: saranno loro, assieme alle rispettive famiglie a poter fruire dei nuovi spazi destinati anche ai residenti della zona\u201d.<\/em><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong>Cenni tecnici <\/strong><\/p>\n<p>Con deliberazione di Consiglio Comunale n.60 del 20\/06\/2011 \u00e8 stato approvato il Bilancio Pluriennale di Previsione con allegato il Programma Triennale delle Opere pubbliche 2011-2013 e il relativo Elenco Annuale dei lavori dell\u2019anno 2011, nel quale \u00e8 stato inserito il progetto relativo alla \u201c<em>Riqualificazione di Piazza Partigiani<\/em>\u201d. Pertanto \u00e8 stato predisposto uno stralcio del progetto di riqualificazione della piazza Partigiani dell\u2019importo complessivo di 500.000 euro, finanziato con mutuo da contrarre con la Cassa Depositi e Prestiti.<\/p>\n<p>L\u2019intervento consiste nella riqualificazione di piazza Partigiani attraverso interventi mirati ad una migliore disciplina del traffico e della sosta delle autovetture, alla sistemazione della zona antistante la Chiesa San Giovanni Vianney con passaggi pedonali e la piantumazione di essenze arboree, ridefinendo e riorganizzando gli spazi per un migliore utilizzo da parte dei residenti e di quanti si recano in chiesa e provvedendo ad un nuovo impianto di pubblica illuminazione. E\u2019 stata rivista anche l\u2019area adiacente la scuola con la sistemazione delle aiuole e nuovi percorsi pedonali.<\/p>\n<p>E\u2019 stata prevista, inoltre, la sistemazione\u00a0 dell\u2019area esterna della scuola sita in via Fornari angolo con via Benedetto Croce.<\/p>\n<p>Il progetto \u00e8 stato redatto dal professionista esterno architetto <strong>Aristide Malecore<\/strong> appositamente incaricato dall\u2019Amministrazione Comunale. La responsabile del procedimento \u00e8 il geometra <strong>Sonia Cappello<\/strong>, funzionario del Comune di Lecce.<\/p>\n<p>L\u2019impresa che ha eseguito i lavori \u00e8 la Ingrosso Costruzioni Sas di<em> <\/em>Grande Rosanna.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/16\/la-nuova-piazza-partigiani\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/16\/la-nuova-piazza-partigiani\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>E\u2019 stata presentata questa mattina alla citt\u00e0 la nuova veste di piazza Partigiani in seguito alla riqualificazione urbanistica cui \u00e8 stata sottoposta dall\u2019Amministrazione Comunale. Il progetto \u00e8 stato condiviso con gli stessi residenti del quartiere che si sono costituti in un Comitato per offrire il proprio contributo di idee e suggerimenti per la riqualificazione della [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30775"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30775"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30775\/revisions"}],"predecessor-version":[{"id":30779,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30775\/revisions\/30779"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}