{"id":30852,"date":"2014-06-18T12:41:04","date_gmt":"2014-06-18T10:41:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30852"},"modified":"2014-06-18T12:41:04","modified_gmt":"2014-06-18T10:41:04","slug":"aveva-una-carabina-ad-aria-compressa-in-casa-arrestato-a-melendugno","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/18\/aveva-una-carabina-ad-aria-compressa-in-casa-arrestato-a-melendugno\/","title":{"rendered":"AVEVA UNA CARABINA AD ARIA COMPRESSA IN CASA, ARRESTATO A MELENDUGNO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/FRANCESCO-stampa.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"236\" height=\"300\" title=\"FRANCESCO stampa\" class=\"alignnone size-medium wp-image-30853\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/FRANCESCO-stampa-236x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/FRANCESCO-stampa-236x300.jpg 236w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/FRANCESCO-stampa.jpg 606w\" sizes=\"(max-width: 236px) 100vw, 236px\" \/><\/a>Una carabina ad aria compressa, modificata e resa utilizzabile quale arma comune da sparo; e centodieci cartucce per fucile, oltre a venti grammi di marijuana. E&#8217; quanto i Carabinieri di Melendugno hanno trovato nell&#8217;abitazione di Francesco Cal\u00f2, 35 anni, con precedenti.<\/p>\n<p>Dopo che,\u00a0su autorizzazione del pubblico ministero di turno presso la Procura di Lecce, Paola Guglielmi,\u00a0\u00e8 stata verificata l&#8217;efficienza e la pericolosit\u00e0 dell&#8217;arma, l&#8217;uomo \u00e8 stato arrestato e tradotto presso il Carcere di Borgo San Nicola, in attesa del giudizio di convalida.<\/p>\n<p align=\"center\">\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/18\/aveva-una-carabina-ad-aria-compressa-in-casa-arrestato-a-melendugno\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/18\/aveva-una-carabina-ad-aria-compressa-in-casa-arrestato-a-melendugno\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Una carabina ad aria compressa, modificata e resa utilizzabile quale arma comune da sparo; e centodieci cartucce per fucile, oltre a venti grammi di marijuana. E&#8217; quanto i Carabinieri di Melendugno hanno trovato nell&#8217;abitazione di Francesco Cal\u00f2, 35 anni, con precedenti. Dopo che,\u00a0su autorizzazione del pubblico ministero di turno presso la Procura di Lecce, Paola [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30853,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30852"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30852"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30852\/revisions"}],"predecessor-version":[{"id":30854,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30852\/revisions\/30854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/30853"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}