{"id":30890,"date":"2014-06-18T15:34:53","date_gmt":"2014-06-18T13:34:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30890"},"modified":"2014-06-18T15:34:53","modified_gmt":"2014-06-18T13:34:53","slug":"nuovi-giochi-per-bambini-in-quattro-scuole-leccesi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/18\/nuovi-giochi-per-bambini-in-quattro-scuole-leccesi\/","title":{"rendered":"NUOVI GIOCHI PER BAMBINI IN QUATTRO SCUOLE LECCESI"},"content":{"rendered":"<p><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/imagesCAAD8EC3.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"225\" height=\"225\" title=\"imagesCAAD8EC3\" class=\"alignnone size-full wp-image-30891\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/imagesCAAD8EC3.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/imagesCAAD8EC3.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/imagesCAAD8EC3-150x150.jpg 150w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>Saranno riqualificati\u00a0quattro spazi verdi delle scuole dell\u2019infanzia delle periferie della citt\u00e0 con l\u2019installazione di giochi all\u2019aperto. <\/span><\/span><\/p>\n<p><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Il progetto \u00e8 stato interamente finanziato con oltre 15mila euro dall\u2019associazione Rotaract Distretto 2120 Puglia e Basilicata.<\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Le strutture scolastiche interessate sono: la \u201cAmmirato-Falcone\u201d, la &#8220;Banda Bassotti&#8221; di piazzetta Montale, la &#8220;Topolino&#8221; di via Marugi e le Vele, strutture che presentavano carenze di spazi attrezzati con giochi all&#8217;aperto.<\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\">\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/18\/nuovi-giochi-per-bambini-in-quattro-scuole-leccesi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/18\/nuovi-giochi-per-bambini-in-quattro-scuole-leccesi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Saranno riqualificati\u00a0quattro spazi verdi delle scuole dell\u2019infanzia delle periferie della citt\u00e0 con l\u2019installazione di giochi all\u2019aperto. Il progetto \u00e8 stato interamente finanziato con oltre 15mila euro dall\u2019associazione Rotaract Distretto 2120 Puglia e Basilicata. Le strutture scolastiche interessate sono: la \u201cAmmirato-Falcone\u201d, la &#8220;Banda Bassotti&#8221; di piazzetta Montale, la &#8220;Topolino&#8221; di via Marugi e le Vele, strutture [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30891,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30890"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30890"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30890\/revisions"}],"predecessor-version":[{"id":30893,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30890\/revisions\/30893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/30891"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}