{"id":30894,"date":"2014-06-18T15:40:34","date_gmt":"2014-06-18T13:40:34","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30894"},"modified":"2014-06-18T15:40:34","modified_gmt":"2014-06-18T13:40:34","slug":"sabato-sera-di-luci-e-di-musica-a-melpignano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/18\/sabato-sera-di-luci-e-di-musica-a-melpignano\/","title":{"rendered":"SABATO SERA DI LUCI E DI MUSICA A MELPIGNANO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/illuminareamelpilight.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"225\" title=\"illuminarea,melpilight\" class=\"alignnone size-medium wp-image-30895\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/illuminareamelpilight-300x225.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/illuminareamelpilight-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/illuminareamelpilight-1024x768.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Il<strong> 21 giugno<\/strong>, a partire dalle 21.00, in Piazza San Giorgio a Melpignano (nella foto), si svolger\u00e0 la festa finale del\u00a0seminario su <em>light design<\/em> e spazi pubblici \u201c<em>Make it happen\/Ci vediamo in Piazza<\/em>\u201d, organizzato da Scie Urbane, con la presenza di ospiti internazionali.<\/p>\n<p>I protagonisti saranno le installazioni luminose pensate e create dai partecipanti al workshop e <strong>il pubblico<\/strong>, che durante la festa finale,<strong> potr\u00e0 giocare con due quadri interattivi e variare i diversi scenari luminosi della Piazza.<\/strong><\/p>\n<p>Lo stesso giorno, alla stessa ora, sempre in Piazza, prender\u00e0 il via la &#8220;Festa Europea della Musica&#8221;, in cui 13 artisti emergenti locali si esibiranno fino a tarda notte<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/18\/sabato-sera-di-luci-e-di-musica-a-melpignano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/18\/sabato-sera-di-luci-e-di-musica-a-melpignano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il 21 giugno, a partire dalle 21.00, in Piazza San Giorgio a Melpignano (nella foto), si svolger\u00e0 la festa finale del\u00a0seminario su light design e spazi pubblici \u201cMake it happen\/Ci vediamo in Piazza\u201d, organizzato da Scie Urbane, con la presenza di ospiti internazionali. I protagonisti saranno le installazioni luminose pensate e create dai partecipanti al [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30895,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30894"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30894"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30894\/revisions"}],"predecessor-version":[{"id":30897,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30894\/revisions\/30897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/30895"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}