{"id":30938,"date":"2014-06-19T14:38:15","date_gmt":"2014-06-19T12:38:15","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=30938"},"modified":"2014-06-19T14:38:15","modified_gmt":"2014-06-19T12:38:15","slug":"teatro-in-piazza-al-rione-castromediano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/19\/teatro-in-piazza-al-rione-castromediano\/","title":{"rendered":"TEATRO IN PIAZZA AL RIONE CASTROMEDIANO"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"CENTER\"><em><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/E.png\"><img decoding=\"async\" loading=\"lazy\" width=\"208\" height=\"156\" title=\"E\" class=\"alignnone size-full wp-image-30939\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/E.png\" \/><\/a>Teatro d\u2019autore in Piazza Mater Ecclesiae (nella foto)\u00a0a Castromediano. Sabato 21 giugno la compagnia teatrale Calandra di Tuglie porta in scena \u00abMeglio sepolto che vivo\u00bb di Giuseppe Miggiano<\/strong><\/em>\u00a0nell\u2019ambito del cartellone dell\u2019<strong>\u00abEstate Cavallinese 2014\u00bb.<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/19\/teatro-in-piazza-al-rione-castromediano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/19\/teatro-in-piazza-al-rione-castromediano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Teatro d\u2019autore in Piazza Mater Ecclesiae (nella foto)\u00a0a Castromediano. Sabato 21 giugno la compagnia teatrale Calandra di Tuglie porta in scena \u00abMeglio sepolto che vivo\u00bb di Giuseppe Miggiano\u00a0nell\u2019ambito del cartellone dell\u2019\u00abEstate Cavallinese 2014\u00bb.<\/p>\n","protected":false},"author":4,"featured_media":30939,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30938"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30938"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30938\/revisions"}],"predecessor-version":[{"id":30940,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/30938\/revisions\/30940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/30939"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=30938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=30938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=30938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}