{"id":31047,"date":"2014-06-21T12:32:14","date_gmt":"2014-06-21T10:32:14","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=31047"},"modified":"2014-06-22T00:03:51","modified_gmt":"2014-06-21T22:03:51","slug":"problemi-nel-salento-arriva-vendolain-parata","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/21\/problemi-nel-salento-arriva-vendolain-parata\/","title":{"rendered":"PROBLEMI NEL SALENTO? ARRIVA VENDOLA\u2026IN PARATA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/Nichi_Vendola-slinguato.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/Nichi_Vendola-slinguato-269x300.jpg\" alt=\"\" title=\"Nichi_Vendola slinguato\" width=\"269\" height=\"300\" class=\"alignnone size-medium wp-image-31048\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/Nichi_Vendola-slinguato-269x300.jpg 269w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/Nichi_Vendola-slinguato.jpg 350w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><\/a>La Xylella Fastidiosa devasta gli uliveti salentini con grave danno per gli agricoltori e per i vivaisti, nelle marine di Melendugno il pericolo di crollo delle falesie mette in difficolt\u00e0 gli operatori balneari, a Campi Salentina chiude il Centro Imid punto di riferimento del Sud per pazienti colpiti da patologie causate da un cattivo funzionamento del sistema immunitario. E Vendola non si vede! Poi,\u00a0<a href=\"http:\/\/webmaildomini.aruba.it\/ext_aruba\/classic\/html\/mainframe.html?_v_=v4r2b25.20140616_1712?lang=it&amp;flavour=orange&amp;theme=ext_aruba\/classic&amp;useSprite=0\">oggi<\/a>, sulla Gazzetta del Mezzogiorno siamo \u201cconfortati\u201d dalla notizia che Nichi Vendola sar\u00e0 a Lecce il 28 giugno \u2026 per partecipare alla parata del \u201cGay Pride\u201d, la manifestazione per l\u2019orgoglio omosessuale.<br \/>\nRoberto Tundo<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/21\/problemi-nel-salento-arriva-vendolain-parata\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/21\/problemi-nel-salento-arriva-vendolain-parata\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La Xylella Fastidiosa devasta gli uliveti salentini con grave danno per gli agricoltori e per i vivaisti, nelle marine di Melendugno il pericolo di crollo delle falesie mette in difficolt\u00e0 gli operatori balneari, a Campi Salentina chiude il Centro Imid punto di riferimento del Sud per pazienti colpiti da patologie causate da un cattivo funzionamento [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31048,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/31047"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=31047"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/31047\/revisions"}],"predecessor-version":[{"id":31050,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/31047\/revisions\/31050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/31048"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=31047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=31047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=31047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}