{"id":32714,"date":"2014-07-30T17:49:50","date_gmt":"2014-07-30T15:49:50","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=32714"},"modified":"2014-07-30T17:49:50","modified_gmt":"2014-07-30T15:49:50","slug":"campioni-del-mondo-in-maturi-di-stato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/07\/30\/campioni-del-mondo-in-maturi-di-stato\/","title":{"rendered":"CAMPIONI DEL MONDO IN &#8220;MATURI&#8221; DI STATO"},"content":{"rendered":"<div id=\"mainLayout\" dir=\"ltr\">\n<div id=\"mainPane\" dir=\"ltr\">\n<div id=\"mainContainer\" dir=\"ltr\">\n<div>\n<div id=\"mainContent\" title=\"Desktop\" dir=\"ltr\">\n<div id=\"xandmail_widget_layout_LayoutContainer_0\" dir=\"ltr\">\n<div id=\"xandmail_widget_layout_ContentPane_1\" title=\"\" dir=\"ltr\">\n<div id=\"mailSplitCnt\" dir=\"ltr\">\n<div id=\"mailPreview\" title=\"\" dir=\"ltr\">\n<div id=\"preview14531\">\n<div id=\"preview14531_pane\" dir=\"ltr\">\n<div id=\"xandmail_widget_layout_SplitContainer_2\" dir=\"ltr\">\n<div id=\"xandmail_widget_layout_ContentPane_9\" title=\"\" dir=\"ltr\">\n<div id=\"msgText_preview14531\" dir=\"ltr\">\n<div>\n<div>\n<div>Chi l&#8217;avrebbe mai detto,in periodo di crisi profonda ?<br \/>\nSiamo primi assoluti,in tutto il globo,per &#8220;maturit\u00e0&#8221; dei nostri studenti : 99,2% per quella classica,99,7 per la media !<br \/>\nDopo il disastro pallonaro in Brasile ci siamo subito presi una rivincita.<br \/>\nNon sappiamo pi\u00fa giocare al calcio ma i nostri virgulti sono proprio pozzi di scienza universale.<br \/>\nForse la Merkel e la sua Deutschland pu\u00f2 arrivare a queste percentuali ?<br \/>\nVogliamo mettere la conoscenza scolastica di un crucco (magari multietnico) tedesco con quella del pi\u00f9 scadente diplomato a Roccacannuccia ?<br \/>\nConfrontiamo quella che pu\u00f2 avere una studentessa della Costa Rica oppure della Corea,della Nigeria,Togo od Iran a fronte della preparazione certificata di una qualunque nostra fanciulla di Vattelapesca\u00a0 ?<br \/>\nTutte e tutti &#8220;maturi&#8221;,l&#8217;albero della cultura ha dato i suoi frutti estivi ed \u00e8 rimasto spoglio fino all&#8217;anno scolastico prossimo.<br \/>\nOddio,si intravede lass\u00f9 in alto quel 0,3\/0,8 che resta pervicacemente attaccato al ramo della &#8220;conoscenza&#8221; come immaturo.<br \/>\nMa,in fin dei conti,siamo in Italia e non in Paradiso : la perfezione assoluta non \u00e8 di questa Terra.<\/p>\n<p>Vincenzo Mannello<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n<\/div>\n<div id=\"dijit_layout_ContentPane_2\" title=\"\" dir=\"ltr\">\n<div><\/div>\n<div id=\"dominiTracker\"><\/div>\n<\/div>\n<\/div>\n<div id=\"qsearchTooltip\" dir=\"ltr\"><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/07\/30\/campioni-del-mondo-in-maturi-di-stato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/07\/30\/campioni-del-mondo-in-maturi-di-stato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Chi l&#8217;avrebbe mai detto,in periodo di crisi profonda ? Siamo primi assoluti,in tutto il globo,per &#8220;maturit\u00e0&#8221; dei nostri studenti : 99,2% per quella classica,99,7 per la media ! Dopo il disastro pallonaro in Brasile ci siamo subito presi una rivincita. Non sappiamo pi\u00fa giocare al calcio ma i nostri virgulti sono proprio pozzi di scienza [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/32714"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=32714"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/32714\/revisions"}],"predecessor-version":[{"id":32715,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/32714\/revisions\/32715"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=32714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=32714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=32714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}