{"id":33234,"date":"2014-08-08T14:19:12","date_gmt":"2014-08-08T12:19:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=33234"},"modified":"2014-08-08T14:19:12","modified_gmt":"2014-08-08T12:19:12","slug":"estorsione-tramite-virus-infettivo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/08\/08\/estorsione-tramite-virus-infettivo\/","title":{"rendered":"ESTORSIONE TRAMITE VIRUS INFETTIVO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/08\/video-malato.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/08\/video-malato-300x225.jpg\" alt=\"\" title=\"video malato\" width=\"300\" height=\"225\" class=\"alignnone size-medium wp-image-33238\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/08\/video-malato-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/08\/video-malato.jpg 320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Questa volta non si tratta del solito tossicodipendente con una siringa in mano che cerca di estorcere qualche spicciolo ai passanti con la minacciandoli di infettarli.<br \/>\nSi tratta invece di allarme per un nuovo virus informatico messo in circolazione a scopo di estorsione.<br \/>\nEsperti svizzeri mettono in guardia la platea degli utenti della rete in merito ad un nuovo software nocivo di nome &#8220;SynoLocker&#8221; che sarebbe utilizzato a scopo di estorsione. A rischio sono memorie di massa in rete NAS (Network Attached Storage) del produttore Synologie con sistemi operativi meno recenti, indica la Centrale d&#8217;annuncio e d&#8217;analisi per la sicurezza dell&#8217;informazione (MELANI). Il programma agisce in modo simile a &#8220;Cryptolocker&#8221;, virus osservato per la prima volta lo scorso novembre in Svizzera che cripta i dati presenti sul computer e in seguito estorce pagamenti alle vittime in cambio della decodificazione. MELANI, consiglia ai clienti di utilizzare la versione pi\u00f9 aggiornata del sistema operativo e di copiare i dati regolarmente su supporti esterni collegati al computer solo durante la procedura di backup. La Centrale informa, inoltre, che \u00e8 ora disponibile un servizio gratuito online con il quale \u00e8 possibile decodificare i dati criptati da &#8220;Cryplocker&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/08\/08\/estorsione-tramite-virus-infettivo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/08\/08\/estorsione-tramite-virus-infettivo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Questa volta non si tratta del solito tossicodipendente con una siringa in mano che cerca di estorcere qualche spicciolo ai passanti con la minacciandoli di infettarli. Si tratta invece di allarme per un nuovo virus informatico messo in circolazione a scopo di estorsione. Esperti svizzeri mettono in guardia la platea degli utenti della rete in [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":33238,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/33234"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=33234"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/33234\/revisions"}],"predecessor-version":[{"id":33239,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/33234\/revisions\/33239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/33238"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=33234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=33234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=33234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}