{"id":33666,"date":"2014-08-16T09:17:25","date_gmt":"2014-08-16T07:17:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=33666"},"modified":"2014-08-16T09:17:25","modified_gmt":"2014-08-16T07:17:25","slug":"crisi-meloni-fdi-rompere-gabbia-euro","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/08\/16\/crisi-meloni-fdi-rompere-gabbia-euro\/","title":{"rendered":"Crisi, Meloni (Fdi): Rompere gabbia euro"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/08\/1389697673_meloni-940x400.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/08\/1389697673_meloni-940x400-300x236.jpg\" alt=\"\" title=\"1389697673_meloni-940x400\" width=\"300\" height=\"236\" class=\"alignnone size-medium wp-image-33667\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/08\/1389697673_meloni-940x400-300x236.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/08\/1389697673_meloni-940x400.jpg 508w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>&#8220;I pessimi dati sull&#8217;andamento del Pil della Germania e di molti altri Stati europei che adottano l&#8217;euro confermano quello che Fratelli d&#8217;Italia-Alleanza Nazionale ha sostenuto da sempre: la moneta unica non funziona e sta provocando recessione e disoccupazione anche in quelle Nazioni che finora ne hanno tratto un vantaggio competitivo. Analizzare questa situazione vuol dire affrontare la questione dell&#8217;euro in modo pragmatico, non ideologico e senza preclusioni. Capire, dati alla mano, cosa conviene fare, perch\u00e9 finora l&#8217;euro ha distrutto la domanda interna, ha fatto crollare i consumi delle famiglie e ha disintegrato la competitivit\u00e0 delle nostre aziende. \u00c8 uno dei pi\u00f9 potenti fattori di disgregazione dell&#8217;unit\u00e0 europea e sta mettendo in pericolo tutti i progressi che finora sono stati fatti per rafforzare la solidariet\u00e0 tra i popoli d&#8217;Europa&#8221;. \u00c8 quanto scrive il presidente di Fratelli d&#8217;Italia-Alleanza Nazionale, Giorgia Meloni, in un editoriale pubblicato sul sito www.fratelli-italia.it. &#8220;Prima si rompe la gabbia dell&#8217;euro e si abbandona la follia di un sistema costruito su economie troppo diverse tra loro -continua Meloni &#8211; e pi\u00f9 l&#8217;Italia e l&#8217;Europa avranno la possibilit\u00e0 di tornare a crescere e avere un futuro. A dispetto delle certezze degli integralisti dell&#8217;euro, questa al momento sembra la strada pi\u00f9 credibile da percorrere, perch\u00e9 l&#8217;alternativa \u00e8 la realt\u00e0 drammatica che stiamo vivendo. E se esistono ipotesi migliori di queste, che non siano il semplice mantenimento dello status quo, saremo felici di sostenerle. Ma se l&#8217;alternativa \u00e8 fare finta che vada tutto bene mentre le aziende chiudono, i disoccupati aumentano e sempre pi\u00f9 famiglie scendono sotto la soglia della povert\u00e0, allora serve qualcuno che abbia il coraggio di dire le cose come stanno e non come vorremmo che fossero&#8221;, aggiunge il presidente di Fdi-An.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/08\/16\/crisi-meloni-fdi-rompere-gabbia-euro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/08\/16\/crisi-meloni-fdi-rompere-gabbia-euro\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&#8220;I pessimi dati sull&#8217;andamento del Pil della Germania e di molti altri Stati europei che adottano l&#8217;euro confermano quello che Fratelli d&#8217;Italia-Alleanza Nazionale ha sostenuto da sempre: la moneta unica non funziona e sta provocando recessione e disoccupazione anche in quelle Nazioni che finora ne hanno tratto un vantaggio competitivo. Analizzare questa situazione vuol dire [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":33667,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/33666"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=33666"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/33666\/revisions"}],"predecessor-version":[{"id":33668,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/33666\/revisions\/33668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/33667"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=33666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=33666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=33666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}