{"id":3400,"date":"2012-08-14T16:16:18","date_gmt":"2012-08-14T16:16:18","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=3400"},"modified":"2012-08-14T16:16:20","modified_gmt":"2012-08-14T16:16:20","slug":"stelle-del-parco-giovedi-16-agosto-il-programma-completo-la-documentazione-fotografica-e-tutte-le-informazioni-sullevento-dellestate-le","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/08\/14\/stelle-del-parco-giovedi-16-agosto-il-programma-completo-la-documentazione-fotografica-e-tutte-le-informazioni-sullevento-dellestate-le\/","title":{"rendered":"STELLE DEL PARCO &#8211; GIOVEDI&#8217; 16 AGOSTO &#8211; IL PROGRAMMA COMPLETO, LA DOCUMENTAZIONE FOTOGRAFICA E TUTTE LE INFORMAZIONI SULL&#8217;EVENTO DELL&#8217;ESTATE LE"},"content":{"rendered":"<p align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/08\/14\/stelle-del-parco-giovedi-16-agosto-il-programma-completo-la-documentazione-fotografica-e-tutte-le-informazioni-sullevento-dellestate-le\/club-dogo-01\/\" rel=\"attachment wp-att-3401\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/club-dogo-01-198x300.jpg\" alt=\"\" width=\"198\" height=\"300\" class=\"alignnone size-medium wp-image-3401\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/club-dogo-01-198x300.jpg 198w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/club-dogo-01.jpg 473w\" sizes=\"(max-width: 198px) 100vw, 198px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/08\/14\/stelle-del-parco-giovedi-16-agosto-il-programma-completo-la-documentazione-fotografica-e-tutte-le-informazioni-sullevento-dellestate-le\/club-dogo-02\/\" rel=\"attachment wp-att-3402\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/club-dogo-02-300x229.jpg\" alt=\"\" width=\"300\" height=\"229\" class=\"alignnone size-medium wp-image-3402\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/club-dogo-02-300x229.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/club-dogo-02.jpg 630w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/08\/14\/stelle-del-parco-giovedi-16-agosto-il-programma-completo-la-documentazione-fotografica-e-tutte-le-informazioni-sullevento-dellestate-le\/locandina-16-agosto-2\/\" rel=\"attachment wp-att-3403\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/locandina-16-agosto1-199x300.jpg\" alt=\"\" width=\"199\" height=\"300\" class=\"alignnone size-medium wp-image-3403\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/locandina-16-agosto1-199x300.jpg 199w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/locandina-16-agosto1-682x1024.jpg 682w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/locandina-16-agosto1.jpg 1299w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/08\/14\/stelle-del-parco-giovedi-16-agosto-il-programma-completo-la-documentazione-fotografica-e-tutte-le-informazioni-sullevento-dellestate-le\/anna-01-2\/\" rel=\"attachment wp-att-3404\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/anna-011-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" class=\"alignnone size-medium wp-image-3404\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/anna-011-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/anna-011.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/08\/14\/stelle-del-parco-giovedi-16-agosto-il-programma-completo-la-documentazione-fotografica-e-tutte-le-informazioni-sullevento-dellestate-le\/anna-02-2\/\" rel=\"attachment wp-att-3405\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/anna-021-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" class=\"alignnone size-medium wp-image-3405\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/anna-021-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/anna-021-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/anna-021.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p align=\"center\"><strong><em>STELLE DEL PARCO<\/em><\/strong><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Ritorna uno degli eventi pi\u00f9 attesi dell\u2019estate leccese. Gioved\u00ec 16 agosto riflettori accesi sul Parco di Rauccio: musica, installazioni luminose, mapping in 3d della masseria e prodotti \u00a0enogastronomici. Predisposto anche un servizio autobus per raggiungere l\u2019oasi naturale<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>E\u2019 fissato per <strong>gioved\u00ec 16 agosto<\/strong> l\u2019appuntamento con <strong>Stelle del Parco<\/strong>, quest\u2019anno con un cartellone eccezionale nel quale spiccano i milanesi <strong>Club Dogo<\/strong>, la crew pi\u00f9 prolifica del rap italiano, la pi\u00f9 famosa in assoluta e quella che vanta il pi\u00f9 grande numero di fan. <strong>Jake la Furia<\/strong>, <strong>Gu\u00e8 Pegueno<\/strong> e <strong>Don Joe<\/strong> presenteranno, per l\u2019occasione, uno spettacolo tratto dal loro sesto album, <em>\u201cNoi siamo il Club\u201d<\/em>, a met\u00e0 strada tra il live il dj set.<\/p>\n<p>Come vuole la tradizione, per una notte sola il <strong>Parco Naturale Regionale Bosco e Paludi di Rauccio<\/strong>, in particolar modo la <strong>Masseria Rauccio &#8211;<\/strong> suggestivo simbolo dell\u2019area antistante il bosco, caratterizzata dall\u2019antica torre di difesa risalente al XV secolo &#8211; torner\u00e0 ad essere la location del consueto evento annuale completamente gratuito per il pubblico promosso dal settore Ambiente dell\u2019Amministrazione Comunale, tra i pi\u00f9 attesi dell\u2019estate leccese.<\/p>\n<p>Oltre ai Club Dogo sul palco salir\u00e0 il vulcanico <strong>Cesare Dell\u2019Anna<\/strong> con una formazione speciale degli <strong>Opa Cupa<\/strong>, l\u2019<strong>Electric Trio<\/strong>, nella quale, oltre alla celebre tromba di Dell\u2019Anna, spiccano Luigi Bruno (chitarra) e Ekland Hasa (tastiere). La performance sar\u00e0 animata dai ritmi incalzanti delle danze dell\u2019est, dagli antichi canti bosniaci mescolati alla cultura albanese, allargandosi al grande Mediterraneo fino alle coste dell\u2019Africa settentrionale. Particolarit\u00e0 del concerto sar\u00e0 la rilettura in chiave elettronica del materiale edito e inedito firmato da Cesare Dell\u2019Anna e compagni.<\/p>\n<p>Dalle ore <strong>21<\/strong> e fino a notte fonda la <strong>Masseria Rauccio<\/strong> sar\u00e0 la cornice di un <strong>evento musicale<\/strong>,<strong> <\/strong>ma<strong> <\/strong>anche<strong> enogastronomico<\/strong>, e che si svolger\u00e0 sotto l\u2019egida dell\u2019eco-sostenibilit\u00e0, regalando un\u2019esperienza unica sia ai cittadini sia ai turisti presenti e agli abitanti dei comuni limitrofi.<\/p>\n<p><strong>Stand eno-gastronomici<\/strong> a cura degli agriturismo e delle aziende che operano dell\u2019area Parco di Rauccio; <strong>Visite Guidate Notturne nel Bosco<\/strong> a cura della Cooperativa <strong>Terradimezzo<\/strong> e allietate dall\u2019intervento del <strong>M\u00b0 Gianluca Milanese<\/strong>, e del suo flauto traverso, tra i pi\u00f9 celebri e apprezzati in tutta Italia; esposizioni di attrezzature e tecniche per Kite Surf; area relax con massaggi shiatzu ed esposizione di creazioni di sartoria artigianale salentina; <strong>Laboratorio Creativo sul Recupero del Vetro<\/strong> distribuzione gadget e proiezioni multimediali; <strong>Laboratorio Didattico sulla Biodoversit\u00e0 del Parco<\/strong> a cura del <strong>WWF Salento<\/strong>, apertura straordinaria notturna del <strong>Centro Recupero Tartarughe del Salento<\/strong>; interventi ed esposizioni di <strong>Lega Ambiente<\/strong> e <strong>Forma Mentis<\/strong>.<\/p>\n<p>Un evento che, oltre a prevedere spettacoli di qualit\u00e0 con artisti di altissimo profilo della scena musicale hip hop nazionale e di quella salentino-balcanica, vanter\u00e0 un\u2019installazione video tra le pi\u00f9 grandi mai realizzate nel Sud Italia e che potr\u00e0 contare sul mapping 3D dell\u2019intera Masseria, a cura della societ\u00e0 milanese operante in seno all\u2019<strong>Accademia di Comunicazione di Brera in Milano<\/strong>, <strong>In-Synch Lab<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Grande attenzione sar\u00e0 rivolta anche alla sostenibilit\u00e0 dell\u2019evento stesso, oltre ad installazioni luminose a bassissimo impatto ambientale al fine di valorizzare la suggestiva scenografia naturale della location, il basso impatto dei decibel che verranno concentrati unicamente nell\u2019area concerto grazie a sofisticati impianti sonori di ultima generazione firmati Void, prestigiosissima azienda inglese leader del settore.<\/p>\n<p>Per raggiungere il Parco si potr\u00e0 fare affidamento sul servizio autobus organizzato dalla <strong>Sgm <\/strong>che, per ridurre il numero delle auto che potrebbero giungere nei pressi dell\u2019area parco, ha istituito un servizio speciale notturno. Il costo del servizio sar\u00e0 pari alla normale tariffa urbana di 90 centesimi\u00a0 acquistando il normale biglietto prima di salire sul mezzo o di 1,50 euro acquistando il biglietto\u00a0direttamente dal conducente a bordo del bus (sar\u00e0 valido\u00a0anche l\u2019utilizzo dell\u2019abbonamento ai mezzi di cui si \u00e8 gi\u00e0 eventualmente in possesso).<\/p>\n<p>Di seguito gli orari:<\/p>\n<p><strong>Servizio Notturno Autobus Cittadino da Lecce<\/strong>:<\/p>\n<p>ANDATA, partenze <strong>dal City Terminal <\/strong>(Foro Boario, Viale Porta d\u2019Europa):<\/p>\n<p>h 21,00 &gt;&gt;&gt; Parco di Rauccio;<\/p>\n<p>h 21,30 &gt;&gt;&gt; Parco di Rauccio;<\/p>\n<p>h 22,00 &gt;&gt;&gt; Parco di Rauccio;<\/p>\n<p>h 22,30 &gt;&gt;&gt; Parco di Rauccio;<\/p>\n<p>h 23,00 &gt;&gt;&gt; Parco di Rauccio;<\/p>\n<p>h 23,30 &gt;&gt;&gt; Parco di Rauccio.<\/p>\n<p>&nbsp;<\/p>\n<p>RITORNO, <strong>dal Parco di Rauccio<\/strong>:<\/p>\n<ul>\n<li>h 02,00 &gt;&gt;&gt; City Terminal;<\/li>\n<li>h 02,30 &gt;&gt;&gt; City Terminal;<\/li>\n<li>h 03,00 &gt;&gt;&gt; City Terminal;<\/li>\n<li>h 03,30 &gt;&gt;&gt; City Terminal;<\/li>\n<li>h 04,00 &gt;&gt;&gt; City Terminal.<\/li>\n<\/ul>\n<p>Promotori dell\u2019evento, anche quest\u2019anno, affianco al settore Ambiente dell\u2019Amministrazione Comunale, all\u2019Assessorato alle Politiche Ambientali e all\u2019Autorit\u00e0 di Gestione del Parco Naturale Regionale Bosco e Paludi di Rauccio, il WWF Lecce, Legambiente, la Cooperativa Terradimezzo, il Centro Recupero Tartarughe del Salento, la SGM e il Consorzio Recupero Vetro \u2013 COREVE e Ancitel Energia &amp; Ambiente \u2013 Ancitel E&amp;A.<\/p>\n<p>\u201c<em>E\u2019 nel ricco programma dell\u2019evento Stelle di Vetro &#8211; <\/em>dichiara l\u2019assessore alle Politiche<strong> <\/strong>Ambientali del Comune di Lecce, <strong>Andrea Guido<\/strong> &#8211; <em>che emergono la metodologia dell\u2019azione di marketing dell\u2019Amministrazione Comunale e gli sforzi costanti dell\u2019Assessorato alle Politiche Ambientali per creare strumenti d\u2019incentivazione e promozione dell\u2019immagine del territorio, di tutela e valorizzazione del patrimonio ambientale, ma anche sociale, culturale ed economico<\/em>\u201d. <em>\u201cL\u2019intero<\/em> <em>allestimento dell\u2019evento<\/em> \u2013 aggiunge l\u2019assessore Guido &#8211; <em>sar\u00e0 contraddistinto dall\u2019idea di poter dimostrare in concreto l&#8217;importanza della necessit\u00e0 di attuare un corretto recupero del vetro (anche per colore), ridurre la quantit\u00e0 dei rifiuti non recuperabili e assumere comportamenti civilmente e ambientalmente sostenibili. Vogliamo esaltare le risorse naturali, culturali, associative e agrituristiche del territorio del Parco Naturale Regionale di Rauccio, con lo scopo di valorizzarle e farle conoscere, ma soprattutto, operando una precisa azione d\u2019informazione ed educazione ambientale. Una kermesse, quella del 16 agosto, in cui vengono fuse, a mio avviso, quindi, finalit\u00e0 culturali, sociali, d\u2019intrattenimento e di marketing strategico\u201d.<\/em><\/p>\n<p>Soddisfazione \u00e8 stata espressa anche dal dirigente del settore Ambiente del Comune di Lecce e Direttore del Parco di Rauccio,<strong> Fernando Bonocuore. <\/strong><\/p>\n<p><em>\u201cDopo la sottoscrizione dell\u2019Accordo di Programma con il <strong>Consorzio Recupero Vetro (CO.RE.VE)<\/strong> e con <strong>Ancitel Energia &amp; Ambiente<\/strong> \u2013 <strong>Ancitel E&amp;A<\/strong> \u2013 e la relativa Convenzione per l\u2019erogazione del relativo incentivo economico e dopo il conferimento nelle mani del sindaco Paolo Perrone dei premi <strong>Blue Award<\/strong> e<strong> Green Award<\/strong> all\u2019Amministrazione Comunale da parte del CO.RE.VE. e l\u2019avvio del progetto <strong>\u201cPi\u00f9 vetro per Lecce\u201d<\/strong>, giunto al secondo anno, <\/em><em>questo ennesimo intervento<strong> <\/strong>dimostra ancora una volta che l<\/em><em>a salvaguardia dell\u2019ambiente resta una delle priorit\u00e0 di questa amministrazione. L\u2019evento, completamente gratuito per il pubblico, non grava sulle casse dell\u2019Amministrazione, \u00e8 realizzato, infatti, grazie ai fondi derivanti dallo stesso progetto \u2018<strong>Pi\u00f9 vetro per Lecce\u2019<\/strong> e assegnati al mio settore dal CO.RE.VE sulla base di un progetto redatto dai tecnici dell\u2019Ufficio Ambiente durante lo scorso anno\u201d.<\/em><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Info<\/strong><\/p>\n<p><strong>STELLE DEL PARCO 2012<\/strong><\/p>\n<p><strong>(Stelle di Vetro II)<\/strong><\/p>\n<p><strong>Gioved\u00ec 16 agosto \u2013 Masseria Rauccio<\/strong><\/p>\n<p><strong>Parco Naturale Regionale Bosco e Paludi di Rauccio &#8211; Lecce<\/strong><\/p>\n<p><strong>Come arrivare<\/strong>: Provinciale Lecce Torre-Chianca, al km 8 svoltare a sinistra in direzione Torre Rinalda, dopo due chilometri svoltare a destra.<\/p>\n<p><strong>Infoline<\/strong>: 393 3357865 \u2013 329 7795021<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/08\/14\/stelle-del-parco-giovedi-16-agosto-il-programma-completo-la-documentazione-fotografica-e-tutte-le-informazioni-sullevento-dellestate-le\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/08\/14\/stelle-del-parco-giovedi-16-agosto-il-programma-completo-la-documentazione-fotografica-e-tutte-le-informazioni-sullevento-dellestate-le\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>STELLE DEL PARCO \u00a0 Ritorna uno degli eventi pi\u00f9 attesi dell\u2019estate leccese. Gioved\u00ec 16 agosto riflettori accesi sul Parco di Rauccio: musica, installazioni luminose, mapping in 3d della masseria e prodotti \u00a0enogastronomici. Predisposto anche un servizio autobus per raggiungere l\u2019oasi naturale \u00a0 \u00a0 E\u2019 fissato per gioved\u00ec 16 agosto l\u2019appuntamento con Stelle del Parco, quest\u2019anno [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3405,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3400"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=3400"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3400\/revisions"}],"predecessor-version":[{"id":3407,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3400\/revisions\/3407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/3405"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=3400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=3400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=3400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}