{"id":36519,"date":"2014-10-06T16:13:43","date_gmt":"2014-10-06T14:13:43","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=36519"},"modified":"2014-10-06T16:13:43","modified_gmt":"2014-10-06T14:13:43","slug":"una-denuncia-per-rapina-e-un-arresto-per-droga","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/06\/una-denuncia-per-rapina-e-un-arresto-per-droga\/","title":{"rendered":"UNA DENUNCIA PER RAPINA E UN ARRESTO PER DROGA"},"content":{"rendered":"<h4><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/P-PICONESE.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"214\" height=\"300\" title=\"P - PICONESE\" class=\"alignleft size-medium wp-image-36520\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/P-PICONESE-214x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/P-PICONESE-214x300.jpg 214w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/P-PICONESE.jpg 277w\" sizes=\"(max-width: 214px) 100vw, 214px\" \/><\/a>Gli agenti della Questura di Lecce, indagando\u00a0 sulla rapina compiuta sabato scorso presso la tabaccheria di\u00a0via Dalmazio Birago, hanno effettuato una serie di perquisizioni sulla base dei primi elementi raccolti in fase di indagini.<\/h4>\n<h4>Dopo una di esse\u00a0hanno denunciato in stato di libert\u00e0, A.C., trentatreenne leccese con precedenti specifici per reati contro il patrimonio. L\u2019uomo, fuori dalla flagranza, \u00e8 stato infatti individuato quale co-autore della rapina, in quanto possessore della motocicletta utilizzata dai malfattori per raggiungere la tabaccheria e poi fuggire:\u00a0sulla Yamaha 600 di colore nero c&#8217;erano ancora i\u00a0biglietti gratta e vinci asportati durante la rapina.<\/h4>\n<h4>Ma queste perquisizioni hanno portato anche ad un altro risultato. Infatti, questa mattina\u00a0i poliziotti hanno arrestato \u00a0in flagranza di reato Francesco Piconese (nella foto), ventisette anni, residente ad Arnesano, gravato da precedenti penali per reati contro il patrimonio e per cessione illecita di sostanze stupefacenti.<\/h4>\n<h4>Durante il corso della perquisizione domiciliare effettuata questa mattina\u00a0a casa\u00a0sua, e specificatamente nella camera da letto, sono stati rinvenuti centotrenta grammi lordi di eroina. La sostanza stupefacente era occultata sotto il materasso del suo letto all\u2019interno di una busta in plastica. Sull\u2019armadio\u00a0\u00e8 stata rinvenuta inoltre la somma di 510,00 euro ritenuta provento dell\u2019attivit\u00e0 di spaccio.<\/h4>\n<p>&nbsp;<\/p>\n<h4><\/h4>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/06\/una-denuncia-per-rapina-e-un-arresto-per-droga\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/06\/una-denuncia-per-rapina-e-un-arresto-per-droga\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Gli agenti della Questura di Lecce, indagando\u00a0 sulla rapina compiuta sabato scorso presso la tabaccheria di\u00a0via Dalmazio Birago, hanno effettuato una serie di perquisizioni sulla base dei primi elementi raccolti in fase di indagini. Dopo una di esse\u00a0hanno denunciato in stato di libert\u00e0, A.C., trentatreenne leccese con precedenti specifici per reati contro il patrimonio. L\u2019uomo, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":36520,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/36519"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=36519"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/36519\/revisions"}],"predecessor-version":[{"id":36522,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/36519\/revisions\/36522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/36520"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=36519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=36519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=36519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}