{"id":36563,"date":"2014-10-07T17:28:48","date_gmt":"2014-10-07T15:28:48","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=36563"},"modified":"2014-10-07T17:29:06","modified_gmt":"2014-10-07T15:29:06","slug":"importante-operazione-dei-carabinieri-smantellata-la-masseria-dello-spaccio-tra-lecce-e-surbo-un-arresto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/07\/importante-operazione-dei-carabinieri-smantellata-la-masseria-dello-spaccio-tra-lecce-e-surbo-un-arresto\/","title":{"rendered":"IMPORTANTE OPERAZIONE DEI CARABINIERI\/ SMANTELLATA LA MASSERIA DELLO SPACCIO TRA LECCE E SURBO, UN ARRESTO"},"content":{"rendered":"<h3>Ogni sera accoglieva clienti provenienti da tutta la provincia, tanto che\u00a0la zona\u00a0era stata paragonata a Scampia, il quartiere delle vele napoletano dove gli spacciatori dettano legge e \u00abvedette\u00bb e telecamere li allertano tempestivamente dell&#8217;arrivo degli \u00absbirri\u00bb, permettendogli di sfuggire puntualmente ai controlli. E un po&#8217; come il &#8220;Tossic park&#8221; di Torino di anni fa sulle rive della Dora.<\/h3>\n<h3>Ma i Carabinieri (operazione condotta dai nuclei di Copertino, Gallipoli, Campi Salentina e Lecce, con l&#8217;ausilio del nucleo cinofilo di Modugno)\u00a0indagavano da tempo su questo &#8220;supermarket&#8221; della droga leccese e questa mattina hanno inferto il colpo di grazia al traffico illecito.<\/h3>\n<h3>Un\u00a0ragazzo,\u00a0Federico Vitale,20 anni (nella foto) <a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/VITALE-FEDERICO-1.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"232\" height=\"300\" title=\"VITALE FEDERICO 1\" class=\"alignleft size-medium wp-image-36564\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/VITALE-FEDERICO-1-232x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/VITALE-FEDERICO-1-232x300.jpg 232w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/VITALE-FEDERICO-1.jpg 596w\" sizes=\"(max-width: 232px) 100vw, 232px\" \/><\/a>\u00e8 finito in manette.<\/h3>\n<h3>Numerose, lunghe ed approfondite le perquisizioni che hanno interessato la masseria di propriet\u00e0 della famiglia Vitale\u00a0in contrada Verrazze \u2013 tra Lecce e Surbo &#8211;\u00a0considerata terra franca per lo spaccio. Auto incolonnate in attesa di ritirare le dosi. Vedette sempre all&#8217;erta e telecamere puntate 24h su 24 in tutte le direzioni. Oggetti contundenti e pietre da lanciare contro gli agenti o i militari dell&#8217;Arma che disturbavano l&#8217;attivit\u00e0. I primi controlli erano partiti mesi fa.<\/h3>\n<h3>Gi\u00e0 nel 2012 c&#8217;erano stati i primi servizi di osservazione, controllo e pedinamento di soggetti tossicodipendenti provenienti dal territorio di competenza della Compagnia Carabinieri di Gallipoli, culminati con il blitz di dicembre presso un\u2019altra masseria della medesima famiglia in contrada \u201cLi Manzi\u201d. Da allora si erano avuti importanti e sempre maggiori riscontri sull\u2019attivit\u00e0 posta in essere dalla famiglia Vitale.<\/h3>\n<h3>Tutto questo, per\u00f2, non era stato sufficiente a stroncare il traffico di droga. Anche perch\u00e9 il sistema di video sorveglianza adottato dai malviventi era molto elaborato. I \u00abclienti\u00bb si recavano presso l\u2019abitazione, punto dove venivano ritirate le dosi. Gli scambi avvenivano in due punti: il retro del fienile o l\u2019ingresso principale della casa, ma solo dopo il \u00abcontrollo\u00bb delle telecamere da parte dei Vitale. In una stradina sterrata senza via d&#8217;uscita adiacente alla masseria avveniva poi il \u00abdrug &amp; drive\u00bb: le auto venivano fatte incolonnare e controllate all&#8217;interno. Nel corso del blitz, scattato nella mattinata di\u00a0e protrattosi fino al tardo pomeriggio, i Carabinieri hanno sequestrato, dopo averlo trovato, anche se era stato abilmente occultato:<\/h3>\n<h3>&#8211;\u00a0\u00a0 ottocentocinquanta grammi di\u00a0sostanza stupefacente tipo \u201cmarijuana\u201d;<\/h3>\n<h3>&#8211;\u00a0 5565 euro\u00a0in banconote vario taglio, nastro isolante e altro materiale per il confezionamento delle dosi, nonch\u00e9\u00a0due bilancini di precisione.<\/h3>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/07\/importante-operazione-dei-carabinieri-smantellata-la-masseria-dello-spaccio-tra-lecce-e-surbo-un-arresto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/07\/importante-operazione-dei-carabinieri-smantellata-la-masseria-dello-spaccio-tra-lecce-e-surbo-un-arresto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Ogni sera accoglieva clienti provenienti da tutta la provincia, tanto che\u00a0la zona\u00a0era stata paragonata a Scampia, il quartiere delle vele napoletano dove gli spacciatori dettano legge e \u00abvedette\u00bb e telecamere li allertano tempestivamente dell&#8217;arrivo degli \u00absbirri\u00bb, permettendogli di sfuggire puntualmente ai controlli. E un po&#8217; come il &#8220;Tossic park&#8221; di Torino di anni fa sulle [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":36564,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/36563"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=36563"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/36563\/revisions"}],"predecessor-version":[{"id":36567,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/36563\/revisions\/36567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/36564"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=36563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=36563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=36563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}