{"id":36745,"date":"2014-10-10T16:26:35","date_gmt":"2014-10-10T14:26:35","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=36745"},"modified":"2014-10-10T16:26:35","modified_gmt":"2014-10-10T14:26:35","slug":"la-giornata-provinciale-del-ringraziamento-della-coldiretti-domenica-a-parabita","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/10\/la-giornata-provinciale-del-ringraziamento-della-coldiretti-domenica-a-parabita\/","title":{"rendered":"LA GIORNATA PROVINCIALE DEL RINGRAZIAMENTO DELLA COLDIRETTI DOMENICA A PARABITA"},"content":{"rendered":"<h4><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/untitled20.png\"><img decoding=\"async\" loading=\"lazy\" width=\"216\" height=\"234\" title=\"untitled\" class=\"alignleft size-full wp-image-36746\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/untitled20.png\" \/><\/a>La Coldiretti Lecce celebra la Giornata provinciale del Ringraziamento, un rito annuale di ringraziamento per i frutti generosi che la terra offre agli uomini, grazie al lavoro ed all&#8217;impegno dei contadini, domenica 12 ottobre, a Parabita, con inizio alle 9.30. In programma riti religiosi e civili, degustazioni di prodotti locali e alle 17.30 un convegno sull&#8217;identit\u00e0 salentina<\/h4>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/10\/la-giornata-provinciale-del-ringraziamento-della-coldiretti-domenica-a-parabita\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/10\/la-giornata-provinciale-del-ringraziamento-della-coldiretti-domenica-a-parabita\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La Coldiretti Lecce celebra la Giornata provinciale del Ringraziamento, un rito annuale di ringraziamento per i frutti generosi che la terra offre agli uomini, grazie al lavoro ed all&#8217;impegno dei contadini, domenica 12 ottobre, a Parabita, con inizio alle 9.30. In programma riti religiosi e civili, degustazioni di prodotti locali e alle 17.30 un convegno [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":36746,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/36745"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=36745"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/36745\/revisions"}],"predecessor-version":[{"id":36748,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/36745\/revisions\/36748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/36746"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=36745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=36745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=36745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}