{"id":3687,"date":"2012-09-01T13:18:04","date_gmt":"2012-09-01T13:18:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=3687"},"modified":"2012-09-01T13:18:06","modified_gmt":"2012-09-01T13:18:06","slug":"torre-dellorso-1-2-settembre-2012-appuntamento-deccezione-per-il-nuoto-di-fondo-in-acque-libere","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/01\/torre-dellorso-1-2-settembre-2012-appuntamento-deccezione-per-il-nuoto-di-fondo-in-acque-libere\/","title":{"rendered":"Torre dell\u2019Orso 1 &#8211; 2 settembre 2012   Appuntamento d\u2019eccezione per il nuoto di fondo in acque libere."},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/01\/torre-dellorso-1-2-settembre-2012-appuntamento-deccezione-per-il-nuoto-di-fondo-in-acque-libere\/schermata-2012-09-01-a-15-15-46\/\" rel=\"attachment wp-att-3688\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/09\/Schermata-2012-09-01-a-15.15.46-208x300.png\" alt=\"\" width=\"208\" height=\"300\" class=\"alignnone size-medium wp-image-3688\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/09\/Schermata-2012-09-01-a-15.15.46-208x300.png 208w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/09\/Schermata-2012-09-01-a-15.15.46-712x1024.png 712w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/09\/Schermata-2012-09-01-a-15.15.46.png 765w\" sizes=\"(max-width: 208px) 100vw, 208px\" \/><\/a><\/p>\n<p>Appuntamento d\u2019eccezione per il <strong>nuoto di fondo in acque libere<\/strong>. Sar\u00e0 infatti la splendida cornice della baia di <strong>Torre dell\u2019Orso<\/strong>, marina di Melendugno, in provincia di Lecce, ad ospitare il <strong><span style=\"text-decoration: underline\">1\u00b0 Trofeo \u201cLe Due sorelle\u201d<\/span><\/strong>. L\u2019evento si svolger\u00e0 i prossimi <strong>1 <\/strong>e<strong> 2 settembre<\/strong> (date di riserva 8-9 settembre) e sar\u00e0 valevole per il campionato nazionale di nuoto di fondo in acque libere, circuito <strong>FIN<\/strong>.<\/p>\n<p>La manifestazione prevede tre gare: la <strong>2,5 km<\/strong>, la <strong>5,2 km<\/strong> e la <strong>10 km<\/strong>. La prima giornata di competizioni vedr\u00e0 impegnati nelle acque cristalline della rinomata localit\u00e0 balneare salentina atleti che si sfideranno sui primi due percorsi di gara. L\u2019indomani avr\u00e0 luogo la prova sui 10 chilometri.<\/p>\n<p>L\u2019organizzazione del trofeo \u00e8 stata curata dalla neonata associazione \u201c<strong>Salento NAL<\/strong>\u201d, in collaborazione con <strong>Fimco Sport<\/strong>. Il termine ultimo per presentare le domande di iscrizione \u00e8 fissato per il 20 agosto 2012, con la quota cos\u00ec ripartita: \u20ac 10 per la 2,5 km; \u20ac 15 per la 5,2 km; \u20ac 20 per la sola 10 km ed infine \u20ac 35 per tutte e tre le competizioni. Il pagamento di tali importi si effettuer\u00e0 direttamente sul campo di gara, ospitato nello stabilimento balneare \u201cLa Pineta\u201d.<\/p>\n<p>Il programma completo della manifestazione (che ha gi\u00e0 raccolto unanimi consensi, oltre che autorevoli apprezzamenti), tutti i dati del campo gara, cos\u00ec come ogni altra informazione sono disponibili sul sito: <strong><em><span style=\"text-decoration: underline\"><a href=\"http:\/\/www.salentonal.it\">www.salentonal.it<\/a><\/span><\/em><\/strong> nel quale \u00e8 presente l\u2019apposita sezione per quanti volessero effettuare le iscrizioni <em>on-line<\/em> all\u2019indirizzo: <strong><em><a href=\"mailto:salentonal@libero.it\">salentonal@libero.it<\/a><\/em><\/strong>. Le adesioni si potranno sottoscrivere, sempre in rete, anche tramite un apposito <em>form<\/em> da compilare.<\/p>\n<p>Responsabili dell\u2019evento sono <strong>Ivan Marrocco<\/strong> (responsabile e Tecnico di Salento Nal &#8211; mob. 347.1961484) e <strong>Mario Paolino<\/strong> (infermiere specializzato in Rianimazione Terapia Intensiva della Salento Nal &#8211; mob. 333.7630232).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><strong><em>Segreteria organizzativa: SalentoNAL (e-mail: staff@salentonal.it)<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/01\/torre-dellorso-1-2-settembre-2012-appuntamento-deccezione-per-il-nuoto-di-fondo-in-acque-libere\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/01\/torre-dellorso-1-2-settembre-2012-appuntamento-deccezione-per-il-nuoto-di-fondo-in-acque-libere\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Appuntamento d\u2019eccezione per il nuoto di fondo in acque libere. Sar\u00e0 infatti la splendida cornice della baia di Torre dell\u2019Orso, marina di Melendugno, in provincia di Lecce, ad ospitare il 1\u00b0 Trofeo \u201cLe Due sorelle\u201d. L\u2019evento si svolger\u00e0 i prossimi 1 e 2 settembre (date di riserva 8-9 settembre) e sar\u00e0 valevole per il campionato [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3688,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3687"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=3687"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3687\/revisions"}],"predecessor-version":[{"id":3691,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3687\/revisions\/3691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/3688"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=3687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=3687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=3687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}