{"id":37350,"date":"2014-10-18T16:48:45","date_gmt":"2014-10-18T14:48:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=37350"},"modified":"2014-10-18T16:49:06","modified_gmt":"2014-10-18T14:49:06","slug":"dopo-il-blocco-dei-tetti-di-spesa-regionali-disagi-al-poliambulatorio-di-piazza-bottazzi-per-leccessivo-affollamento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/18\/dopo-il-blocco-dei-tetti-di-spesa-regionali-disagi-al-poliambulatorio-di-piazza-bottazzi-per-leccessivo-affollamento\/","title":{"rendered":"DOPO IL BLOCCO DEI TETTI DI SPESA REGIONALI, DISAGI AL POLIAMBULATORIO DI PIAZZA BOTTAZZI PER L&#8217;ECCESSIVO AFFOLLAMENTO"},"content":{"rendered":"<h3><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/untitled42.png\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"123\" title=\"untitled\" class=\"alignleft size-medium wp-image-37351\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/untitled42-300x123.png\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/untitled42-300x123.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/10\/untitled42.png 350w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>di Cesare Mazzotta____________<\/h3>\n<h3>Il Poliambulatorio di piazza Bottazzi viene preso d\u2019assalto dagli utenti dopo il blocco dei \u201ctetti di spesa\u201d dei laboratori privati. Il flusso di persone \u00e8 triplicato, i tecnici e gli impiegati sono allo stremo.<\/h3>\n<h3>Dati alla mano, sono 23mila in pi\u00f9 gli utenti che passano dal Poliambulatorio leccese, da quando i laboratori privati hanno chiuso la porta in faccia agli over 65, esenti da ticket. E 300 circa quelli che ogni giorno si mettono in coda per fare i prelievi. Tutti ammassati, a turno, nella saletta all\u2019ingresso della \u201cCittadella della Salute\u201d. Quando i laboratori privati disponevano ancora di budget (sono stati dimezzati dalla Regione), al massimo se ne vedevano un centinaio.<\/h3>\n<h3>Il personale \u00e8 alle corde, ma tiene la schiena dritta. A farne le spese sono gli utenti, che pur di risparmiare sul costo degli esami, sono disposti ad attendere due ore in fila e anche\u00a0venti giorni per il referto.<\/h3>\n<h3>Una giovane signora leccese il 2 ottobre scorso ha atteso\u00a0tre ore per fare i prelievi. Ha pagato 105 euro. E prima di scegliere il laboratorio pubblico ha chiesto il preventivo alle strutture private: ha risparmiato 25 euro ma dovr\u00e0 attendere diciotto giorni per il ritiro. Le hanno spiegato che qualche esame particolare dovevano mandarlo \u00abfuori\u00bb sede, al \u201cVito Fazzi\u201d. Il laboratorio privato, ha appurato la signora, le avrebbe consegnato il referto in una settimana.\u00a0 Sono esami particolari che richiedono l\u2019utilizzo di reattivi molto costosi. I \u201crecettori\u201d, per esempio, vengono mandati a Scorrano e a Galatina. E i tempi si allungano.<\/h3>\n<h3>Ma in piazza Bottazzi alcuni esami fuori tabella sono a pagamento. Come la \u201comocisteina\u201d, un fattore di rischio cardiovascolare: si pagano 22 euro in Alpi, l\u2019attivit\u00e0 a pagamento dei medici. Al Fazzi invece 20 euro, perch\u00e9 non ha aderito all\u2019Alpi. Ogni laboratorio pu\u00f2 fissare liberamente il costo della prestazione, anche 35 \u2013 45 euro,\u00a0 perch\u00e9 l\u2019esame non rientra nel tabulato regionale.<\/h3>\n<h3>Ma non \u00e8 finita. La signora leccese dei 105 euro denuncia che &#8220;sul foglio del ritiro c\u2019\u00e8 un numero, 0832.215897, che l\u2019utente deve chiamare per sapere se gli esami sono pronti: chiamare dalle 11 alle 13, da luned\u00ec a venerd\u00ec e dalle 16 alle 18 il marted\u00ec e il gioved\u00ec: <strong>non risponde mai nessuno&#8221; <\/strong>.<\/h3>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/18\/dopo-il-blocco-dei-tetti-di-spesa-regionali-disagi-al-poliambulatorio-di-piazza-bottazzi-per-leccessivo-affollamento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/10\/18\/dopo-il-blocco-dei-tetti-di-spesa-regionali-disagi-al-poliambulatorio-di-piazza-bottazzi-per-leccessivo-affollamento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Cesare Mazzotta____________ Il Poliambulatorio di piazza Bottazzi viene preso d\u2019assalto dagli utenti dopo il blocco dei \u201ctetti di spesa\u201d dei laboratori privati. Il flusso di persone \u00e8 triplicato, i tecnici e gli impiegati sono allo stremo. Dati alla mano, sono 23mila in pi\u00f9 gli utenti che passano dal Poliambulatorio leccese, da quando i laboratori [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":37351,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/37350"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=37350"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/37350\/revisions"}],"predecessor-version":[{"id":37353,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/37350\/revisions\/37353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/37351"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=37350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=37350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=37350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}