{"id":3924,"date":"2012-09-13T10:41:24","date_gmt":"2012-09-13T10:41:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=3924"},"modified":"2012-09-13T10:42:24","modified_gmt":"2012-09-13T10:42:24","slug":"a-undici-anni-di-distanza-avanza-la-verita","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/13\/a-undici-anni-di-distanza-avanza-la-verita\/","title":{"rendered":"A UNDICI ANNI DI DISTANZA, AVANZA LA VERITA"},"content":{"rendered":"<div>ITALIA SOTT&#8217;OCCHIO MONDO COL CANNOCCHIALE<\/div>\n<div>RUBRICA DI CONTRO &#8211; INFORMAZIONE A CURA DI BEPI ANGUILLA<\/div>\n<div>\n<h2><\/h2>\n<h2><strong>A 11 anni da quell&#8217;11 settembre: era Strategia della Tensione<\/strong><\/h2>\n<p><strong>di Ferdinando Imposimato<\/strong> &#8211; 11\/09\/2012<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/13\/a-undici-anni-di-distanza-avanza-la-verita\/senza-titolo3\/\" rel=\"attachment wp-att-3926\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/09\/Senza-titolo3.png\" alt=\"\" title=\"Senza titolo3\" width=\"199\" height=\"141\" class=\"alignnone size-full wp-image-3926\" \/><\/a><\/p>\n<p>Gli attentati dell&#8217;11\/9 sono stati un&#8217;operazione globale di terrorismo di Stato consentita dall&#8217;amministrazione degli USA, che sapeva gi\u00e0 dell\u2019azione ma \u00e8 rimasta intenzionalmente non reattiva al fine di fare la guerra contro l&#8217;Afghanistan e l&#8217;Iraq. Per dirla in breve, <strong>gli eventi dell&#8217;11\/9 erano un caso di <\/strong><strong>Strategia della Tensione<\/strong> messa in atto dai poteri politici ed economici negli Stati Uniti per perseguire vantaggi in capo all&#8217;industria petrolifera e delle armi.<\/p>\n<\/div>\n<div>\n<p>Anche l&#8217;Italia \u00e8 stata una vittima della &#8220;Strategia della Tensione&#8221; della CIA, attuata in Italia dai tempi della strage di Portella della Ginestra, in Sicilia, nel 1947, fino al 1993.<\/p>\n<p>Ci sono molte prove di una tale strategia, sia circostanziali che scientifiche. Le relazioni del National Institute of Standards and Technology (NIST), del 20 novembre 2005, hanno sancito le conclusioni di seguito esposte.<\/p>\n<p>Gli aerei che hanno colpito ciascuna delle torri gemelle hanno causato tanto una breccia quanto un&#8217;esplosione evidenziata da una gigantesca palla di fuoco. Il carburante rimanente fluiva verso i piani inferiori, alimentando gli incendi. Il calore degli incendi deformava le strutture degli edifici cos\u00ec che entrambe le torri sono crollate completamente da cima a fondo. Molto poco \u00e8 rimasto di quanto era di qualsiasi dimensione dopo questi eventi, a parte i frammenti in acciaio e in alluminio e i detriti polverizzati provenienti dai pavimenti in cemento. <strong>Anche<\/strong> <strong>l\u2019edificio 7 del World Trade Center<\/strong> <strong>croll\u00f2<\/strong>: lo fece in un modo che risultava <strong>in contrasto con l&#8217;esperienza comune degli ingegneri<\/strong>.<\/p>\n<p>Il rapporto finale del NIST ha affermato che gli attacchi aerei contro le torri gemelle erano la causa dei crolli per tutti e tre gli edifici: WTC1, WTC2 e WTC7.<\/p>\n<p>Tutti e tre gli edifici sono crollati completamente, ma l&#8217;edificio 7 non fu colpito da un aereo. Il crollo totale del WTC7 ha violato l&#8217;esperienza comune ed era senza precedenti.<\/p>\n<p>Il rapporto del NIST non analizza la reale natura dei crolli. Secondo gli esperti intervenuti nel corso delle Udienze di Toronto (<em>\u201cToronto Hearings\u201d<\/em>, 8-11 settembre 2011), i crolli avevano caratteristiche che indicano esplosioni controllate. Sono d&#8217;accordo con l\u2019architetto Richard Gage e l\u2019ingegnere Jon Cole, entrambi professionisti di grande esperienza, che sono arrivati alle loro conclusioni attraverso test affidabili, prove scientifiche, e la testimonianza visiva di persone insospettabili, tra cui i vigili del fuoco e le vittime.<\/p>\n<p>L&#8217;autorevole teologo David Ray Griffin ha descritto con grande precisione perch\u00e9 l&#8217;ipotesi di demolizione controllata dovrebbe essere presa in considerazione. Vari testimoni hanno sentito raffiche di esplosioni.<\/p>\n<p>Secondo il NIST il crollo dell&#8217;edificio 7 \u00e8 stato causato da incendi provocati dal crollo delle torri gemelle. Il chimico e ricercatore indipendente Kevin Ryan, tuttavia, ha dimostrato che il NIST ha dato versioni contraddittorie del crollo dell&#8217;edificio 7. In un rapporto preliminare del NIST dichiarava che il WTC7 fu distrutto a causa di incendi provocati da gasolio conservato nel palazzo, mentre in una seconda relazione questo combustibile non era pi\u00f9 considerato come la causa del crollo dell&#8217;edificio. Ulteriori commenti sulla versione degli eventi data dal NIST sono stati formulati da <strong>David Chandler<\/strong>, un altro testimone esperto intervenuto nel corso delle Udienze di Toronto. Nonostante la presunzione del NIST in merito a tre distinte fasi di crollo, Chandler ha sottolineato che molti video disponibili dimostrano che per circa due secondi e mezzo l&#8217;accelerazione dell\u2019edificio non pu\u00f2 essere distinta da una caduta libera. Il NIST \u00e8 stato costretto a concordare con con questo fatto empirico come sottolineato da Chandler, e ora comprensibile per chiunque.<\/p>\n<p><strong>Peter Dale Scott<\/strong>, un altro testimone alle Udienze di Toronto, ha dimostrato l&#8217;esistenza di un modello d\u2019azione sistematico della CIA volto a bloccare importanti informazioni nei confronti dell&#8217;FBI, anche quando l&#8217;FBI avrebbe normalmente diritto di ottenerle. Inoltre, ci sono ulteriori elementi di prova contro <strong>George Tenet<\/strong> e <strong>Tom Wilshire<\/strong>. Secondo l&#8217;ex capo dell\u2019antiterrorismo della Casa Bianca, <strong>Richard Clarke<\/strong> (intervista rilasciata alla televisione francese e tedesca come parte di un documentario di Fabrizio Calvi e Christopf Klotz ,31 agosto 2011, nonch\u00e9 <a href=\"http:\/\/www.dagospia.com\/rubrica-3\/politica\/1-diciotto-mesi-prima-della-strage-dell119-la-cia-era-sulle-tracce-di-due-29146.htm\"><strong>l&#8217;intervista con Calvi e Leo Sisti, &#8220;Il Fatto Quotidiano &#8220;, 30 agosto 2011<\/strong><\/a>) <em>la CIA era a conoscenza dell\u2019imminente attacco dell\u201911\/9<\/em>.<\/p>\n<p>Inoltre, dal 1999 la CIA aveva indagato <strong>Khalid al-Mihdhar<\/strong> e <strong>Nawaf al-Hamzi<\/strong>, entrambi sauditi, che sono stati associati con l&#8217;aereo della American Airlines che ha colpito il Pentagono. La CIA era stata informata che Khalid al-Mihdhar e Nawaf al-Hamzi erano arrivati negli Stati Uniti all&#8217;inizio del 2000. \u00c8 legittimo dedurre che Tenet, capo della CIA, e Wilshire, secondo Peter Dale Scott una &#8220;figura chiave&#8221; nella <a href=\"http:\/\/en.wikipedia.org\/wiki\/Bin_Laden_Issue_Station\"><strong>Alec Station<\/strong><\/a>, bloccarono gli sforzi di due agenti dell&#8217;FBI, Doug Miller e Mark Rossini, intesi a notificare al centro FBI che uno dei partecipanti alla riunione di Kuala Lumpur, al-Mihdhar, aveva ottenuto un <strong>visto USA attraverso il consolato degli Stati Uniti a Jeddah<\/strong>. Il professor Scott, basandosi sulla ricerca di Kevin Fenton, cita <strong>35 occasioni in cui i dirottatori sono stati protetti in questo modo<\/strong>, a partire dal gennaio del 2000 al 5 settembre 2001. Con riferimento al precedente di questi incidenti, il <strong>motivo di questa protezione<\/strong> era evidentemente, secondo Fenton, <strong>\u00abper coprire un&#8217;operazione della CIA che era gi\u00e0 in corso.\u00bb<\/strong><\/p>\n<p>Ulteriore prova indiziaria contro Tenet e Wilshire \u00e8 la seguente. Il 12 luglio 2001 Osama bin Laden si trovava nell\u2019ospedale americano di Dubai. Fu visitato da un agente della CIA. Questa informazione \u00e8 stata data a Le Figaro, che ha anche riferito che bin Laden era stato operato in questo ospedale, essendo arrivato da Quetta (Pakistan). Questa informazione \u00e8 stata confermata da Radio France International, che ha rivelato il nome dell&#8217;agente che ha incontrato bin Laden: <strong>Larry Mitchell<\/strong>. Tenet e Wilshire, consapevoli della presenza di bin Laden negli Emirati Arabi Uniti, non sono riusciti a farlo arrestare n\u00e9 estradare, anche se i documenti dell&#8217;FBI e della CIA lo ritenevano responsabile di massacri in Kenya e Tanzania.<\/p>\n<p>L&#8217;<em>insider<\/em> <em>trading<\/em> \u00e8 una forte ulteriore prova contro la CIA, l\u2019FBI e il governo degli Stati Uniti.<\/p>\n<p><a href=\"http:\/\/ithp.org\/articles\/septemberinsidertrading.html\"><strong>Gli articoli del professor <strong>Paul Zarembka<\/strong><\/strong><\/a>, cos\u00ec come da <strong>Kevin Ryan<\/strong> e altri, dimostrano che tali casi di <em>insider trading<\/em> hanno avuto luogo nei giorni immediatamente precedenti rispetto agli attentati. Eppure questi casi di <em>insider trading<\/em> sono stati negati dall&#8217;FBI e dalla Commissione d\u2019inchiesta sull\u201911\/9.<\/p>\n<p>Ulteriore prova contro la CIA e l&#8217;amministrazione degli Stati Uniti \u00e8 la seguente. <strong>Mohammed Atta<\/strong>, almeno a partire dal maggio 2000, era sotto sorveglianza della CIA in Germania, secondo la Commissione sull\u201911\/9, sia perch\u00e9 era accusato sin dal 1986 di attentati contro Israele, sia perch\u00e9 era stato sorpreso mentre acquistava grandi quantit\u00e0 di prodotti chimici per l&#8217;uso in esplosivi a Francoforte (<em>The Observer<\/em>, 30 settembre 2001). \u00c8 stato indagato dal servizio segreto egiziano e il suo telefono cellulare era sotto controllo. Nel novembre del 1999 Mohammed Atta lasci\u00f2 Amburgo, and\u00f2 a Karachi, in Pakistan, e poi a Kandahar. Qui ha incontrato bin Laden e lo sceicco Omar Saeed (secondo la rivista specializzata in questioni di sicurezza interna GlobalSecurity.org, alla voce &#8220;Movements of Mohammed Atta&#8221;). Dopo giugno 2000 gli USA hanno continuato a monitorare Atta, intercettando le sue conversazioni con <strong><a href=\"http:\/\/www.megachip.info\/finestre\/zero-11-settembre\/1190-il-processo-al-reo-confesso-che-annegava-sei-volte-al-giorno.html\">Khalid Sheikh Mohammed<\/a><\/strong>, considerato il regista del 9\/11, che ha vissuto in Pakistan.<\/p>\n<p>Una forte prova del fatto che <strong>la CIA era a conoscenza dei movimenti irregolari di Atta <\/strong>dagli Stati Uniti verso l&#8217;Europa e all\u2019interno degli Stati Uniti \u00e8 il documento declassificato della CIA inviato dall&#8217;Agenzia a G.W Bush (<em>President\u2019s Daily Brief<\/em> \u2013 Ndt: \u201crelazione breve giornaliera per il presidente\u201d). Questo documento, del 6 agosto 2001, dice: \u00abBin Laden determinato a colpire in USA.\u00bb E continua: &#8220;relazioni di provenienza clandestina, di governi stranieri, e dei media indicano che bin Laden sin dal 1997 ha voluto condurre attacchi terroristici negli Stati Uniti. Bin Laden ha inteso in interviste a televisioni statunitensi nel 1997 e nel 1998 che i suoi seguaci avrebbero seguito l&#8217;esempio dell\u2019attentatore del World Trade Center Ramzi Yousef, e avrebbero \u201cportato i combattimenti in America\u201d.\u00bb<\/p>\n<p>Dopo gli attacchi missilistici degli Stati Uniti sulla sua base in <strong>Afghanistan<\/strong> nel 1998, bin Laden disse ai seguaci che voleva infliggere una rappresaglia a danno di Washington, secondo un servizio di intelligence straniero. Un membro operativo egiziano della Jihad islamica ha rivelato a un agente di un servizio segreto straniero, nel frattempo, che bin Laden aveva intenzione di sfruttare l&#8217;accesso operativo agli Stati Uniti per organizzare un attacco terroristico &#8230;<\/p>\n<p>Una fonte clandestina ha affermato nel 1998, che una cellula di bin Laden a New York stava reclutando giovani musulmani americani per gli attentati.<\/p>\n<p>Questo documento dimostra che <strong>la CIA, l\u2019FBI, cos\u00ec come il presidente Bush, conoscevano gi\u00e0 dal 6 agosto 2001<\/strong> chi aveva un accesso operativo: <strong>Atta<\/strong>. Nessuno ha goduto di un tale accesso negli Stati Uniti quanto Atta. Ma la CIA, l\u2019FBI e Bush non hanno fatto nulla per fermarlo.<\/p>\n<p>In Italia ho raccolto prove che la guerra in Iraq \u00e8 stata decisa dal governo degli Stati Uniti prima degli attacchi dell&#8217;11\/9 con l&#8217;aiuto dei servizi segreti italiani. Secondo <strong>Michel Chossudovsky<\/strong>, gli attacchi dell&#8217;11\/9 sono stati usati come pretesto per la guerra, avendo avuto come sfondo i molti anni in cui si \u00e8 avuta la <strong>creazione e il sostegno<\/strong> <strong>da parte della CIA della rete terroristica ora conosciuta come <\/strong><strong>al-Qa\u2019ida<\/strong>. Oggi c&#8217;\u00e8 il pericolo di una nuova &#8220;guerra preventiva&#8221; contro l&#8217;Iran da parte degli Stati Uniti. Questo potrebbe essere terribile per la gente di tutto il mondo e potrebbe anche distruggere una gran parte dell&#8217;umanit\u00e0.<\/p>\n<p>L&#8217;unica possibilit\u00e0 per avere giustizia \u00e8 quello di presentare le migliori <strong>prove<\/strong> relative al <strong>coinvolgimento di singoli individui nei fatti dell\u201911\/9<\/strong> al Procuratore della <strong>Corte penale internazionale<\/strong> chiedendogli di indagare in base agli articoli 12, 13, 15 e 17, lettere a e b, dello Statuto della Corte penale internazionale, ricordando anche il preambolo della Statuto:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><em>Riconoscere che tali gravi reati minacciano la pace, la sicurezza e il benessere del mondo, <\/em><\/li>\n<li><em>Affermare che i reati pi\u00f9 gravi che sono motivo di allarme per la comunit\u00e0 internazionale nel suo insieme non debbano rimanere impuniti e che la loro repressione debba essere efficacemente garantita mediante provvedimenti adottati a livello nazionale ed attraverso il rafforzamento della cooperazione internazionale, <\/em><\/li>\n<li><em>Essere determinati a porre fine all&#8217;impunit\u00e0 degli autori di tali crimini e quindi di contribuire al perseguimento di tali reati, <\/em><\/li>\n<li><em>Ricordare il dovere di ogni Stato di esercitare la propria giurisdizione nei confronti dei responsabili di reati internazionali &#8230;<\/em><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Ferdinando Imposimato, settembre 2012.<\/strong><\/p>\n<p><em>Fonte:<\/em><em> <\/em><a href=\"http:\/\/www.journalof911studies.com\/resources\/2012-September---Imposimato-letter.pdf\"><strong>http:\/\/www.journalof911studies.com\/resources\/2012-September&#8212;Imposimato-letter.pdf<\/strong><\/a>.<em><\/em><\/p>\n<p>&nbsp;<\/p>\n<p align=\"right\">Traduzione per Megachip a cura di <strong>Pino Cabras<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ferdinando Imposimato<\/strong> \u00e8 presidente onorario aggiunto della Suprema Corte di Cassazione ed ex senatore e deputato. A lungo ha fatto parte della Commissione bicamerale Antimafia.<\/p>\n<p>Da magistrato ha istruito alcuni tra i pi\u00f9 importanti processi sul terrorismo (il caso Aldo Moro, l&#8217;attentato al papa Giovanni Paolo II, il caso Bachelet). Ha scoperto la \u201cpista bulgara\u201d e altre connessioni terroristiche internazionali. Innumerevoli i processi contro mafia e camorra. Tra gli altri, ha istruito il caso Michele Sindona e il processo alla Banda della Magliana.<\/p>\n<p>\u00c8 autore o co-autore di sette libri sul terrorismo internazionale, la corruzione statale, e di questioni connesse, nonch\u00e9 Grand&#8217;Ufficiale dell&#8217;Ordine al merito della Repubblica Italiana.<br \/>\nTante altre notizie su <a title=\"www.ariannaeditrice.it\" href=\"http:\/\/www.ariannaeditrice.it\"><strong>www.ariannaeditrice.it<\/strong><\/a><br \/>\nGli attentati dell&#8217;11\/9 sono stati un&#8217;operazione globale di terrorismo di Stato consentita dall&#8217;amministrazione degli USA, che sapeva gi\u00e0 dell\u2019azione ma \u00e8 rimasta intenzionalmente non reattiva al fine di fare la guerra contro l&#8217;Afghanistan e l&#8217;Iraq. Per dirla in breve, <strong>gli eventi dell&#8217;11\/9 erano un caso di <\/strong><strong>Strategia della Tensione<\/strong> messa in atto dai poteri politici ed economici negli Stati Uniti per perseguire vantaggi in capo all&#8217;industria petrolifera e delle armi.<\/p>\n<p>Anche l&#8217;Italia \u00e8 stata una vittima della &#8220;Strategia della Tensione&#8221; della CIA, attuata in Italia dai tempi della strage di Portella della Ginestra, in Sicilia, nel 1947, fino al 1993.<\/p>\n<p>Ci sono molte prove di una tale strategia, sia circostanziali che scientifiche. Le relazioni del National Institute of Standards and Technology (NIST), del 20 novembre 2005, hanno sancito le conclusioni di seguito esposte.<\/p>\n<p>Gli aerei che hanno colpito ciascuna delle torri gemelle hanno causato tanto una breccia quanto un&#8217;esplosione evidenziata da una gigantesca palla di fuoco. Il carburante rimanente fluiva verso i piani inferiori, alimentando gli incendi. Il calore degli incendi deformava le strutture degli edifici cos\u00ec che entrambe le torri sono crollate completamente da cima a fondo. Molto poco \u00e8 rimasto di quanto era di qualsiasi dimensione dopo questi eventi, a parte i frammenti in acciaio e in alluminio e i detriti polverizzati provenienti dai pavimenti in cemento. <strong>Anche<\/strong> <strong>l\u2019edificio 7 del World Trade Center<\/strong> <strong>croll\u00f2<\/strong>: lo fece in un modo che risultava <strong>in contrasto con l&#8217;esperienza comune degli ingegneri<\/strong>.<\/p>\n<p>Il rapporto finale del NIST ha affermato che gli attacchi aerei contro le torri gemelle erano la causa dei crolli per tutti e tre gli edifici: WTC1, WTC2 e WTC7.<\/p>\n<p>Tutti e tre gli edifici sono crollati completamente, ma l&#8217;edificio 7 non fu colpito da un aereo. Il crollo totale del WTC7 ha violato l&#8217;esperienza comune ed era senza precedenti.<\/p>\n<p>Il rapporto del NIST non analizza la reale natura dei crolli. Secondo gli esperti intervenuti nel corso delle Udienze di Toronto (<em>\u201cToronto Hearings\u201d<\/em>, 8-11 settembre 2011), i crolli avevano caratteristiche che indicano esplosioni controllate. Sono d&#8217;accordo con l\u2019architetto Richard Gage e l\u2019ingegnere Jon Cole, entrambi professionisti di grande esperienza, che sono arrivati alle loro conclusioni attraverso test affidabili, prove scientifiche, e la testimonianza visiva di persone insospettabili, tra cui i vigili del fuoco e le vittime.<\/p>\n<p>L&#8217;autorevole teologo David Ray Griffin ha descritto con grande precisione perch\u00e9 l&#8217;ipotesi di demolizione controllata dovrebbe essere presa in considerazione. Vari testimoni hanno sentito raffiche di esplosioni.<\/p>\n<p>Secondo il NIST il crollo dell&#8217;edificio 7 \u00e8 stato causato da incendi provocati dal crollo delle torri gemelle. Il chimico e ricercatore indipendente Kevin Ryan, tuttavia, ha dimostrato che il NIST ha dato versioni contraddittorie del crollo dell&#8217;edificio 7. In un rapporto preliminare del NIST dichiarava che il WTC7 fu distrutto a causa di incendi provocati da gasolio conservato nel palazzo, mentre in una seconda relazione questo combustibile non era pi\u00f9 considerato come la causa del crollo dell&#8217;edificio. Ulteriori commenti sulla versione degli eventi data dal NIST sono stati formulati da <strong>David Chandler<\/strong>, un altro testimone esperto intervenuto nel corso delle Udienze di Toronto. Nonostante la presunzione del NIST in merito a tre distinte fasi di crollo, Chandler ha sottolineato che molti video disponibili dimostrano che per circa due secondi e mezzo l&#8217;accelerazione dell\u2019edificio non pu\u00f2 essere distinta da una caduta libera. Il NIST \u00e8 stato costretto a concordare con con questo fatto empirico come sottolineato da Chandler, e ora comprensibile per chiunque.<\/p>\n<p><strong>Peter Dale Scott<\/strong>, un altro testimone alle Udienze di Toronto, ha dimostrato l&#8217;esistenza di un modello d\u2019azione sistematico della CIA volto a bloccare importanti informazioni nei confronti dell&#8217;FBI, anche quando l&#8217;FBI avrebbe normalmente diritto di ottenerle. Inoltre, ci sono ulteriori elementi di prova contro <strong>George Tenet<\/strong> e <strong>Tom Wilshire<\/strong>. Secondo l&#8217;ex capo dell\u2019antiterrorismo della Casa Bianca, <strong>Richard Clarke<\/strong> (intervista rilasciata alla televisione francese e tedesca come parte di un documentario di Fabrizio Calvi e Christopf Klotz ,31 agosto 2011, nonch\u00e9 <a href=\"http:\/\/www.dagospia.com\/rubrica-3\/politica\/1-diciotto-mesi-prima-della-strage-dell119-la-cia-era-sulle-tracce-di-due-29146.htm\"><strong>l&#8217;intervista con Calvi e Leo Sisti, &#8220;Il Fatto Quotidiano &#8220;, 30 agosto 2011<\/strong><\/a>) <em>la CIA era a conoscenza dell\u2019imminente attacco dell\u201911\/9<\/em>.<\/p>\n<p>Inoltre, dal 1999 la CIA aveva indagato <strong>Khalid al-Mihdhar<\/strong> e <strong>Nawaf al-Hamzi<\/strong>, entrambi sauditi, che sono stati associati con l&#8217;aereo della American Airlines che ha colpito il Pentagono. La CIA era stata informata che Khalid al-Mihdhar e Nawaf al-Hamzi erano arrivati negli Stati Uniti all&#8217;inizio del 2000. \u00c8 legittimo dedurre che Tenet, capo della CIA, e Wilshire, secondo Peter Dale Scott una &#8220;figura chiave&#8221; nella <a href=\"http:\/\/en.wikipedia.org\/wiki\/Bin_Laden_Issue_Station\"><strong>Alec Station<\/strong><\/a>, bloccarono gli sforzi di due agenti dell&#8217;FBI, Doug Miller e Mark Rossini, intesi a notificare al centro FBI che uno dei partecipanti alla riunione di Kuala Lumpur, al-Mihdhar, aveva ottenuto un <strong>visto USA attraverso il consolato degli Stati Uniti a Jeddah<\/strong>. Il professor Scott, basandosi sulla ricerca di Kevin Fenton, cita <strong>35 occasioni in cui i dirottatori sono stati protetti in questo modo<\/strong>, a partire dal gennaio del 2000 al 5 settembre 2001. Con riferimento al precedente di questi incidenti, il <strong>motivo di questa protezione<\/strong> era evidentemente, secondo Fenton, <strong>\u00abper coprire un&#8217;operazione della CIA che era gi\u00e0 in corso.\u00bb<\/strong><\/p>\n<p>Ulteriore prova indiziaria contro Tenet e Wilshire \u00e8 la seguente. Il 12 luglio 2001 Osama bin Laden si trovava nell\u2019ospedale americano di Dubai. Fu visitato da un agente della CIA. Questa informazione \u00e8 stata data a Le Figaro, che ha anche riferito che bin Laden era stato operato in questo ospedale, essendo arrivato da Quetta (Pakistan). Questa informazione \u00e8 stata confermata da Radio France International, che ha rivelato il nome dell&#8217;agente che ha incontrato bin Laden: <strong>Larry Mitchell<\/strong>. Tenet e Wilshire, consapevoli della presenza di bin Laden negli Emirati Arabi Uniti, non sono riusciti a farlo arrestare n\u00e9 estradare, anche se i documenti dell&#8217;FBI e della CIA lo ritenevano responsabile di massacri in Kenya e Tanzania.<\/p>\n<p>L&#8217;<em>insider<\/em> <em>trading<\/em> \u00e8 una forte ulteriore prova contro la CIA, l\u2019FBI e il governo degli Stati Uniti.<\/p>\n<p><a href=\"http:\/\/ithp.org\/articles\/septemberinsidertrading.html\"><strong>Gli articoli del professor <strong>Paul Zarembka<\/strong><\/strong><\/a>, cos\u00ec come da <strong>Kevin Ryan<\/strong> e altri, dimostrano che tali casi di <em>insider trading<\/em> hanno avuto luogo nei giorni immediatamente precedenti rispetto agli attentati. Eppure questi casi di <em>insider trading<\/em> sono stati negati dall&#8217;FBI e dalla Commissione d\u2019inchiesta sull\u201911\/9.<\/p>\n<p>Ulteriore prova contro la CIA e l&#8217;amministrazione degli Stati Uniti \u00e8 la seguente. <strong>Mohammed Atta<\/strong>, almeno a partire dal maggio 2000, era sotto sorveglianza della CIA in Germania, secondo la Commissione sull\u201911\/9, sia perch\u00e9 era accusato sin dal 1986 di attentati contro Israele, sia perch\u00e9 era stato sorpreso mentre acquistava grandi quantit\u00e0 di prodotti chimici per l&#8217;uso in esplosivi a Francoforte (<em>The Observer<\/em>, 30 settembre 2001). \u00c8 stato indagato dal servizio segreto egiziano e il suo telefono cellulare era sotto controllo. Nel novembre del 1999 Mohammed Atta lasci\u00f2 Amburgo, and\u00f2 a Karachi, in Pakistan, e poi a Kandahar. Qui ha incontrato bin Laden e lo sceicco Omar Saeed (secondo la rivista specializzata in questioni di sicurezza interna GlobalSecurity.org, alla voce &#8220;Movements of Mohammed Atta&#8221;). Dopo giugno 2000 gli USA hanno continuato a monitorare Atta, intercettando le sue conversazioni con <strong><a href=\"http:\/\/www.megachip.info\/finestre\/zero-11-settembre\/1190-il-processo-al-reo-confesso-che-annegava-sei-volte-al-giorno.html\">Khalid Sheikh Mohammed<\/a><\/strong>, considerato il regista del 9\/11, che ha vissuto in Pakistan.<\/p>\n<p>Una forte prova del fatto che <strong>la CIA era a conoscenza dei movimenti irregolari di Atta <\/strong>dagli Stati Uniti verso l&#8217;Europa e all\u2019interno degli Stati Uniti \u00e8 il documento declassificato della CIA inviato dall&#8217;Agenzia a G.W Bush (<em>President\u2019s Daily Brief<\/em> \u2013 Ndt: \u201crelazione breve giornaliera per il presidente\u201d). Questo documento, del 6 agosto 2001, dice: \u00abBin Laden determinato a colpire in USA.\u00bb E continua: &#8220;relazioni di provenienza clandestina, di governi stranieri, e dei media indicano che bin Laden sin dal 1997 ha voluto condurre attacchi terroristici negli Stati Uniti. Bin Laden ha inteso in interviste a televisioni statunitensi nel 1997 e nel 1998 che i suoi seguaci avrebbero seguito l&#8217;esempio dell\u2019attentatore del World Trade Center Ramzi Yousef, e avrebbero \u201cportato i combattimenti in America\u201d.\u00bb<\/p>\n<p>Dopo gli attacchi missilistici degli Stati Uniti sulla sua base in <strong>Afghanistan<\/strong> nel 1998, bin Laden disse ai seguaci che voleva infliggere una rappresaglia a danno di Washington, secondo un servizio di intelligence straniero. Un membro operativo egiziano della Jihad islamica ha rivelato a un agente di un servizio segreto straniero, nel frattempo, che bin Laden aveva intenzione di sfruttare l&#8217;accesso operativo agli Stati Uniti per organizzare un attacco terroristico &#8230;<\/p>\n<p>Una fonte clandestina ha affermato nel 1998, che una cellula di bin Laden a New York stava reclutando giovani musulmani americani per gli attentati.<\/p>\n<p>Questo documento dimostra che <strong>la CIA, l\u2019FBI, cos\u00ec come il presidente Bush, conoscevano gi\u00e0 dal 6 agosto 2001<\/strong> chi aveva un accesso operativo: <strong>Atta<\/strong>. Nessuno ha goduto di un tale accesso negli Stati Uniti quanto Atta. Ma la CIA, l\u2019FBI e Bush non hanno fatto nulla per fermarlo.<\/p>\n<p>In Italia ho raccolto prove che la guerra in Iraq \u00e8 stata decisa dal governo degli Stati Uniti prima degli attacchi dell&#8217;11\/9 con l&#8217;aiuto dei servizi segreti italiani. Secondo <strong>Michel Chossudovsky<\/strong>, gli attacchi dell&#8217;11\/9 sono stati usati come pretesto per la guerra, avendo avuto come sfondo i molti anni in cui si \u00e8 avuta la <strong>creazione e il sostegno<\/strong> <strong>da parte della CIA della rete terroristica ora conosciuta come <\/strong><strong>al-Qa\u2019ida<\/strong>. Oggi c&#8217;\u00e8 il pericolo di una nuova &#8220;guerra preventiva&#8221; contro l&#8217;Iran da parte degli Stati Uniti. Questo potrebbe essere terribile per la gente di tutto il mondo e potrebbe anche distruggere una gran parte dell&#8217;umanit\u00e0.<\/p>\n<p>L&#8217;unica possibilit\u00e0 per avere giustizia \u00e8 quello di presentare le migliori <strong>prove<\/strong> relative al <strong>coinvolgimento di singoli individui nei fatti dell\u201911\/9<\/strong> al Procuratore della <strong>Corte penale internazionale<\/strong> chiedendogli di indagare in base agli articoli 12, 13, 15 e 17, lettere a e b, dello Statuto della Corte penale internazionale, ricordando anche il preambolo della Statuto:<\/p>\n<ul>\n<li><em>Riconoscere che tali gravi reati minacciano la pace, la sicurezza e il benessere del mondo, <\/em><\/li>\n<li><em>Affermare che i reati pi\u00f9 gravi che sono motivo di allarme per la comunit\u00e0 internazionale nel suo insieme non debbano rimanere impuniti e che la loro repressione debba essere efficacemente garantita mediante provvedimenti adottati a livello nazionale ed attraverso il rafforzamento della cooperazione internazionale, <\/em><\/li>\n<li><em>Essere determinati a porre fine all&#8217;impunit\u00e0 degli autori di tali crimini e quindi di contribuire al perseguimento di tali reati, <\/em><\/li>\n<li><em>Ricordare il dovere di ogni Stato di esercitare la propria giurisdizione nei confronti dei responsabili di reati internazionali &#8230;<\/em><\/li>\n<\/ul>\n<p>Ferdinando Imposimato, settembre 2012.<\/p>\n<p><em>Fonte: <\/em><a href=\"http:\/\/www.journalof911studies.com\/resources\/2012-September---Imposimato-letter.pdf\"><strong>http:\/\/www.journalof911studies.com\/resources\/2012-September&#8212;Imposimato-letter.pdf<\/strong><\/a>.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/13\/a-undici-anni-di-distanza-avanza-la-verita\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/13\/a-undici-anni-di-distanza-avanza-la-verita\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>ITALIA SOTT&#8217;OCCHIO MONDO COL CANNOCCHIALE RUBRICA DI CONTRO &#8211; INFORMAZIONE A CURA DI BEPI ANGUILLA A 11 anni da quell&#8217;11 settembre: era Strategia della Tensione di Ferdinando Imposimato &#8211; 11\/09\/2012 Gli attentati dell&#8217;11\/9 sono stati un&#8217;operazione globale di terrorismo di Stato consentita dall&#8217;amministrazione degli USA, che sapeva gi\u00e0 dell\u2019azione ma \u00e8 rimasta intenzionalmente non reattiva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3926,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3924"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=3924"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3924\/revisions"}],"predecessor-version":[{"id":3928,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3924\/revisions\/3928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/3926"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=3924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=3924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=3924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}