{"id":3939,"date":"2012-09-17T14:58:23","date_gmt":"2012-09-17T14:58:23","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=3939"},"modified":"2012-09-17T14:59:06","modified_gmt":"2012-09-17T14:59:06","slug":"cassa-integrazione-in-esaurimento-715-su-agosto-2011","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/17\/cassa-integrazione-in-esaurimento-715-su-agosto-2011\/","title":{"rendered":"CASSA INTEGRAZIONE IN ESAURIMENTO. -71,5 % SU AGOSTO 2011"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><strong>Il grido di dolore del segretario della Uil Salvatore Giannetto<\/strong><\/p>\n<p style=\"text-align: left;\" align=\"center\"><strong>Riceviamo e volentieri pubblichiamo<\/strong><\/p>\n<p style=\"text-align: left;\" align=\"center\">Cresce l\u2019allarme-lavoro nel Salento. Dalla lettura dei dati Inps elaborati dall\u2019Ufficio Studi della Uil emerge che nella provincia di Lecce, rispetto ad agosto di un anno fa, il ricorso alla cassa integrazione ha sub\u00ecto complessivamente un calo del 71,5%, passando da un totale di 273.189 ore autorizzate in agosto 2011 a 77.888 nello stesso mese del 2012.<\/p>\n<p>La cassa in deroga, rappresenta il 77,3% delle ore complessivamente autorizzate nel mese. Incidenza che, a livello regionale, \u00e8 pari al 78,6. In particolare, le ore di Cig in deroga nella provincia di Lecce sono passate da 179.589 a 60.208 (-66,5% rispetto ad agosto 2011); la Cig straordinaria, da 93.600 a 17.680 (-81,1%). Una flessione che non attenua la preoccupazione del sindacato.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cE\u2019 un calo dovuto all\u2019ormai inesorabile avanzamento del fenomeno della chiusura delle nostre aziende e all&#8217;esaurimento, nella gran parte di esse, degli ammortizzatori sociali \u2013 spiega il segretario provinciale Uil, <strong>Salvatore Giannetto<\/strong> \u2013 Ne \u00e8 prova il fatto che, da dicembre, altri 5.500 lavoratori salentini resteranno senza assegno: andranno infatti a esaurimento gli ammortizzatori sociali per 700 operai dell\u2019Adelchi e per altri 1000 della Filanto; in scadenza, c&#8217;\u00e8 poi la cassa integrazione in deroga per 230 operai della Romano, per altri 2500 dipendenti delle piccole imprese del manifatturiero, per altri mille del settore meccanico. E non dimentichiamoci \u2013 ricorda &#8211; che dal 2001 ad oggi, nel Salento sono scomparsi complessivamente ben 12mila posti di lavoro solo nel tessile, abbigliamento e calzaturiero\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Anche rispetto al luglio scorso, le ore di Cig complessivamente autorizzate nel mese di agosto hanno registrato un calo: da 2.821.562 a 77.888 (-97,2%). In particolare, la Cig ordinaria \u00e8 passata da 324.131 ore autorizzate a luglio 2012 a zero in agosto; si \u00e8 registrato invece un aumento del ricorso alla Cig straordinaria, che da 2.528 ore autorizzate a luglio \u00e8 passata a 17.680 ore autorizzate in agosto (+599,4%); per la Cig in deroga, sempre un calo: da 2.494.903 a 60.208 (-97,2%).<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cSulla base di questi dati \u2013 osserva Giannetto &#8211; non sono pi\u00f9 rinviabili politiche, sostenute da adeguate risorse pubbliche, mirate alla crescita e alla buona occupazione: ridurre le tasse per lavoratori dipendenti e pensionati, contenere i costi della politica, garantire anche nel 2013 sufficienti risorse per gli ammortizzatori sociali, riaprire i canali del credito per le pmi, indirizzare le risorse nazionali ed europee verso il Sud per rafforzare in particolare il settore manifatturiero, l\u2019agricoltura, il turismo, il nuovo settore delle energie. Nel Salento la situazione \u00e8 allarmante: le proteste dei dipendenti della ex Manifattura Tabacchi e della Omfesa, in questi primi giorni di settembre, non sono nulla rispetto agli effetti che potrebbe provocare l&#8217;esplosione di questa &#8220;bomba ad orologeria&#8221; gi\u00e0 innescata. Sarebbe opportuno che la politica e le istituzioni locali, anzich\u00e9 rilasciare dichiarazioni soltanto quando le vertenze arrivano sotto la Prefettura, si muovessero e chiedessero al Governo interventi strutturali a sostegno della nostra economia. Si pone ormai \u2013 conclude\u00a0 &#8211; anche il tema di come si potr\u00e0 garantire, dal prossimo anno, una quota di reddito aggiuntiva a queste migliaia di lavoratori che potrebbero essere impegnate in attivit\u00e0 utili alla collettivit\u00e0, collegate ad un reale processo di riqualificazione professionale\u201d.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/17\/cassa-integrazione-in-esaurimento-715-su-agosto-2011\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/17\/cassa-integrazione-in-esaurimento-715-su-agosto-2011\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il grido di dolore del segretario della Uil Salvatore Giannetto Riceviamo e volentieri pubblichiamo Cresce l\u2019allarme-lavoro nel Salento. Dalla lettura dei dati Inps elaborati dall\u2019Ufficio Studi della Uil emerge che nella provincia di Lecce, rispetto ad agosto di un anno fa, il ricorso alla cassa integrazione ha sub\u00ecto complessivamente un calo del 71,5%, passando da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3940,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3939"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=3939"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3939\/revisions"}],"predecessor-version":[{"id":3942,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3939\/revisions\/3942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/3940"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=3939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=3939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=3939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}