{"id":3990,"date":"2012-09-20T14:57:06","date_gmt":"2012-09-20T14:57:06","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=3990"},"modified":"2012-09-29T09:04:05","modified_gmt":"2012-09-29T09:04:05","slug":"provincia-grande-salento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/20\/provincia-grande-salento\/","title":{"rendered":"PROVINCIA \u201cGRANDE SALENTO\u201d"},"content":{"rendered":"<h4>Dal dirigente del Pdl Roberto Tundo riceviamo e volentieri pubblichiamo.<\/h4>\n<p><em>\u201cIl Grande Salento potrebbe essere una Provincia, come lo \u00e8 stato nel passato, con la Terra d\u2019Otranto. Con un referendum, i cittadini salentini potrebbero scegliere il capoluogo.<\/em><\/p>\n<p><em><br \/>\nPer anni i vari presidenti che si sono succeduti alla guida delle Province di Lecce, Brindisi e Taranto hanno sostenuto che, per far decollare il Salento, sarebbe stato opportuno unire le forze delle tre province e programmare uno sviluppo comune e coerente del territorio.<br \/>\nSi sono tenuti tavoli di discussione e si \u00e8 coniato anche il suggestivo termine di Grande Salento, per dare una immagine forte, ad un progetto che aveva l\u2019ambizione di indirizzare e di gestire l\u2019utilizzo dei finanziamenti comunitari verso le infrastrutture necessarie allo sviluppo socio-economico.<\/em><\/p>\n<p>Poi, dopo tanto affanno, l\u2019iniziativa \u00e8 andata a scemare.<\/p>\n<p>Con la legge della spending review , quella che prevede la diminuzione del numero delle province italiane, il tema \u00e8 tornato di attualit\u00e0. La Provincia di Lecce conserva la propria autonomia perch\u00e9 ha un\u2019estensione di oltre 2.500 chilometri quadrati ed una popolazione superiore ai 350mila abitanti, mentre Taranto e Brindisi sono destinate a scomparire. Sia il sindaco di Lecce, Paolo Perrone, che il presidente della Provincia, Antonio Gabellone,si sono dichiarati favorevoli ad una provincia che aggreghi l\u2019intero Salento, la senatrice Adriana Poli aggiunge che con un referendum si potrebbe scegliere il capoluogo di una grande provincia salentina, che unisca Lecce, Brindisi e Taranto.<br \/>\nProposte di buon senso, lungimiranti, che tengono conto di un lungo dibattito politico che finalmente potrebbe trovare attuazione.<\/p>\n<p>Invece no.<\/p>\n<p>Ancora una volta stanno prevalendo (al di l\u00e0 di tanti buoni propositi) gli interessi particolari, quelli campanilistici. Taranto, che \u00e8 la citt\u00e0 pi\u00f9 popolosa, mira ad essere il capoluogo della nuova provincia, che sorger\u00e0 dalla fusione con Brindisi e non pensa affatto di unirsi con Lecce.<br \/>\nTutte le ragioni che per anni sono state formulate per la realizzazione del Grande Salento cedono il passo davanti alle piccole utilit\u00e0 (ad esempio, avere una sede della Prefettura) che essere capoluogo comporta.<br \/>\nNonostante siano riservati alle \u201cnuove\u201d province un ristretto campo di compiti e di mansioni, la logica prevalente \u00e8 quella che \u00e8 meglio gestire in proprio una piccola fetta di potere, piuttosto che partecipare alla costruzione di un progetto di grande respiro\u201d.<em><\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/20\/provincia-grande-salento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/20\/provincia-grande-salento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Dal dirigente del Pdl Roberto Tundo riceviamo e volentieri pubblichiamo. \u201cIl Grande Salento potrebbe essere una Provincia, come lo \u00e8 stato nel passato, con la Terra d\u2019Otranto. Con un referendum, i cittadini salentini potrebbero scegliere il capoluogo. Per anni i vari presidenti che si sono succeduti alla guida delle Province di Lecce, Brindisi e Taranto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3990"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=3990"}],"version-history":[{"count":8,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3990\/revisions"}],"predecessor-version":[{"id":4206,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/3990\/revisions\/4206"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=3990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=3990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=3990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}