{"id":39926,"date":"2014-11-27T19:20:57","date_gmt":"2014-11-27T18:20:57","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=39926"},"modified":"2014-11-27T19:22:42","modified_gmt":"2014-11-27T18:22:42","slug":"iniziative-trekking-fra-le-architetture-di-campagna-domenica-30","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/11\/27\/iniziative-trekking-fra-le-architetture-di-campagna-domenica-30\/","title":{"rendered":"INIZIATIVE \/ TREKKING DI CAMPAGNA DOMENICA 30"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/11\/ARCHITETTURE-DI-CAMPAGNA.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"600\" title=\"ARCHITETTURE DI CAMPAGNA\" class=\"alignleft size-full wp-image-39927\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/11\/ARCHITETTURE-DI-CAMPAGNA.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/11\/ARCHITETTURE-DI-CAMPAGNA.jpg 800w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/11\/ARCHITETTURE-DI-CAMPAGNA-300x225.jpg 300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>Lo studio ambientale &#8220;Avanguardie&#8221; organizza con le proprie guide ambientali e turistiche un trekking di circa 12 km,\u00a0domenica 30 novembre,\u00a0nel territorio del\u00a0comune di Nard\u00f2, localit\u00e0 Villaggio Resta-Vico-Lucia,\u00a0per camminare, rilassarsi e conoscere un territorio dove dominano diverse e variegate le architetture di campagna: dalla masseria, alla torre, dal castello alla chiesetta e poi muretti a secco, ulivi secolari e storie di porti e pesci fossili.<\/p>\n<p>NOTE: \u00e8 INDISPENSABILE abbigliamento idoneo ad un trekking in ambiente naturale. Pranzo al sacco a carico dei partecipanti.<\/p>\n<p>TEMPO PREVISTO: COPERTO<\/p>\n<p>PRANZO: AL SACCO<\/p>\n<p>RITROVO: ORE 09.30 presso la chiesetta di Villaggio Resta<\/p>\n<p>CONCLUSIONE PREVISTA: ORE 14.30<\/p>\n<p>Per informazioni: 349.3788738<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/11\/27\/iniziative-trekking-fra-le-architetture-di-campagna-domenica-30\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/11\/27\/iniziative-trekking-fra-le-architetture-di-campagna-domenica-30\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Lo studio ambientale &#8220;Avanguardie&#8221; organizza con le proprie guide ambientali e turistiche un trekking di circa 12 km,\u00a0domenica 30 novembre,\u00a0nel territorio del\u00a0comune di Nard\u00f2, localit\u00e0 Villaggio Resta-Vico-Lucia,\u00a0per camminare, rilassarsi e conoscere un territorio dove dominano diverse e variegate le architetture di campagna: dalla masseria, alla torre, dal castello alla chiesetta e poi muretti a secco, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":39927,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/39926"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=39926"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/39926\/revisions"}],"predecessor-version":[{"id":39931,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/39926\/revisions\/39931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/39927"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=39926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=39926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=39926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}