{"id":4016,"date":"2012-09-20T16:03:59","date_gmt":"2012-09-20T16:03:59","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=4016"},"modified":"2012-09-20T16:28:00","modified_gmt":"2012-09-20T16:28:00","slug":"alla-scoperta-dellitalia-di-serie-c-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/20\/alla-scoperta-dellitalia-di-serie-c-2\/","title":{"rendered":"ALLA SCOPERTA DELL\u2019ITALIA DI SERIE C"},"content":{"rendered":"<p><strong>TREVISO:\u00a0<\/strong><strong>23 SETTEMBRE 2012<\/strong><\/p>\n<p><strong>di Un italiano Vero<\/strong><\/p>\n<p>Dopo i Cunesi al rhum, il calendario porta a gustare il radicchio, la verdura rossa pregiata usata per il risotto, che con polenta e faraona sono i piatti tipici di Treviso.<\/p>\n<p>Poco sopra Venezia, ancora tutta quanta in pianura, fredda d\u2019inverno, senza caldo assillante d\u2019estate, per via dei canali che la percorrono per intero, Treviso ha una dimensione tipicamente provinciale, di quella provincia del ceto medio emergente negli anni Sessanta e Settanta, bonario e intraprendente, devoto quanto pettegolo.<\/p>\n<p>Se non di persona, l\u2019avrete vista senz\u2019altro in uno dei capolavori della commedia all\u2019italiana, \u201cSignore e signori\u201d, di Pietro Germi, che racconta dei pettegolezzi da bar e dei tradimenti extraconiugali che ne ravvivano la vita lenta e tranquilla.<\/p>\n<p>Tutta di bellezza rinascimentale, molti edifici storici restaurati, portici e, appunto, canali d\u2019acqua fluviale, con la piazza dei Signori centro unico e di gravit\u00e0 permanente.<\/p>\n<p>Siamo nel mitico Nord \u2013 est che nei decenni passati come un motore potente trainava l\u2019economia fatta di piccole imprese, per lo pi\u00f9 a conduzione famigliare, capaci di assicurare lavoro e sviluppo, e che pi\u00f9 di tutto in quelli pi\u00f9 recenti patisce la crisi della globalizzazione e delle tasse e imposte: non a caso Forza Italia e Lega Nord qui la fanno da padroni, anche se oggi devono fronteggiare uno scontento diffuso, e palpabile nella vita quotidiana, che preannuncia, qui pi\u00f9 che altrove, prossimi sconvolgimenti socio \u2013 economici, prima ancora che politici.<\/p>\n<p>Al calcio a Treviso sono disaffezionati ormai, dopo una breve stagione che fece conoscere addirittura la serie A, salvo poi fallimenti sportivi e amministrativi, che portarono la squadra, in lenta risalita nelle ultime due stagioni, addirittura in serie D.<\/p>\n<p>Lo stadio piccolo, anche se adeguato alle nuove norme, ha un nome impossibile, dedicato a un pilota motociclista di origini locali, anche se lombardo d\u2019adozione, Omobono Tenni, famoso nella prima met\u00e0 del Novecento.<\/p>\n<p>Una visita completa all\u2019intera citt\u00e0 si fa in un paio d\u2019ore, comunque c\u2019\u00e8 poco da capire, e da ricordare.<\/p>\n<p>( 2 \u2013 continua \u2013 il precedente articolo \u00e8 stato pubblicato per il 9 settembre )<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/20\/alla-scoperta-dellitalia-di-serie-c-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/09\/20\/alla-scoperta-dellitalia-di-serie-c-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>TREVISO:\u00a023 SETTEMBRE 2012 di Un italiano Vero Dopo i Cunesi al rhum, il calendario porta a gustare il radicchio, la verdura rossa pregiata usata per il risotto, che con polenta e faraona sono i piatti tipici di Treviso. Poco sopra Venezia, ancora tutta quanta in pianura, fredda d\u2019inverno, senza caldo assillante d\u2019estate, per via dei [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4020,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[56],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4016"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=4016"}],"version-history":[{"count":11,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4016\/revisions"}],"predecessor-version":[{"id":4019,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/4016\/revisions\/4019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/4020"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=4016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=4016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=4016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}