{"id":40297,"date":"2014-12-03T16:15:44","date_gmt":"2014-12-03T15:15:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=40297"},"modified":"2014-12-03T18:48:53","modified_gmt":"2014-12-03T17:48:53","slug":"da-compagni-di-lotta-a-compagni-in-lotta","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/03\/da-compagni-di-lotta-a-compagni-in-lotta\/","title":{"rendered":"FORESIO DIFENDE LA BELLANOVA E ATTACCA LA CAMUSSO \/ DA COMPAGNI DI LOTTA A COMPAGNI IN LOTTA"},"content":{"rendered":"<div>\n<div><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/bellanova-foresio1.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"946\" title=\"bellanova - foresio\" class=\"alignleft size-full wp-image-40299\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/bellanova-foresio1.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/bellanova-foresio1.jpg 800w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/bellanova-foresio1-253x300.jpg 253w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>Paolo Foresio scrive: &#8220;Le dichiarazioni della segretaria generale del Cgil Susanna Camusso, ieri a Lecce, contro la sottosegretaria al Lavoro Teresa Bellanova sono gravi e fuoriluogo. Mi auguro che siano state travisate: la Bellanova, infatti, rappresenta per questo territorio una risorsa e un punto di riferimento, come testimoniano la sua storia personale, il suo impegno costante e la sua onest\u00e0 riconosciuta.\u00a0<\/strong><\/div>\n<div><strong>Cosa dovrebbe rendere conto alla sua coscienza e agli elettori? Lo sforzo sulle tante vertenze di lavoro che il governo sta risolvendo con successo proprio grazie alla mediazione della sottosegretaria salentina o quello sul Jobs Act, una legge che prova a rilanciare un mercato del lavoro a dir poco stagnante con una disoccupazione giovanile ai massimi storici?\u00a0<\/strong><\/div>\n<div><strong>Altro che tradimento, quindi. Mi pare che la Bellanova al governo si stia confermando la personalit\u00e0 di grande spessore politico che abbiamo avuto modo di apprezzare qui nel Salento&#8221;.<\/strong><\/div>\n<\/div>\n<div><\/div>\n<div>\n<div><strong><em><br \/>\n<\/em><\/strong><\/div>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/03\/da-compagni-di-lotta-a-compagni-in-lotta\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/03\/da-compagni-di-lotta-a-compagni-in-lotta\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Paolo Foresio scrive: &#8220;Le dichiarazioni della segretaria generale del Cgil Susanna Camusso, ieri a Lecce, contro la sottosegretaria al Lavoro Teresa Bellanova sono gravi e fuoriluogo. Mi auguro che siano state travisate: la Bellanova, infatti, rappresenta per questo territorio una risorsa e un punto di riferimento, come testimoniano la sua storia personale, il suo impegno [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":40299,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40297"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=40297"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40297\/revisions"}],"predecessor-version":[{"id":40301,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40297\/revisions\/40301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/40299"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=40297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=40297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=40297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}