{"id":40405,"date":"2014-12-04T18:29:12","date_gmt":"2014-12-04T17:29:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=40405"},"modified":"2014-12-05T08:17:10","modified_gmt":"2014-12-05T07:17:10","slug":"40405","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/04\/40405\/","title":{"rendered":"&#8220;IL DERBY PUGLIESE&#8221; : ECCO COME IL LECCE SI PRESENTA ALLA TRASFERTA DI FOGGIA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/foto-1.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"190\" height=\"240\" title=\"foto 1\" class=\"alignleft  wp-image-40411\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/foto-1-237x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/foto-1-237x300.jpg 237w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/foto-1.jpg 713w\" sizes=\"(max-width: 190px) 100vw, 190px\" \/><\/a><\/p>\n<p>di <strong>Laura Ricci<\/strong>________<\/p>\n<p>L&#8217;ambiente giallorosso si prepara a un nuovo capitolo di questo campionato di Lega Pro avvincente e molto equilibrato.<\/p>\n<p>Il <strong>Lecce<\/strong> con trentuno punti conquistati in quindici incontri, si \u00e8 portato a meno tre dalla <strong>Salernitana<\/strong> che guida la classifica con trentaquattro punti. I ragazzi di <strong>Lerda<\/strong> dovranno proseguire sulla scia positiva di questo momento prolifico della squadra e saranno chiamati alla vittoria in un <strong>&#8220;derby pugliese&#8221;<\/strong> contro il <strong>Foggia<\/strong>. Domani alle 20.45 allo<strong> stadio Pino Zaccheria<\/strong> il tecnico salentino potr\u00e0 contare non solo sul ritorno di <strong>Filipe Gomez<\/strong> che aveva saltato una giornata a causa dell&#8217;espulsione rimediata contro il <strong>Benevento<\/strong>, ma anche sul recupero di <strong>Mariano Bogliacino<\/strong> che sta man mano riprendendo il ritmo agonistico dopo un periodo tormentato da una serie di infortuni. Il centrocampista giallorosso fa ben sperare vista anche la rete trovata nello spezzone del finale di partita dopo pochi minuti dal suo ingresso. All&#8217;appello per\u00f2 mancheranno <strong>Walter Lopez<\/strong>, ammonito durante la gara contro il<strong> Melfi<\/strong> nella quale era diffidato, i lungodegenti <strong>Sacilotto, Diniz<\/strong> e <strong>D&#8217;Ambrosio<\/strong> ai quali si aggiunge <strong>Fabrizio Miccoli<\/strong> che pare abbia degli acciacchi fisici che lo tengono ormai fuori dal campo da lungo tempo. Le voci di un&#8217;eventuale frattura fra il giocatore salentino e Lerda sono state pi\u00f9 volte ufficialmente smentite, la situazione rimane per\u00f2 poco chiara.<\/p>\n<p><strong>L&#8217;avversario<\/strong>, il <strong>Foggia<\/strong> di <strong>Roberto De Zerbi<\/strong>, proviene da un trascorso burrascoso. Nonostante un passato per certi versi glorioso grazie alla guida di <strong>Zeman<\/strong> che nel 1991 ha portato la squadra in<strong> Serie A<\/strong> e poi nel 1994 a due passi dall&#8217; accesso in <strong>Coppa Uefa<\/strong>, alla fine della stagione 2011-12 la dirigenza dell&#8221; <strong>Unione Sportiva Foggia<\/strong> decise di non iscrivere la squadra alla prima divisione di Lega Pro nella quale militava da diversi anni. Dopo i tentativi di vendere la societ\u00e0\u00a0non andati a buon fine, l&#8217; <strong>Us Foggia<\/strong> ha disputato il campionato di terza categoria per poi essere dichiarata fallita dal Tribunale di Foggia. A dare un proseguo alle gesta dei foggiani \u00e8 stata l&#8217;<strong>Associazione Calcio Dilettantistica Foggia Calcio<\/strong>, poi rinominata in <strong>&#8220;Foggia Calcio S.r.l&#8221;<\/strong> nella stagione 2012-13, che nel 2013 ha ottenuto l&#8217;accesso alla Lega Pro di seconda divisione e poi al <strong>girone C di Lega Pro<\/strong> <strong>unica<\/strong> in questa stagione. I rossoneri vantano un rullino di marcia di tutto rispetto: come il Lecce, risultano fin&#8217;ora imbattuti in casa e con sei vittorie, otto pareggi e una sola sconfitta sono al sesto posto a quota venticinque punti.<\/p>\n<p><strong>La citt\u00e0: <\/strong>con 152.961 abitanti, Foggia \u00e8 il terzo comune per popolazione della regione e l&#8217;ottavo per superficie in Italia. Una citt\u00e0 grossa e popolata, che vive peggio di altre la crisi economica di adesso, che l&#8217;ha privata delle tradizionali risorse provenienti dall&#8217;agricoltura e dal commercio, e le contraddizioni del Meridione d&#8217; Italia di sempre.<\/p>\n<p>Ogni incontro per il <strong>Lecce<\/strong> \u00e8 determinante per il cammino verso la vetta della classifica, la squadra dovr\u00e0 dare seguito alle buone prestazioni messe in mostra fin&#8217;ora e &#8220;non lasciare punti per strada&#8221;.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/04\/40405\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/04\/40405\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Laura Ricci________ L&#8217;ambiente giallorosso si prepara a un nuovo capitolo di questo campionato di Lega Pro avvincente e molto equilibrato. Il Lecce con trentuno punti conquistati in quindici incontri, si \u00e8 portato a meno tre dalla Salernitana che guida la classifica con trentaquattro punti. I ragazzi di Lerda dovranno proseguire sulla scia positiva di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40405"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=40405"}],"version-history":[{"count":12,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40405\/revisions"}],"predecessor-version":[{"id":40425,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40405\/revisions\/40425"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=40405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=40405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=40405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}