{"id":40477,"date":"2014-12-05T15:37:35","date_gmt":"2014-12-05T14:37:35","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=40477"},"modified":"2014-12-06T12:52:02","modified_gmt":"2014-12-06T11:52:02","slug":"torte-vegan-in-gara-a-cutrofiano-domenica-14-lindirizzo-di-posta-elettronica-da-utilizzare-per-prenotarsi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/05\/torte-vegan-in-gara-a-cutrofiano-domenica-14-lindirizzo-di-posta-elettronica-da-utilizzare-per-prenotarsi\/","title":{"rendered":"DOLCI VEGAN IN GARA A CUTROFIANO DOMENICA 14 &#8211; LA MAIL DA UTILIZZARE PER PRENOTARSI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/1-gara-dolci-veg-1-copia.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"212\" title=\"1 gara dolci veg-1 copia\" class=\"alignleft size-medium wp-image-40530\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/1-gara-dolci-veg-1-copia-300x212.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/1-gara-dolci-veg-1-copia-300x212.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/1-gara-dolci-veg-1-copia-1024x724.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Il 14 Dicembre a Cutrofiano ci sar\u00e0 la prima Gara di Dolci Vegan del Salento. Pasticceri e&#8230;pasticcioni vegani si sfideranno a colpi di panna di soia e ingredienti vegetali fino all\u2019ultima fetta.<\/p>\n<p>Lo scopo \u00e8\u00a0diffondere l&#8217;alimentazione Vegan,\u00a0in un momento di divertimento, senza competizione vera e propria, ma con lo spirito del gioco.<\/p>\n<p>Gli organizzatori ci mandano il seguente comunicato che volentieri pubblichiamo, per invitare alla partecipazione alla manifestazione e quindi alla conoscenza del loro metodo, che, come \u00e8 noto,\u00a0esclude l&#8217;utilizzo di alimenti di origine animale______<\/p>\n<p>&#8220;<em>Potranno partecipare infatti solo pasticceri non professionisti e la giuria sar\u00e0 composta sia dal pubblico che ricever\u00e0 una scheda per votare il dolce preferito dopo averli assaggiati tutti, che dai cuochi stessi (che potranno votare i dolci degli altri concorrenti ma non il proprio).\u00a0<\/em><\/p>\n<p><em>I premi sono divisi in due categorie, \u201cDolce pi\u00f9 buono\u201d e \u201cDolce pi\u00f9 bello\u201d . Quest\u2019ultimo ricever\u00e0 un premio a sorpresa offerto da \u201cErboristeria la Calendula\u201d di Cutrofiano mentre, per la categoria Dolce pi\u00f9 buono, i concorrenti che prenderanno pi\u00f9 voti si aggiudicheranno 3 premi offerti dai partner dell\u2019evento: \u201cAgriostello Piccapane\u201d di Cutrofiano, \u201cCooperativa Bio Amrita\u201d di Scorrano e \u201cCaffetteria Mondoni Vegano \u201d di Lecce.\u00a0<\/em><\/p>\n<p><em>La struttura ospiter\u00e0 un\u2019esposizione di Mandala a cura di Atitlan (Prem Chandana e Anando Khrishan) ed un mercatino artigianale che si potr\u00e0 visitare anche dopo la fine della gara insieme alla degustazione di the ed altri dolci offerti dagli organizzatori.\u00a0<\/em><\/p>\n<p><em>L\u2019evento \u00e8 stato organizzato da LecceVegan, Sara Cacciatore e Melania Sabato con l\u2019idea di diffondere la cultura Vegan nel nostro territorio e mostrare con un evento gioioso come questo\u00a0che \u201cdiverso \u00e8 possibile\u201d.\u00a0\u00a0<\/em><\/p>\n<p><em>Concorreranno dolci buonissimi che non prevedono l\u2019utilizzo di ingredienti di origine animale, senza contribuire, cos\u00ec, al crudele sfruttamento delle mucche per il latte o allo sterminio di cui sono vittime migliaia di pulcini nell\u2019industria delle uova.\u00a0<\/em><\/p>\n<p><em>E\u2019 ormai riconosciuto dai pi\u00f9 grandi esperti e ricercatori come T.Colin Campbell (autore di The China Study ) e Franco Berrino (Direttore del Dipartimento di medicina preventiva e predittiva presso l\u2019Istituto Nazionale dei Tumori di Milano ) che una dieta priva di ingredienti di origine animale \u00e8 l\u2019unica dieta che permette di preservarsi da malattie gravi, di farle regredire se si \u00e8 gi\u00e0 ammalati e di garantire una salute forte ed una maggiore longevit\u00e0.\u00a0\u00a0<\/em><\/p>\n<p><em>La Gara di Dolci Vegan sar\u00e0 un evento divertente ed eticamente attento al rispetto degli animali, dell\u2019ambiente ed alla nostra salute.\u00a0<\/em><\/p>\n<p><em>Gli organizzatori vi aspettano alle 16.30 presso il Laboratorio Urbano Sottomondo (ex mercato coperto di Cutrofiano) in via Milite Ignoto.\u00a0<\/em><\/p>\n<p><em>Per informazioni, iscrizioni e per il regolamento completo inviare una mail all\u2019indirizzo <a href=\"mailto:sara.cacciatored@gmail.com\">sara.cacciatored@gmail.com<\/a>\u00a0<\/em><\/p>\n<p><em>Tel: 3204863688 \u2013 3293845754&#8243;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/05\/torte-vegan-in-gara-a-cutrofiano-domenica-14-lindirizzo-di-posta-elettronica-da-utilizzare-per-prenotarsi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/05\/torte-vegan-in-gara-a-cutrofiano-domenica-14-lindirizzo-di-posta-elettronica-da-utilizzare-per-prenotarsi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il 14 Dicembre a Cutrofiano ci sar\u00e0 la prima Gara di Dolci Vegan del Salento. Pasticceri e&#8230;pasticcioni vegani si sfideranno a colpi di panna di soia e ingredienti vegetali fino all\u2019ultima fetta. Lo scopo \u00e8\u00a0diffondere l&#8217;alimentazione Vegan,\u00a0in un momento di divertimento, senza competizione vera e propria, ma con lo spirito del gioco. Gli organizzatori ci [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":40530,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40477"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=40477"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40477\/revisions"}],"predecessor-version":[{"id":40480,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40477\/revisions\/40480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/40530"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=40477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=40477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=40477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}