{"id":40501,"date":"2014-12-05T23:13:22","date_gmt":"2014-12-05T22:13:22","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=40501"},"modified":"2014-12-06T13:02:42","modified_gmt":"2014-12-06T12:02:42","slug":"lecce-rammarico-nel-derby-pugliese-brusca-frenata-contro-un-foggia-coraggioso-e-inaspettato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/05\/lecce-rammarico-nel-derby-pugliese-brusca-frenata-contro-un-foggia-coraggioso-e-inaspettato\/","title":{"rendered":"LECCE, DERBY PUGLIESE AMARO: BRUSCO STOP CONTRO UN FOGGIA CORAGGIOSO E MOTIVATO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/foto-5.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"270\" height=\"270\" title=\"foto (5)\" class=\"alignleft  wp-image-40504\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/foto-5-300x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/foto-5-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/foto-5-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/foto-5.jpg 666w\" sizes=\"(max-width: 270px) 100vw, 270px\" \/><\/a>di <strong>Laura Ricci<\/strong>_______<\/p>\n<p>Nell&#8217; anticipo della\u00a0sedicesima giornata di campionato il Lecce ha l&#8217;occasione di allungare la serie positiva e di confermare il buon momento della squadra. Allo stadio Pino Zaccheria gli uomini di Lerda vengono per\u00f2\u00a0battuti da un Foggia incisivo e senza timore.<\/p>\n<p><strong>La cronaca.<\/strong><\/p>\n<p>Il Lecce scende in campo con Caglioni, Mannini, Donida, Papini, Martinez, Abruzzese, Filipe Gomes, Salvi, Carrozza, Moscardelli e Doumbia.<\/p>\n<p>Mister De Zerbi schiera per il Foggia Narciso, Loiacono, Agostinone, Agnelli, Potenza, Gigliotti, D&#8217;Allocco, Sainz-Maza, Iemmello, Cavallaro e Sarno.<\/p>\n<p>La prima fase del match \u00e8 dominata dalle azioni offensive e dalle continue iniziative dei padroni di casa, che senza paura organizzano e gestiscono il gioco. Il Lecce, nonostante sia messo alle strette dalle percussioni del Foggia, riesce a sfruttare la superiorit\u00e0 tecnica dei propri giocatori: gli uomini di Lerda mettono in difficolt\u00e0 la retroguardia foggiana con Carrozza, che per\u00f2, una volta giunto in area di rigore,\u00a0 si fa sfilare il pallone.<\/p>\n<p>I rossoneri non si lasciano intimidire e tentano l&#8217;imbucata prima con Iemmello fermato da Donida al momento del tiro, e poi con Maza che scalda i guantoni del portiere del Lecce bravo a respingere la conclusione. Il ritmo del match rimane sostenuto, le due squadre si affrontano a viso aperto e il Lecce sfiora la rete del vantaggio con Moscardelli che, servito da Carrozza, colpisce in pieno la traversa. Il numero dieci giallorosso si conferma il pi\u00f9 pericoloso in campo e fa tremare nuovamente Narciso al 38&#8242; con un rasoterra che si spegne di poco al lato e ancora al 42&#8242; con un bel tiro volo deviato dal numero uno del Foggia. Nonostante il buon ritmo e le diverse occasioni da goal sopratutto per il Lecce, i primi quarantacinque minuti terminano a reti inviolate.<\/p>\n<p>Nella seconda frazione di gioco i ritmi calano notevolmente, Lecce e Foggia riprendono a studiarsi e le occasioni da goal scarseggiano a dispetto di un primo tempo vivace e ricco di emozioni. Al nono minuto Iemmello, il migliore dei suoi, alza un campanile dal limite dell&#8217;area di rigore giallorossa senza riuscire a trovare lo specchio della porta. Al 14&#8242; Papini si rende protagonista di un tiro potente e veloce, insidioso ma poco preciso;\u00a0 i salentini ci riprovano con Moscardelli, che, divincolandosi da tre avversari, permette a Salvi di tentare la conclusione poi deviata in calcio d&#8217;angolo. Dopo il buon momento del Lecce, il Foggia si riporta in avanti e costringe Papini a un intervento tempestivo che salva i giallorossi; pochi secondi dopo i rossoneri impensieriscono nuovamente la squadra ospite con un tiro-cross su calcio d&#8217;angolo poi deviato da Caglioni.<\/p>\n<p>L&#8217;entusiasmo foggiano non si spegne nemmeno a fine partita e proprio al 45&#8242; Sarno beffa il portiere giallorosso su calcio di punzione magistralmente battuto. Allo scadere della partita, ancora Sarno chiude definitivamente i conti: prima ipnotizza Mannini e poi trafigge l&#8217;estremo difensore salentino.<\/p>\n<p><strong>Il giudizio: <\/strong>l&#8217; insidia dell&#8217;incontro era ben nota ai giocatori del Lecce. Il Foggia ha dimostrato di essere una vera squadra e di non farsi condizionare dall&#8217;avversario che si ritrova di fronte. I giallorossi hanno adottato una tattica troppo &#8220;guardinga&#8221;: aspettare i foggiani per poi ripartire non ha dato i suoi frutti.<\/p>\n<p>Il migliore in campo: prestazione maiuscola di Moscardelli che ci prova e ci riprova, prima di destro e poi di sinistro. Il numero dieci leccese \u00e8 stato il protagonista delle azioni pi\u00f9 pericolose per i giallorossi, sempre una spina nel fianco della difesa del Foggia.<\/p>\n<p><strong>Da ricordare:<\/strong>\u00a0ogni incontro \u00e8 illuminato da una conclusione o da una giocata del bomber Moscardelli che oggi non ha centrato il bersaglio ma \u00e8 stato protagonista di un bel tiro dalla distanza che si \u00e8 spento sulla traversa.<\/p>\n<p><strong>L&#8217;arbitraggio: <\/strong>la direzione dell&#8217;incontro affidata al signor <strong>Carmine di Ruberto<\/strong> di <strong>Nocera Inferiore<\/strong>, affiancato da<strong> Oreste Muto di Torre Annunziata<\/strong> e<strong> Matteo Benedettino di Bologna<\/strong>, \u00e8 stata macchiata dai troppi falli fischiati che hanno frammentato l&#8217;incontro.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/05\/lecce-rammarico-nel-derby-pugliese-brusca-frenata-contro-un-foggia-coraggioso-e-inaspettato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/05\/lecce-rammarico-nel-derby-pugliese-brusca-frenata-contro-un-foggia-coraggioso-e-inaspettato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Laura Ricci_______ Nell&#8217; anticipo della\u00a0sedicesima giornata di campionato il Lecce ha l&#8217;occasione di allungare la serie positiva e di confermare il buon momento della squadra. Allo stadio Pino Zaccheria gli uomini di Lerda vengono per\u00f2\u00a0battuti da un Foggia incisivo e senza timore. La cronaca. Il Lecce scende in campo con Caglioni, Mannini, Donida, Papini, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40501"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=40501"}],"version-history":[{"count":12,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40501\/revisions"}],"predecessor-version":[{"id":40534,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40501\/revisions\/40534"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=40501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=40501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=40501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}