{"id":40775,"date":"2014-12-09T09:26:58","date_gmt":"2014-12-09T08:26:58","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=40775"},"modified":"2014-12-09T09:26:58","modified_gmt":"2014-12-09T08:26:58","slug":"incidente-stradale-sulla-maglie-collepasso-muore-un-anziano-di-78-anni","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/09\/incidente-stradale-sulla-maglie-collepasso-muore-un-anziano-di-78-anni\/","title":{"rendered":"INCIDENTE STRADALE SULLA MAGLIE &#8211; COLLEPASSO, MUORE UN ANZIANO DI 78 ANNI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/images2.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"271\" height=\"186\" title=\"images\" class=\"alignright size-full wp-image-40776\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/images2.jpg\" \/><\/a>(t.l.)______La festivit\u00e0 dell&#8217; Immacolata \u00e8 stata funestata da un tragico incidente stradale, ancora morti sulla strade del Salento. Ieri pomeriggio, in un terribile &#8220;frontale&#8221;, ha perso la vita Luigi Montagna, 78 anni, di Collepasso, alla guida della sua utilitaria sulla strada per Maglie. Feriti due giovani che viaggiavano sull&#8217;altra auto coinvolta. Carabinieri, vigili del fuoco e personale sanitario sono prontamente accorsi per tutti gli interventi e i rilievi del caso.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/09\/incidente-stradale-sulla-maglie-collepasso-muore-un-anziano-di-78-anni\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/09\/incidente-stradale-sulla-maglie-collepasso-muore-un-anziano-di-78-anni\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)______La festivit\u00e0 dell&#8217; Immacolata \u00e8 stata funestata da un tragico incidente stradale, ancora morti sulla strade del Salento. Ieri pomeriggio, in un terribile &#8220;frontale&#8221;, ha perso la vita Luigi Montagna, 78 anni, di Collepasso, alla guida della sua utilitaria sulla strada per Maglie. Feriti due giovani che viaggiavano sull&#8217;altra auto coinvolta. Carabinieri, vigili del fuoco [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":40776,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40775"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=40775"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40775\/revisions"}],"predecessor-version":[{"id":40777,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40775\/revisions\/40777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/40776"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=40775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=40775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=40775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}