{"id":40838,"date":"2014-12-10T12:22:17","date_gmt":"2014-12-10T11:22:17","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=40838"},"modified":"2014-12-10T12:22:17","modified_gmt":"2014-12-10T11:22:17","slug":"musica-il-dj-salentino-enea-yard-nei-locali-svedesi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/10\/musica-il-dj-salentino-enea-yard-nei-locali-svedesi\/","title":{"rendered":"MUSICA \/ IL DJ SALENTINO ENEA YARD NEI LOCALI SVEDESI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/enea-yard-foto-official.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"696\" title=\"enea yard foto official\" class=\"alignright size-full wp-image-40839\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/enea-yard-foto-official.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/enea-yard-foto-official.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/enea-yard-foto-official-300x217.jpg 300w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a>(p.s.)______Il giovane dj salentino\u00a0Enea Mazzotta, in arte Enea Yard (nella foto), specializzato nel genere house, \u00e8 a Stoccolma, prima tappa di una tourne\u00e9\u00a0di alcuni giorni in locali svedesi, col suo progetto &#8220;you&#8217;re my energy&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/10\/musica-il-dj-salentino-enea-yard-nei-locali-svedesi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/10\/musica-il-dj-salentino-enea-yard-nei-locali-svedesi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(p.s.)______Il giovane dj salentino\u00a0Enea Mazzotta, in arte Enea Yard (nella foto), specializzato nel genere house, \u00e8 a Stoccolma, prima tappa di una tourne\u00e9\u00a0di alcuni giorni in locali svedesi, col suo progetto &#8220;you&#8217;re my energy&#8221;. &nbsp; &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":40839,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40838"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=40838"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40838\/revisions"}],"predecessor-version":[{"id":40841,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40838\/revisions\/40841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/40839"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=40838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=40838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=40838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}