{"id":40877,"date":"2014-12-10T19:13:44","date_gmt":"2014-12-10T18:13:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=40877"},"modified":"2014-12-10T19:13:44","modified_gmt":"2014-12-10T18:13:44","slug":"minorenne-originario-del-gambia-arrestato-per-furto-in-una-comunita-di-tricase","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/10\/minorenne-originario-del-gambia-arrestato-per-furto-in-una-comunita-di-tricase\/","title":{"rendered":"MINORENNE ORIGINARIO DEL GAMBIA ARRESTATO PER FURTO IN UNA COMUNITA&#8217; DI TRICASE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/images2CXT7HM4.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"290\" height=\"174\" title=\"images2CXT7HM4\" class=\"alignright size-full wp-image-40878\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/images2CXT7HM4.jpg\" \/><\/a>(t.l.)______Nella serata di ieri\u00a0i Carabinieri di Tricase hanno arrestato per rapina un\u00a0ragazzo proveniente dal Gambia di diciassette anni, colto\u00a0in flagranza\u00a0reato.<\/p>\n<p>Il giovane era ospite della casa famiglia \u201cGli Angeli\u201d di Tricase, in regime di residenzialit\u00e0 per richiesta di asilo.<\/p>\n<p>Gi\u00e0 nei giorni passati\u00a0 era stato protagonista di alcuni episodi di violenza all\u2019interno della struttura, tant\u2019\u00e8 che gli operatori avevano richiesto alla Stazione Carabinieri di effettuare una vigilanza\u00a0particolare nelle ore serali, quando il centro \u00e8 affidato a pochi operatori.<\/p>\n<p>Ieri il ragazzo, non si sa bene per quale motivo, dopo aver visto un\u2019operatrice intenta a maneggiare il proprio cellulare (nella foto d&#8217;archivio, un&#8217;immagine di repertorio), la aggrediva cercando di strapparglielo di mano e nonostante l\u2019attiva resistenza da parte della donna, riusciva a portarglielo via.<\/p>\n<p>Immediatamente alcuni operatori cercavano di bloccare il minore, ma tempestivamente giungevano anche i\u00a0Carabinieri allertati tramite il 112.\u00a0 Il minore veniva bloccato e tratto in arresto, il cellulare recuperato\u00a0e riconsegnato alla legittima proprietaria.<\/p>\n<p>Dei fatti veniva dato avviso al sostituto procuratore\u00a0 Imerio Tramis della Procura dei minori, che disponeva l\u2019accompagnamento del soggetto al Centro di Prima Accoglienza \u00a0di Monteroni. L&#8217;operatrice \u00a0veniva invece soccorsa da sanitari del 118 che le diagnosticavano lesioni alla mano destra giudicate guaribili in tre\u00a0giorni.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/10\/minorenne-originario-del-gambia-arrestato-per-furto-in-una-comunita-di-tricase\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/10\/minorenne-originario-del-gambia-arrestato-per-furto-in-una-comunita-di-tricase\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)______Nella serata di ieri\u00a0i Carabinieri di Tricase hanno arrestato per rapina un\u00a0ragazzo proveniente dal Gambia di diciassette anni, colto\u00a0in flagranza\u00a0reato. Il giovane era ospite della casa famiglia \u201cGli Angeli\u201d di Tricase, in regime di residenzialit\u00e0 per richiesta di asilo. Gi\u00e0 nei giorni passati\u00a0 era stato protagonista di alcuni episodi di violenza all\u2019interno della struttura, tant\u2019\u00e8 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":40878,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40877"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=40877"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40877\/revisions"}],"predecessor-version":[{"id":40880,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/40877\/revisions\/40880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/40878"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=40877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=40877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=40877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}