{"id":41025,"date":"2014-12-12T18:38:28","date_gmt":"2014-12-12T17:38:28","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=41025"},"modified":"2014-12-12T18:40:19","modified_gmt":"2014-12-12T17:40:19","slug":"due-docenti-universitari-leccesi-protgonisti-di-un-progetto-scientifico-internazionale-per-i-bambini-che-si-spostano-da-un-paese-allaltro","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/12\/due-docenti-universitari-leccesi-protgonisti-di-un-progetto-scientifico-internazionale-per-i-bambini-che-si-spostano-da-un-paese-allaltro\/","title":{"rendered":"DUE DOCENTI UNIVERSITARI LECCESI PROTAGONISTI DI UN PROGETTO SCIENTIFICO INTERNAZIONALE PER I BAMBINI AMMALATI CHE SI SPOSTANO DA UN PAESE ALL&#8217;ALTRO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/marco-mancarella.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"225\" height=\"300\" title=\"marco mancarella\" class=\"alignright size-medium wp-image-41026\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/marco-mancarella-225x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/marco-mancarella-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/marco-mancarella.jpg 450w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>(c.m.)______Il sito-progetto \u201cTranslators for children\u201d, in sigla T4C, al quale hanno aderito gratuitamente 85 nazioni, 700 interpreti e traduttori, 68 pediatri specializzati di tutto il mondo, \u00e8 nato con il compito di tradurre le cartelle cliniche dei bambini che devono sottoporsi ad intervento chirurgico in altri Paesi.<\/p>\n<p>Qual \u00e8 il problema che ha dato vita al progetto gestito da un comitato scientifico internazionale?<\/p>\n<p>Un paio di anni fa Marco Squicciarini, un medico di Roma, si \u00e8 reso conto che i bambini nel mondo muoiono anche perch\u00e9, nello spostamento da un paese all\u2019altro, le cartelle cliniche e i referti non sono tradotti a norma. E in ambito medico basta sbagliare una parola e scattano grosse responsabilit\u00e0. Squicciarini si \u00e8 rivolto quindi alla docente dell\u2019universit\u00e0 di Lecce Maria Rosaria Buri, una delle interpreti e traduttrici ufficiali pi\u00f9 prestigiose a livello internazionale. Da qui il passo verso il Dream \u00e8 stato breve.<\/p>\n<p>Marco Mancarella (nella foto) \u00e8 docente di Informatica giuridica e direttore del Laboratorio di e-governmet all\u2019universit\u00e0 del Salento. E ha partecipato al tavolo internazionale T4C di marted\u00ec scorso al ministero, dove si \u00e8 preso atto che presso il Dream di Lecce vi sono server, banche dati e ambienti che favoriscono l\u2019allocazione del Comitato T4C. Al momento il Dream di Lecce \u00e8 stato il primo e l\u2019unico al mondo a proporsi al ministro.<\/p>\n<p>\u00abQuindi il Dream\u00bb, anticipa il professore Mancarella, \u00abpotrebbbe validare le traduzioni e ospitare qui da noi il centro T4C, dove abbiamo dei centri di supercalcolo per la gestione dei dati. Proprio questo ha tranquillizato il ministero. Adesso ci sono vari accordi da sottoscrivere e quindi si proceder\u00e0\u00bb.<\/p>\n<p>In appena un anno e mezzo il T4C ha gi\u00e0 salvato 35 bambini ( un paio anche italiani), grazie al contatto con i genitori che ha reso possibile la traduzione e il viaggio\u00a0da un paese all\u2019altro.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/12\/due-docenti-universitari-leccesi-protgonisti-di-un-progetto-scientifico-internazionale-per-i-bambini-che-si-spostano-da-un-paese-allaltro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/12\/due-docenti-universitari-leccesi-protgonisti-di-un-progetto-scientifico-internazionale-per-i-bambini-che-si-spostano-da-un-paese-allaltro\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(c.m.)______Il sito-progetto \u201cTranslators for children\u201d, in sigla T4C, al quale hanno aderito gratuitamente 85 nazioni, 700 interpreti e traduttori, 68 pediatri specializzati di tutto il mondo, \u00e8 nato con il compito di tradurre le cartelle cliniche dei bambini che devono sottoporsi ad intervento chirurgico in altri Paesi. Qual \u00e8 il problema che ha dato vita [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":41026,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41025"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=41025"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41025\/revisions"}],"predecessor-version":[{"id":41029,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41025\/revisions\/41029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/41026"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=41025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=41025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=41025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}