{"id":41205,"date":"2014-12-15T17:06:51","date_gmt":"2014-12-15T16:06:51","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=41205"},"modified":"2014-12-15T17:12:07","modified_gmt":"2014-12-15T16:12:07","slug":"una-lodevole-iniziativa-dellassessore-allambiente-del-comune-di-lecce-amanti-dei-nostri-amici-animali-segnate-questo-numero-verde-800-101-108","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/15\/una-lodevole-iniziativa-dellassessore-allambiente-del-comune-di-lecce-amanti-dei-nostri-amici-animali-segnate-questo-numero-verde-800-101-108\/","title":{"rendered":"UNA LODEVOLE INIZIATIVA DELL&#8217;ASSESSORE ALL&#8217;AMBIENTE DEL COMUNE DI LECCE \/ AMANTI DEI NOSTRI AMICI ANIMALI, SEGNATE QUESTO NUMERO (VERDE) : 800 101 108"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/10418881_10204108123855268_436666070918672565_n.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"720\" title=\"10418881_10204108123855268_436666070918672565_n\" class=\"alignright size-full wp-image-41206\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/10418881_10204108123855268_436666070918672565_n.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/10418881_10204108123855268_436666070918672565_n.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/10418881_10204108123855268_436666070918672565_n-300x225.jpg 300w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a>(Rdl)______E&#8217;\u00a0stato istituito\u00a0a Lecce lo Sportello &#8220;Ufficio per i diritti degli animali&#8221; (nella foto: Benito Puppi Maggi, in una delle tane della sua residenza di via Adda) con un numero verde, 800 101 108, per raccogliere le segnalazioni dei cittadini.<\/p>\n<p>Con questa nuova iniziativa l\u2019Assessorato alle Politiche Ambientali di Andrea Guido garantir\u00e0 i seguenti servizi:<\/p>\n<p>\u2022 Informazione e consulenza alla cittadinanza sui temi legati al benessere degli animali;<\/p>\n<p>\u2022 Segnalazioni riguardanti maltrattamenti, smarrimenti, ritrovamenti ;<\/p>\n<p>\u2022 Raccolta delle istanze presentate dai cittadini e dalle associazioni presenti sul territorio \u2028interessate alla tutela degli animali;<\/p>\n<p>\u2022 Predisposizione ed elaborazione di progetti di tutela e salvaguardia delle popolazioni animali \u2028presenti sul territorio;<\/p>\n<p>\u2022 Divulgazione alla cittadinanza, ed in particolare ai possessori di animali, di informazioni e \u2028disposizioni amministrative riguardo le corrette norme di disciplina e detenzione degli animali;<\/p>\n<p>\u2022 Interventi volti all\u2019incentivazione dell\u2019adozione dei cani presenti presso il canile e i rifugi convenzionati;<\/p>\n<p>\u2022 Realizzazione campagne di informazione e sensibilizzazione.<\/p>\n<p>Il nuovo servizio \u00e8 frutto dell&#8217;accordo tra l\u2019Assessore Guido e la sezione leccese dell&#8217;Associazione A.n.p.a.n.a. Onlus. Lo sportello \u00e8 attivo al secondo piano della sede comunale di via Lombardia n.7 ed \u00e9 aperto al pubblico 5 giorni alla settimana (Luned\u00ec, Mercoled\u00ec, Venerd\u00ec dalle ore 10.00 alle ore 12.00; Marted\u00ec e Gioved\u00ec dalle ore 15.00 alle ore 17.00).<\/p>\n<p>Il numero verde 800 101 108 \u00e8 attivo fino alla fine di dicembre solo in orario d\u2019ufficio, con il nuovo anno, invece, il servizio sar\u00e0 esteso per tutto l&#8217;arco delle ventiquattro ore..<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/15\/una-lodevole-iniziativa-dellassessore-allambiente-del-comune-di-lecce-amanti-dei-nostri-amici-animali-segnate-questo-numero-verde-800-101-108\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/15\/una-lodevole-iniziativa-dellassessore-allambiente-del-comune-di-lecce-amanti-dei-nostri-amici-animali-segnate-questo-numero-verde-800-101-108\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______E&#8217;\u00a0stato istituito\u00a0a Lecce lo Sportello &#8220;Ufficio per i diritti degli animali&#8221; (nella foto: Benito Puppi Maggi, in una delle tane della sua residenza di via Adda) con un numero verde, 800 101 108, per raccogliere le segnalazioni dei cittadini. Con questa nuova iniziativa l\u2019Assessorato alle Politiche Ambientali di Andrea Guido garantir\u00e0 i seguenti servizi: \u2022 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":41206,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41205"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=41205"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41205\/revisions"}],"predecessor-version":[{"id":41209,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41205\/revisions\/41209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/41206"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=41205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=41205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=41205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}