{"id":41260,"date":"2014-12-16T15:42:13","date_gmt":"2014-12-16T14:42:13","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=41260"},"modified":"2014-12-17T08:00:53","modified_gmt":"2014-12-17T07:00:53","slug":"pallavolo-aurispa-alessano-sfortunata-trasferta-a-cantu","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/16\/pallavolo-aurispa-alessano-sfortunata-trasferta-a-cantu\/","title":{"rendered":"PALLAVOLO \/ ALESSANO, TRASFERTA AMARA A CANTU&#8217;"},"content":{"rendered":"<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div>\n<div title=\"Desktop\" dir=\"ltr\">\n<div dir=\"ltr\">\n<div title=\"\" dir=\"ltr\">\n<div dir=\"ltr\">\n<div title=\"\" dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div title=\"\" dir=\"ltr\">\n<div dir=\"ltr\">\n<div>\n<div>\n<div><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/cantu.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"168\" title=\"cantu\" class=\"alignright size-medium wp-image-41262\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/cantu-300x168.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/cantu-300x168.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/cantu.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>(a.c.p.a.a.)_______L\u2019Aurispa Alessano perde per 3-0 contro la Cassa Rurale Cant\u00f9, combattendo ad armi pari per lunghi tratti contro i pi\u00f9 quotati avversari, ma commettendo degli errori nei momenti topici dell\u2019incontro che hanno determinato il risultato finale.<\/div>\n<div><\/div>\n<div><strong>Il giudizio<\/strong><\/div>\n<div>La squadra di mister Medico ha dovuto ha dovuto combattere anche contro la sfortuna: oltre a dover rinunciare al greco Armenakis, ancora alle prese con l\u2019infortunio alla caviglia, ha avuto Bolla a mezzo servizio a causa di un attacco influenzale che lo ha costretto ad abbandonare definitivamente l\u2019incontro ad inizio terzo set. I biancoazzurri comunque non hanno demeritato del tutto, proponendo buone azioni di gioco davanti ad un nutrito gruppo di supporter giunti dalle zone vicine ad incitare Mazza e compagni. In casa canturina ottima la prova dei tre schiacciatori Tamburo, Mercorio e Ippolito, autori di 16 punti ciascuno.<\/div>\n<div><\/div>\n<div><strong>La cronaca<\/strong><\/div>\n<div>Il Cant\u00f9 scende in campo con Gerosa in regia, Tamburo opposto, Ippolito e Mercorio laterali, Bargi e Robbiati centrali, Butti libero. Mister Medico risponde con Parisi al palleggio, Mazza opposto, Bolla e Grassano laterali, Torsello e Musardo centrali, Ancora libero.<\/div>\n<div>\n<p>Inizio partita con Mercorio che con due attacchi e un muro porta sul 3-1 il Cant\u00f9. La squadra di casa prende un altro punto di vantaggio per il 6-3, ma l\u2019Aurispa reagisce con grinta e ribalta la situazione con un 5-0 portandosi sull\u20198-6 in proprio favore, sfruttando soprattutto il muro (tre consecutivi con Musardo, Mazza e Grassano). Al tempo tecnico \u00e8 12-10 per i biancoazzurri che al rientro in campo per\u00f2 non riescono a gestire il vantaggio e vanno sotto 15-13, con il laterale Ippolito autore di quattro punti consecutivi. Due mani e fuori di capitan Mazza danno il nuovo pareggio (16-16). L\u2019equilibrio \u00e8 spezzato da un\u2019invasione a muro di Torsello che d\u00e0 il 20-18 per Gerosa e compagni. Tamburo porta la sua squadra sul 23-19, poi due sviste arbitrali regalano un punto per parte (non visti l\u2019asticella toccata da Mazza su attacco e un tocco a muro del Cant\u00f9 sempre su Mazza). La squadra di casa chiude il set con un attacco di Ippolito per il 25-20 in 30\u00a0 minuti di gioco.<\/p>\n<p>2-0 per il Cant\u00f9 ad inizio secondo set con Tamburo che mette in difficolt\u00e0 la ricezione biancoazzurra. L\u2019Aurispa raggiunge subito il 3 pari con due errori canturini, poi due punti di Torsello, un errore in attacco di Bargi e un mani e fuori di Mazza portano gli ospiti sul 7-4. Il Cant\u00f9 recupera per il 9 pari, poi si porta avanti 11-10 con Tamburo. Al tempo tecnico \u00e8 12-11 per i padroni di casa. Torsello con tre punti ribalta la situazione (14-12), ma la formazione di mister Della Rosa pareggia immediatamente e passa in vantaggio per 15-14 con un diagonale stretto di Mercorio. I punti di vantaggio diventano due per il 17-15, poi l\u2019Aurispa si riprende e raggiunge di nuovo l\u2019avversario sul 19 pari. Le squadre lottano punto a punto e i biancoazzurri riescono ad annullare anche due setpoint ai canturini che per\u00f2 si impongono ugualmente per 27-25 dopo 32 combattuti minuti, con Mazza che per troppa frenesia manda in rete una palla sulla quale stava comodamente intervenendo Parisi.<\/p>\n<p>Inizio terzo parziale equilibrato fino al 4 pari, poi l\u2019Aurispa prende un margine di vantaggio di tre punti andando sul 7-4. Come nel secondo set i padroni di casa rimontano fino al 9 pari trascinati da Tamburo. Al tempo tecnico \u00e8 12-11 per la Cassa Rurale. Un muro di Robbiati su Grassano d\u00e0 il 13-11; il vantaggio canturino aumenta fino al 16-13. La squadra biancoazzurra si disunisce e Cant\u00f9 ne approfitta per portarsi sul +5 (19-14). Il vantaggio viene amministrato fino al 24-19, quando l\u2019Aurispa, con un ultimo colpo di reni, annulla tre matchpoint. Nulla pu\u00f2 per\u00f2 Schwagler contro il muro a tre avversario: Mercorio intercetta l\u2019attacco del laterale americano e regala il 25-22 alla propria squadra che si aggiudica il parziale in 29 minuti di gioco per il 3-0 definitivo.<\/p>\n<p><strong>I tabellini<\/strong><\/p>\n<p>Aurispa Alessano: Parisi, Mazza 14, Grassano 9, Bolla 5, Musardo 4, Torsello 10, Ancora (L), Schwagler 1, Muccio 1, De Giovanni 1, Nicolazzo, Bisanti (L) n.e. 1\u00b0 all. Medico, 2\u00b0 all. Bramato<\/p>\n<p>Ace 2, B.S. 12, Muri 9. Ric.: pos. 62%, perf. 21%. Att. 27%<\/p>\n<p>Cassa Rurale Cant\u00f9: Gerosa 1 Tamburo 16, Mercorio 16, Ippolito 16 , Bargi, Robbiati 6, Butti (L), Monguzzi 3, Groppi, Rudi (L) n.e., Santangelo n.e., Carminati n.e., Gatti n.e. 1\u00b0 all. Della Rosa Massimo, 2\u00b0 all. Readelli Massimo<\/p>\n<p>Ace 9, B.S. 10, Muri 16. Ric.: pos. 60%, perf. 23%. Att. 49%<\/p>\n<p>Arbitri: Giardini Massimiliano di Verona e Pozzi Roberto di Alessandria<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div dir=\"ltr\"><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/16\/pallavolo-aurispa-alessano-sfortunata-trasferta-a-cantu\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/16\/pallavolo-aurispa-alessano-sfortunata-trasferta-a-cantu\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(a.c.p.a.a.)_______L\u2019Aurispa Alessano perde per 3-0 contro la Cassa Rurale Cant\u00f9, combattendo ad armi pari per lunghi tratti contro i pi\u00f9 quotati avversari, ma commettendo degli errori nei momenti topici dell\u2019incontro che hanno determinato il risultato finale. Il giudizio La squadra di mister Medico ha dovuto ha dovuto combattere anche contro la sfortuna: oltre a dover [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":41262,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41260"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=41260"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41260\/revisions"}],"predecessor-version":[{"id":41352,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41260\/revisions\/41352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/41262"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=41260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=41260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=41260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}