{"id":41334,"date":"2014-12-16T23:23:49","date_gmt":"2014-12-16T22:23:49","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=41334"},"modified":"2014-12-17T08:37:17","modified_gmt":"2014-12-17T07:37:17","slug":"inaugurata-a-lecce-assocuore-per-combattere-le-malattie-cardiovascolari","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/16\/inaugurata-a-lecce-assocuore-per-combattere-le-malattie-cardiovascolari\/","title":{"rendered":"INAUGURATA A LECCE L&#8217;ASSOCIAZIONE &#8220;ASSOCUORE&#8221; PER COMBATTERE LE MALATTIE CARDIOVASCOLARI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/CUORE.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"166\" title=\"CUORE\" class=\"alignright size-full wp-image-41335\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/CUORE.jpg\" \/><\/a>di Cesare Mazzotta____<strong>Al President una sala affollata oltre ogni previsione. Sabato scorso 13 dicembre pi\u00f9 di 200 persone, fra medici, pazienti gi\u00e0 provati dalla patologia cardiaca e semplici \u00ablaici\u00bb che non hanno voluto mancare alla presentazione ufficiale di \u201cAssocuore\u201d, nata il 24 aprile 2014.<\/strong><br \/>\n<strong>Soddisfatto e fiero il presidente della debuttante associazione, il cardiochirurgo del \u00abFazzi\u00bb, Domenico Rocco, che ha illustrato gli scopi, i benefici e le modalit\u00e0 di partecipazione al sodalizio.<\/strong><br \/>\n<strong>\u00abL\u2019associazione nasce da una precisa esigenza, quella di favorire la prevenzione delle malattie cardiovascolari che oggi sono ancora la prima causa di morte nel mondo occidentale\u00bb, ha spiegato il dottore Rocco, \u00abTutti i giorni vediamo arrivare in ospedale persone che potevano farne a meno se fossero andate a controllare alcuni parametri e fattori di rischio\u00bb.<\/strong><\/p>\n<p><strong>\u00a0Prevenzione che il dottore Rocco ha intenzione di portare nelle scuole. \u00abOrganizzando incontri dove si parla con termini comprensibili \u2013 promette \u2013 in modo che la gente capisca il problema e i rischi ai quali va incontro\u00bb.<\/strong><\/p>\n<p><strong>\u00a0Hanno illustrato le finalit\u00e0 di Assocuore anche altri specialisti dell\u2019emergenza cardiovascolare. Maurizio Scardia, direttore del 118 della Asl, Cosimo Greco, cardiologo nel reparto di Cardiochirurgia, specializzato in ecocardiografia e Vincenzo De Rito, del reparto di cardiologia del Fazzi.<\/strong><br \/>\n<strong>Ma le prospettive di \u201cAssocuore\u201d sono pi\u00f9 ampie. L\u2019associazione svolger\u00e0 un\u2019azione di supporto per i soci che hanno avuto un infarto o sub\u00ecto un intervento al cuore. Molto preziosa per questo la presenza della dottoressa Valentina Torsello, psicologa, specialista nel recupero dei pazienti infartuati e operati. E proprio in direzione del \u201csupporto\u201d verranno programmati dei seminari, nei quali saranno coinvolti pazienti cardiopatici.<\/strong><br \/>\n<strong>Tra le finalit\u00e0 di \u201cAssocuore\u201d non manca la raccolta di fondi per acquistare strumentazione da donare ai reparti di cura (defibrillatori, ecografi..).<\/strong><\/p>\n<p><strong>\u00a0Una marcia operativa in pi\u00f9 a favore dei soci di \u201cAssocuore\u201d, gi\u00e0 numerosi, \u00e8 rappresentata dai benefici a loro riservati: visite specialistiche presso strutture convenzionate a prezzi ridotti, sconti sull\u2019acquisto di servizi, consulenza e, non ultima, la possibilit\u00e0 di far sentire la propria voce nelle sedi opportune attraverso l\u2019associazione. E\u2019 prevista una manifestazione di Assocuore in piazza Sant\u2019Oronzo, dove ai passanti che lo desiderano sar\u00e0 misurata la pressione. Un modo concreto per evidenziare l\u2019importanza della pressione, fattore di rischio nell\u2019infarto e nell\u2019ictus.<\/strong><\/p>\n<p><strong>\u00a0\u00abUn altro degli scopi di Assocuore \u00e8 far capire cosa vuol dire essere danneggiati dal fumo \u2013 spiega il presidente Rocco \u2013 Condurre una vita sana, un\u2019 alimentazione equilibrata, non essere statici ma fare un\u2019attivit\u00e0 fisica o uno sport che piace. Attenzione \u2013 avverte &#8211; al colesterolo, ai trigliceridi, alla glicemia e tenere la pressione sotto controllo. L\u2019altro grosso fattore di rischio \u00e8 lo stress, che oggi assume una decisa preponderanza\u00bb.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>E\u2019 gi\u00e0 attivo il sito dell\u2019associazione www.assocuoresalento.it dove si pu\u00f2 scaricare la scheda di adesione (20 euro), ricevere una password e interagire con gli specialisti.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/16\/inaugurata-a-lecce-assocuore-per-combattere-le-malattie-cardiovascolari\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/16\/inaugurata-a-lecce-assocuore-per-combattere-le-malattie-cardiovascolari\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Cesare Mazzotta____Al President una sala affollata oltre ogni previsione. Sabato scorso 13 dicembre pi\u00f9 di 200 persone, fra medici, pazienti gi\u00e0 provati dalla patologia cardiaca e semplici \u00ablaici\u00bb che non hanno voluto mancare alla presentazione ufficiale di \u201cAssocuore\u201d, nata il 24 aprile 2014. Soddisfatto e fiero il presidente della debuttante associazione, il cardiochirurgo del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":41335,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41334"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=41334"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41334\/revisions"}],"predecessor-version":[{"id":41360,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41334\/revisions\/41360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/41335"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=41334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=41334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=41334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}