{"id":41390,"date":"2014-12-17T16:01:48","date_gmt":"2014-12-17T15:01:48","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=41390"},"modified":"2014-12-17T16:02:52","modified_gmt":"2014-12-17T15:02:52","slug":"ancora-altri-sbarchi-di-profughi-sulle-coste-del-salento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/17\/ancora-altri-sbarchi-di-profughi-sulle-coste-del-salento\/","title":{"rendered":"QUESTA MATTINA A ROCA ANCORA UN ALTRO SBARCO DI PROFUGHI SULLE COSTE DEL SALENTO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/untitled39.png\"><img decoding=\"async\" loading=\"lazy\" width=\"259\" height=\"194\" title=\"untitled\" class=\"alignright size-full wp-image-41391\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/untitled39.png\" \/><\/a>(t.l.)______Giorno dopo giorno, episodio dopo episodio, oramai diventati talmente comuni, da passare pressoch\u00e9 inosservati, proseguono gli sbarchi di immigrati extracomunitari, spesso profughi, sempre disperati alla ricerca di una via di salvezza da guerra, miseria e fame, sulle nostre, senza che nessuno cerchi di governare e gestire in qualche modo il fenomeno, prima che diventi anche qui, come a Lampedusa, una vera e propria emergenza.<\/p>\n<p>Questa mattina sono stati rintracciati dai Carabinieri nella zona di Melendugno altri 39 profughi, presumibilmente solo una parte dei nuovi arrivati, i quali hanno detto di essere di nazionalit\u00e0 siriana e di essere giunti nella notte al largo di Roca a bordo di un gommone, da cui uno \u201cscafista\u201d li ha 2scaricari\u201d prima di dileguarsi in mare.<\/p>\n<p>Sono in corso le abituali, in questi casi, trafile burocratiche di visite, identificazioni e accompagnamenti al centro di accoglienza \u201cDon Tonino Bello\u201d di Otranto, non sappiamo ancora per quanto capace di reggere nuovi arrivi.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/17\/ancora-altri-sbarchi-di-profughi-sulle-coste-del-salento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/17\/ancora-altri-sbarchi-di-profughi-sulle-coste-del-salento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)______Giorno dopo giorno, episodio dopo episodio, oramai diventati talmente comuni, da passare pressoch\u00e9 inosservati, proseguono gli sbarchi di immigrati extracomunitari, spesso profughi, sempre disperati alla ricerca di una via di salvezza da guerra, miseria e fame, sulle nostre, senza che nessuno cerchi di governare e gestire in qualche modo il fenomeno, prima che diventi anche [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":41391,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41390"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=41390"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41390\/revisions"}],"predecessor-version":[{"id":41393,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41390\/revisions\/41393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/41391"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=41390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=41390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=41390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}