{"id":41396,"date":"2014-12-17T20:04:14","date_gmt":"2014-12-17T19:04:14","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=41396"},"modified":"2014-12-18T08:01:50","modified_gmt":"2014-12-18T07:01:50","slug":"venti-anni-dopo-la-sua-morte-oggi-e-diventata-legale-il-destino-cosi-fragile-cosi-violento-di-ylenia-carrisi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/17\/venti-anni-dopo-la-sua-morte-oggi-e-diventata-legale-il-destino-cosi-fragile-cosi-violento-di-ylenia-carrisi\/","title":{"rendered":"VENTI ANNI DOPO, LA SUA MORTE OGGI E\u2019 DIVENTATA LEGALE \/ IL DESTINO COSI\u2019 FRAGILE, COSI\u2019 VIOLENTO DI YLENIA CARRISI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/AL.png\"><img decoding=\"async\" loading=\"lazy\" width=\"276\" height=\"182\" title=\"AL\" class=\"alignright size-full wp-image-41397\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/AL.png\" \/><\/a>di Giuseppe Puppo______La notizia \u00e8 di oggi, perch\u00e9 oggi l\u2019hanno battuta le agenzie, ma risale al primo dicembre: il tribunale di Brindisi, espletate la prassi legale di rito e tutti gli adempimenti burocratici, ha decretato la morte presunta di Ylenia Maria Sole Carrisi, la figlia di Al Bano e di Romina Power, scomparsa a New Orleans, negli Stati Uniti, il 31 dicembre del 1994, all\u2019et\u00e0 di 24 anni, in circostanze mai del tutto completamente chiarite.<\/p>\n<p>In questo modo finisce \u2013 almeno dal punto di vista giuridico, perch\u00e9 questa sentenza vale come l\u2019affermazione di un vero decesso \u2013 un caso che ha appassionato un po\u2019 tutti, senza che nessuno ne sia mai venuto a capo, e che per tanti versi rimane ancora avvolto nel mistero.<\/p>\n<p>Ci sono ferite che non si rimarginano, perch\u00e9 ogni volta, per una ragione o per l\u2019altra, si riaprono dolorosamente.<\/p>\n<p>Vent\u2019anni dopo, come il primo giorno, anche perch\u00e9 non c\u2019\u00e8 una tomba, non c\u2019\u00e8 un colpevole, e non c\u2019\u00e8 una spiegazione plausibile.<\/p>\n<p>Le inchieste svolte all\u2019epoca dagli Americani fanno acqua da tutte le parti, e non sono riuscite ad andare a fondo della questione, sfiorando, ma soltanto sfiorando, responsabilit\u00e0 che pure in un caso come questo devono comunque esserci e tanto meno fornendo una ricostruzione attendibile, in particolare sul ruolo avuto nella vicenda da un maturo musicista di strada, a met\u00e0 fra l\u2019incantatore di serpenti e il filosofo esistenzialista all\u2019acqua di rose.<\/p>\n<p>L\u2019unico testimone di qualcosa di quella notte maledetta sulle rive del Mississippi, il guardiano del locale acquario, ha affermato di aver visto una figura femminile, da lui ritenuta a posteriori compatibile con Ylenia, lasciarsi scivolare in acqua, senza per\u00f2 fornire certezza alcuna, anzi, alimentando i dubbi, sul come e perch\u00e9 abbia speso quelle parole, vista l&#8217; anomalia del mancato ritrovamento del corpo in quel tratto.<\/p>\n<p>Purtroppo, non hanno mai trovato certezza alcuna nemmeno le tante segnalazioni, che periodicamente si susseguono, di Ylenia viva e vegeta, nascosta in un convento, o rinchiusa in una comunit\u00e0.<\/p>\n<p>In effetti, contro la tesi dell\u2019allontanamento e della sparizione volontaria ostano le motivazione dei profondi legami famigliari, che ragionevolmente impediscono di pensare a una sorte di questo tipo espressamente da lei voluta, senza nemmeno un minimo di comunicazione.<\/p>\n<p>Rimane dunque, oggi che \u00e8 morta per la legge italiana, una profonda amarezza per il destino di questa ragazza solare come il secondo nome che portava, che a Lecce aveva fatto gli studi e che a Lecce aveva tante amicizie, dalla vicina Cellino San Marco. Poliglotta, colta, ricca di sogni e disprezzatrice dei beni materiali, avida di conoscenza e inquieta quanto basta per volersene andare a scoprire il mondo, fra i villaggi del Sudamerica sulle orme di Bruce Chatwin, o sulle grandi strade piene e i vecchi alberghi trasformati della sua seconda patria americana, appresso a Jack Keruac, per trovare la sua citt\u00e0 per cantare.<\/p>\n<p>Una fatalit\u00e0, un crimine, una leggerezza, non lo sapremo mai, rimarr\u00e0 forse per sempre il mistero, su un destino che dalla tragicit\u00e0 trova la sua grandezza, e destinato a restare in maniera imperitura in quello che abbiamo imparato a chiamare l\u2019immaginario collettivo. Sappiamo per\u00f2 che di sogni si vive, ma si pu\u00f2 anche morire. Di sicuro Ylenia Carrisi \u00e8 morta inseguendo i suoi sogni, e questo nobilita il suo ricordo, questo segna per sempre la sua grandezza.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/17\/venti-anni-dopo-la-sua-morte-oggi-e-diventata-legale-il-destino-cosi-fragile-cosi-violento-di-ylenia-carrisi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/17\/venti-anni-dopo-la-sua-morte-oggi-e-diventata-legale-il-destino-cosi-fragile-cosi-violento-di-ylenia-carrisi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo______La notizia \u00e8 di oggi, perch\u00e9 oggi l\u2019hanno battuta le agenzie, ma risale al primo dicembre: il tribunale di Brindisi, espletate la prassi legale di rito e tutti gli adempimenti burocratici, ha decretato la morte presunta di Ylenia Maria Sole Carrisi, la figlia di Al Bano e di Romina Power, scomparsa a New [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":41397,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41396"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=41396"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41396\/revisions"}],"predecessor-version":[{"id":41400,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41396\/revisions\/41400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/41397"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=41396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=41396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=41396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}