{"id":41502,"date":"2014-12-18T18:42:32","date_gmt":"2014-12-18T17:42:32","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=41502"},"modified":"2014-12-18T18:42:32","modified_gmt":"2014-12-18T17:42:32","slug":"un-colpo-di-arma-da-fuoco-buca-i-vetri-di-una-scuola-di-lecce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/18\/un-colpo-di-arma-da-fuoco-buca-i-vetri-di-una-scuola-di-lecce\/","title":{"rendered":"UN COLPO DI ARMA DA FUOCO BUCA I VETRI DI UNA SCUOLA DI LECCE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/geometri1.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"233\" title=\"geometri1\" class=\"alignright size-medium wp-image-41503\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/geometri1-300x233.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/geometri1-300x233.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/geometri1.jpg 330w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>(t.l.)______Questa mattina gli operatori scolastici dell\u2019istituto tecnico \u201cGalileI\u201d di piazza Palio a Lecce (nella foto), nel sollevare le serrande delle aule, hanno scoperto che i vetri di una finestra erano stati colpiti e perforati da un colpo di proiettile.<\/p>\n<p>Immediatamente avvisati dal personale, sono giunti sul posto gli uomini della squadra mobile della Polizia, che hanno recuperato il bossolo ed eseguito tutti i rilievi del caso.<\/p>\n<p>Da quanto \u00e8 emerso, si tratterebbe di un colpo sparato in altre direzioni, che solamente in maniera indiretta avrebbe raggiunto l\u2019aula. L\u2019 ipotesi \u00e8 avvalorata dalla constatazione che la piazza \u00e8 stata, anche di recente, teatro di episodi di criminalit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/18\/un-colpo-di-arma-da-fuoco-buca-i-vetri-di-una-scuola-di-lecce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/18\/un-colpo-di-arma-da-fuoco-buca-i-vetri-di-una-scuola-di-lecce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)______Questa mattina gli operatori scolastici dell\u2019istituto tecnico \u201cGalileI\u201d di piazza Palio a Lecce (nella foto), nel sollevare le serrande delle aule, hanno scoperto che i vetri di una finestra erano stati colpiti e perforati da un colpo di proiettile. Immediatamente avvisati dal personale, sono giunti sul posto gli uomini della squadra mobile della Polizia, che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":41503,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41502"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=41502"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41502\/revisions"}],"predecessor-version":[{"id":41505,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41502\/revisions\/41505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/41503"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=41502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=41502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=41502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}