{"id":41560,"date":"2014-12-19T14:56:37","date_gmt":"2014-12-19T13:56:37","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=41560"},"modified":"2014-12-19T14:56:37","modified_gmt":"2014-12-19T13:56:37","slug":"un-alfa-romeo-giulietta-sulla-sua-bici-muore-pensionato-di-cursi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/19\/un-alfa-romeo-giulietta-sulla-sua-bici-muore-pensionato-di-cursi\/","title":{"rendered":"UN&#8217; ALFA ROMEO GIULIETTA SULLA SUA BICI, MUORE PENSIONATO DI CURSI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/images61B6INE3.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"137\" title=\"images61B6INE3\" class=\"alignright size-medium wp-image-41562\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/images61B6INE3-300x137.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/images61B6INE3-300x137.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/images61B6INE3.jpg 332w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>(t.l.)______Un anziano, Rocco Siciliano, 79 anni, di Cursi, pensionato, \u00e8 morto nella notte all\u2019ospedale di Scorrano in seguito alle ferite riportate in un incidente stradale successo poche ore prima.<\/p>\n<p>Stava percorrendo in bicicletta la strada provinciale che porta a Melpignano, quando \u00e8 sopraggiunta un\u2019automobile \u2013 una Giulietta Alfa Romeo &#8211; condotta da un medico, che lo ha travolto.<\/p>\n<p>Al momento le cause dell\u2019incidente non sono chiare: le dinamiche sono al vaglio dei carabinieri e della magistratura.<\/p>\n<p>Nella foto d&#8217;archivio un&#8217;immagine di repertorio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/19\/un-alfa-romeo-giulietta-sulla-sua-bici-muore-pensionato-di-cursi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/19\/un-alfa-romeo-giulietta-sulla-sua-bici-muore-pensionato-di-cursi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)______Un anziano, Rocco Siciliano, 79 anni, di Cursi, pensionato, \u00e8 morto nella notte all\u2019ospedale di Scorrano in seguito alle ferite riportate in un incidente stradale successo poche ore prima. Stava percorrendo in bicicletta la strada provinciale che porta a Melpignano, quando \u00e8 sopraggiunta un\u2019automobile \u2013 una Giulietta Alfa Romeo &#8211; condotta da un medico, che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":41562,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41560"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=41560"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41560\/revisions"}],"predecessor-version":[{"id":41563,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41560\/revisions\/41563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/41562"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=41560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=41560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=41560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}