{"id":41733,"date":"2014-12-22T10:56:04","date_gmt":"2014-12-22T09:56:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=41733"},"modified":"2014-12-23T11:04:17","modified_gmt":"2014-12-23T10:04:17","slug":"truffe-assicurative-per-un-giro-daffari-di-circa-un-milione-di-euro","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/22\/truffe-assicurative-per-un-giro-daffari-di-circa-un-milione-di-euro\/","title":{"rendered":"SGOMINATA UN&#8217; ASSOCIAZIONE DEDITA ALLE TRUFFE AI DANNI DELLE COMPAGNIE DI ASSICURAZIONE AUTOMOBILISTICA \/ GUADAGNI ILLECITI PER UN MILIONE DI EURO \/ DODICI ARRESTI, SESSANTA DENUNCE \/ COINVOLTI ANCHE STIMATI PROFESSIONISTI COME MEDICI E AVVOCATI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/assicurazioni-truffa.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/assicurazioni-truffa.jpg\" alt=\"\" title=\"assicurazioni truffa\" width=\"3500\" height=\"444\" class=\"alignleft size-full wp-image-41790\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/assicurazioni-truffa.jpg 3500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/assicurazioni-truffa-300x38.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/assicurazioni-truffa-1024x129.jpg 1024w\" sizes=\"(max-width: 3500px) 100vw, 3500px\" \/><\/a>(t.l.)______La Polizia di Stato ha scoperto\u00a0<strong>37 falsi sinistri stradali<\/strong>\u00a0avvenuti negli anni tra il<strong>\u00a02008\u00a0<\/strong>ed il<strong>\u00a02010. <\/strong>L&#8217; indagine, da tempo avviata,\u00a0\u00e8 culminata con le ordinanze di custodia cautelare nei confronti di\u00a0<strong>dodici<\/strong>\u00a0individui, eseguite questa mattina.<br \/>\nLe articolate investigazioni, svolte dalla \u00a0Sezione di\u00a0polizia giudiziaria presso la\u00a0la Procura della Repubblica di Lecce, hanno permesso di individuare\u00a0 una vera e propria\u00a0associazione criminale operante nella nostra provincia, dedita a inventare incidenti stradali e ad alterare quelli realmente accaduti, al fine di ricavare denaro facile, truffando le compagnie di assicurazione.<\/p>\n<p>Sono stati arrestati\u00a0il titolare di un\u2019autocarrozzeria, due periti assicurativi, due medici chirurghi, due carrozzieri, due avvocati, due liquidatori assicurativi, e\u00a0il titolare di una agenzia d\u2019investigazioni, mentre un medico, specialista in ortopedia e traumatologia, \u00e8 stato sottoposto all\u2019obbligo di dimora; tutti, come si vede, per professione utili all&#8217;organizzazione. A tutti sono stati concessi i domiciliari.<\/p>\n<p>Inoltre, sono stati denunciati in stato di libert\u00e0 altre sessanta persone, tutte ritenute responsabili a vario titolo del delitto di associazione a delinquere, finalizzata alla simulazione di falsi incidenti stradali, al fine di far conseguire consistenti ed indebiti indennizzi da parte delle compagnie assicuratrici attraverso la falsificazione, alterazione e pre costituzione di elementi di prova.<\/p>\n<p>La zona pi\u00f9 colpita da questo malcostume, che finiva per influire pesantemente sui costi e gli aumenti delle polizze, riguarda soprattutto il centro del Salento, dove si era registrato un considerevole aumento delle denunce<br \/>\nI garanti dell\u2019associazione a delinquere risultavano essere i <strong>liquidatori<\/strong> delle compagnie assicuratrici, che, anzich\u00e9 tutelarne gli interessi, attraverso le loro condotte,\u00a0 consentivano\u00a0 il buon esito delle frodi, liquidando i falsi incidenti stradali con\u00a0consistenti indebiti esborsi di denaro. Gli <strong>avvocati<\/strong> partecipavano all\u2019associazione non solo in qualit\u00e0 di legali per tutte le incombenze di carattere tecnico-giuridico necessarie per la liquidazione dei sinistri, ma anche creando loro stessi le condizioni ideali per i falsi incidenti stradali, consigliando ed istruendo i loro clienti indirizzandoli finanche presso <strong>medici c<\/strong>ompiacenti per ottenere false certificazioni attestanti lesioni compatibili con traumi da incidente stradale. In molti altri casi, addirittura, i <strong>medici<\/strong>\u00a0 fornivano le loro certificazioni senza aver mai visitato o conosciuto le persone a cui le rilasciavano.<\/p>\n<p>In seno all\u2019associazione trovano posto anche i <strong>periti<\/strong> che, in qualit\u00e0 di fiduciari delle compagnie assicuratrici, anzich\u00e9 agire nell\u2019interesse delle stesse redigevano false relazioni peritali. Per ultimo, ma non per importanza, \u00e8 il ruolo che assumevano i <strong>carrozzieri<\/strong> i quali, organizzavano falsi incidenti stradali utilizzando i dati di persone ignare, intestatarie di autovetture che in ragione della loro attivit\u00e0 avevano avuto nella loro disponibilit\u00e0.<\/p>\n<p>L\u2019ammontare delle somme elargite dalle compagnie assicurative ed indebitamente percepite dalle persone coinvolte nella truffa \u00e8 risultata essere di circa un milione di euro; la compagnia maggiormente danneggiata \u00e8 stata la UNIPOL,\u00a0che, con la sua denuncia, ha dato l\u2019avvio all\u2019attivit\u00e0 investigativa.<\/p>\n<p>Le indagini\u00a0della Polizia di Stato\u00a0sono ancora in corso.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/22\/truffe-assicurative-per-un-giro-daffari-di-circa-un-milione-di-euro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/22\/truffe-assicurative-per-un-giro-daffari-di-circa-un-milione-di-euro\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(t.l.)______La Polizia di Stato ha scoperto\u00a037 falsi sinistri stradali\u00a0avvenuti negli anni tra il\u00a02008\u00a0ed il\u00a02010. L&#8217; indagine, da tempo avviata,\u00a0\u00e8 culminata con le ordinanze di custodia cautelare nei confronti di\u00a0dodici\u00a0individui, eseguite questa mattina. Le articolate investigazioni, svolte dalla \u00a0Sezione di\u00a0polizia giudiziaria presso la\u00a0la Procura della Repubblica di Lecce, hanno permesso di individuare\u00a0 una vera e propria\u00a0associazione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":41790,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41733"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=41733"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41733\/revisions"}],"predecessor-version":[{"id":41738,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41733\/revisions\/41738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/41790"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=41733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=41733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=41733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}