{"id":41995,"date":"2014-12-27T13:04:13","date_gmt":"2014-12-27T12:04:13","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=41995"},"modified":"2014-12-27T15:48:14","modified_gmt":"2014-12-27T14:48:14","slug":"ufficiale-via-lerda-arriva-pagliari-conosciamo-da-vicino-il-nuovo-tecnico-del-lecce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/27\/ufficiale-via-lerda-arriva-pagliari-conosciamo-da-vicino-il-nuovo-tecnico-del-lecce\/","title":{"rendered":"ESONERATO FRANCO LERDA, ARRIVA DINO PAGLIARI \/ ALLA SCOPERTA DEL NUOVO ALLENATORE DEL LECCE: MEGLIO UNA GALLINA DOMANI, CHE UN UOVO OGGI&#8230;"},"content":{"rendered":"<p>di <strong>Laura Ricci<\/strong>________<a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/225525_174191515970166_7599647_n.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"291\" height=\"300\" title=\"225525_174191515970166_7599647_n\" class=\"alignleft size-medium wp-image-42001\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/225525_174191515970166_7599647_n-291x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/225525_174191515970166_7599647_n-291x300.jpg 291w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/225525_174191515970166_7599647_n.jpg 369w\" sizes=\"(max-width: 291px) 100vw, 291px\" \/><\/a><\/p>\n<p>La decisione di invertire la rotta presa dal<strong> Lecce <\/strong>dopo aver subito tre sconfitte consecutive, deludendo aspettative e prestazioni, implica che la famiglia <strong>Tesoro<\/strong> si sia messa in moto per sostituire il timoniere di\u00a0una barca pericolosamente in fase di affondo.<\/p>\n<p>Giunta l&#8217;<strong> ufficialit\u00e0<\/strong> dell&#8217;esonero di <strong>Lerda<\/strong>, <strong>Antonio Tesoro<\/strong>, direttore sportivo del Lecce, ha intavolato delle trattative con diversi candidati alla panchina giallorossa. Il grande favorito \u00a0sembrava essere <strong>Alessandro Calori<\/strong>, ex allenatore di <strong>Novara, Brescia e Padova<\/strong> che aveva convinto la societ\u00e0 salentina a puntare su di lui per risollevare la situazione della squadra. Dopo fitti colloqui, nonostante l&#8217;iniziale predisposizione del tecnico ad approdare a Lecce<strong>, Calori ha deciso di rifiutare l&#8217;offerta dei Tesoro<\/strong>.<\/p>\n<p>Una volta incassato il &#8220;no&#8221; della prima scelta del Lecce, dopo vari incontri con Dionigi, che per\u00f2 non ha convinto, l&#8217;attenzione della societ\u00e0 giallorossa si \u00e8 riversata su un personaggio inaspettato dalla piazza leccese: <strong>Dino Pagliari.<\/strong> Si parla di un uomo dalla personalit\u00e0 &#8220;stravagante&#8221;, fuori dagli schemi con la sua capigliatura particolare e il modo di fare che richiama l&#8217;attenzione: un curioso aneddoto ci descrive mister <strong>Pagliari<\/strong> in giro per Firenze <strong>con una gallina al guinzaglio.<\/strong><\/p>\n<p>Nato nel 1957 a<strong> Macerata<\/strong>, ex attaccante della <strong>Fiorentina<\/strong> negli anni &#8217;80,intraprende la carriera da allenatore nel 1990 alla guida della squadra giovanile della <strong>Ternana<\/strong>. Pochi anni pi\u00f9 tardi, nel 1995, diviene vice allenatore della <strong>Fiorentina<\/strong> per poi approdare nel 2005 a<strong> Ravenna<\/strong> con la quale ottiene la promozione in Serie B nella stagione 2006\/07. Nel 2009 viene chiamato in soccorso dal <strong>Virtus Lanciano<\/strong> in Prima Divisione di Lega Pro e subentra a <strong>Eusebio Di Francesco<\/strong> riuscendo a salvare la propria squadra ai play out vincendo contro la<strong> Juve Stabia<\/strong>. Nel 2011 a stagione in corso si mette alla guida tecnica del <strong>Pisa<\/strong> risollevandola dalla zona play out e portando la squadra al decimo posto con venti punti in dieci partite. Dopo la conferma nella stagione successiva viene esonerato a causa della sconfitta con il <strong>Lumezzane<\/strong> per poi essere richiamato in panchina. Con sei vittorie in sei partite conduce il Pisa ai play off perdendo per\u00f2 la finale contro il <strong>Latina<\/strong>. Il 23 dicembre, dopo la sconfitta nel derby col <strong>Viareggio<\/strong>, viene esonerato.<\/p>\n<p>Il profilo del nuovo allenatore del Lecce fa ben sperare vista la capacit\u00e0 dimostrata negli anni di riuscire a risollevare le squadre in difficolt\u00e0. Nella stagione 2006\/07 grazie alla promozione del Ravenna in Serie B ha vinto la <strong>panchina d&#8217;oro della Prima Divisione di Lega Pro<\/strong>, segno che le potenzialit\u00e0 di un tecnico poco conosciuto ai tifosi giallorossi ci sono e possono rivelarsi la soluzione ai momentanei problemi del Lecce. Nonostante la diffidenza del popolo salentino spetter\u00e0 a <strong>Dino Pagliari<\/strong> \u00a0risollevare le sorti di questa squadra. Domani presentazione alla stampa, poi subito il primo allenamento.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/27\/ufficiale-via-lerda-arriva-pagliari-conosciamo-da-vicino-il-nuovo-tecnico-del-lecce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/27\/ufficiale-via-lerda-arriva-pagliari-conosciamo-da-vicino-il-nuovo-tecnico-del-lecce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Laura Ricci________ La decisione di invertire la rotta presa dal Lecce dopo aver subito tre sconfitte consecutive, deludendo aspettative e prestazioni, implica che la famiglia Tesoro si sia messa in moto per sostituire il timoniere di\u00a0una barca pericolosamente in fase di affondo. Giunta l&#8217; ufficialit\u00e0 dell&#8217;esonero di Lerda, Antonio Tesoro, direttore sportivo del Lecce, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41995"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=41995"}],"version-history":[{"count":12,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41995\/revisions"}],"predecessor-version":[{"id":42029,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/41995\/revisions\/42029"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=41995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=41995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=41995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}