{"id":43948,"date":"2015-01-29T12:13:11","date_gmt":"2015-01-29T11:13:11","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=43948"},"modified":"2015-01-29T12:14:42","modified_gmt":"2015-01-29T11:14:42","slug":"sentenza-del-tar-di-lecce-equitalia-condannata-non-puo-rifiutarsi-di-fornire-al-cittadino-la-documentazione-relativa-alle-sommne-che-chiede-di-riscuotere","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/01\/29\/sentenza-del-tar-di-lecce-equitalia-condannata-non-puo-rifiutarsi-di-fornire-al-cittadino-la-documentazione-relativa-alle-sommne-che-chiede-di-riscuotere\/","title":{"rendered":"SENTENZA DEL TAR DI LECCE\/ EQUITALIA CONDANNATA: NON PUO&#8217; RIFIUTARSI DI FORNIRE AL CITTADINO LA DOCUMENTAZIONE RELATIVA ALLE SOMME CHE CHIEDE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/01\/intra_033744.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"199\" height=\"300\" title=\"intra_033744\" class=\"alignleft size-medium wp-image-43949\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/01\/intra_033744-199x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/01\/intra_033744-199x300.jpg 199w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/01\/intra_033744.jpg 300w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/a>(Rdl)_______Equitalia nega l\u2019accesso agli atti al contribuente, ed il TAR condanna la Societ\u00e0 di riscossione all\u2019esibizione dei documenti richiesti e alle spese di giudizio.<\/p>\n<p>Con una recentissima sentenza, la n. 357, depositata lo scorso 28 gennaio, la Seconda Sezione del Tar Lecce (nella foto), Presidente Trizzino e Relatore Rinaldi, ha ordinato a Equitalia Sud Spa di esibire al contribuente, entro trenta giorni, i documenti dallo stesso richiesti.<\/p>\n<p>La vicenda traeva origine dalla richiesta di accesso agli atti formulata dal contribuente, ignaro delle ragioni poste a base di una ingente pretesa economica pari ad \u20ac 1.000.000,00, richiesta con avvisi di pagamento notificati dall\u2019ente della riscossione per conto dell\u2019Amministrazione finanziaria.<\/p>\n<p>Il contribuente ricevuto il diniego si vedeva quindi costretto a rivolgersi, per il tramite degli avvocati Alberto Pepe e Alfredo Matranga, al TAR di Lecce per conoscere le ragioni della propria presunta posizione debitoria nei confronti di Equitalia.<\/p>\n<p>In particolare, Equitalia aveva posto a base del proprio diniego, da un lato, pretese esigenze afferenti la tutela della riservatezza di terzi e, dall\u2019altro, il presunto mancato invio da parte dello stesso contribuente della \u201cdelega\u201d e del \u201cdocumento di identit\u00e0\u201d del delegante e del delegato all\u2019accesso.<\/p>\n<p>Con la citata pronuncia il TAR leccese, qualificato giuridicamente tutelabile l\u2019interesse del contribuente ad accedere alla richiesta documentazione (in quanto destinatario degli avvisi di pagamento), ha ritenuto non idonea a giustificare il diniego di accesso la motivazione opposta dall\u2019Agente per la riscossione (mancata integrazione documentale), condannando Equitalia a consentire l\u2019accesso al contribuente nei successivi trenta giorni dalla pubblicazione della sentenza e condannando lo stesso Agente per la riscossione al pagamento delle spese di lite.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/01\/29\/sentenza-del-tar-di-lecce-equitalia-condannata-non-puo-rifiutarsi-di-fornire-al-cittadino-la-documentazione-relativa-alle-sommne-che-chiede-di-riscuotere\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/01\/29\/sentenza-del-tar-di-lecce-equitalia-condannata-non-puo-rifiutarsi-di-fornire-al-cittadino-la-documentazione-relativa-alle-sommne-che-chiede-di-riscuotere\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)_______Equitalia nega l\u2019accesso agli atti al contribuente, ed il TAR condanna la Societ\u00e0 di riscossione all\u2019esibizione dei documenti richiesti e alle spese di giudizio. Con una recentissima sentenza, la n. 357, depositata lo scorso 28 gennaio, la Seconda Sezione del Tar Lecce (nella foto), Presidente Trizzino e Relatore Rinaldi, ha ordinato a Equitalia Sud Spa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":43949,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/43948"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=43948"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/43948\/revisions"}],"predecessor-version":[{"id":43953,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/43948\/revisions\/43953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/43949"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=43948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=43948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=43948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}