{"id":44052,"date":"2015-01-31T15:10:05","date_gmt":"2015-01-31T14:10:05","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=44052"},"modified":"2015-01-31T15:10:05","modified_gmt":"2015-01-31T14:10:05","slug":"presentata-la-stagione-lirica-del-politeama-greco","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2015\/01\/31\/presentata-la-stagione-lirica-del-politeama-greco\/","title":{"rendered":"PRESENTATA LA STAGIONE LIRICA DEL POLITEAMA GRECO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/01\/untitled66.png\"><img decoding=\"async\" loading=\"lazy\" width=\"150\" height=\"114\" title=\"untitled\" class=\"alignleft size-thumbnail wp-image-44053\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2015\/01\/untitled66-150x114.png\" \/><\/a>L&#8217;UFFICIO &#8211; STAMPA DELLA PROVINCIA DI LECCE COMUNICA CHE<\/p>\n<p>&#8220;E\u2019 stata presentata questa mattina, nel foyer del Teatro Politeama Greco a Lecce, la 46^ Stagione Lirica Tradizionale della Provincia di Lecce.<\/p>\n<p>L\u2019edizione 2015 \u00e8 stata illustrata in conferenza stampa da Antonio Gabellone, presidente della Provincia di Lecce, Paolo Perrone, sindaco del Comune di Lecce, Simona Manca, consigliera provinciale, Carlo Antonio De Lucia, direttore artistico, Sonia Greco, in rappresentanza del Politeama.<\/p>\n<p>Il nuovo cartellone, messo a punto sotto la direzione artistica di Carlo Antonio De Lucia, sar\u00e0 di scena sul palcoscenico del Teatro Politeama Greco di Lecce, dal 27 febbraio al 26 aprile 2015.<\/p>\n<p>Ad alzare il sipario della 46^ Stagione Lirica Tradizionale della Provincia di Lecce venerd\u00ec 27 febbraio sar\u00e0 il Barbiere di Siviglia di Gioacchino Rossini (opera in due atti, libretto di Cesare Sterbini), con la regia di Bruno Pratic\u00f2 (ore 20.45). Maestro concertatore e direttore d\u2019orchestra sar\u00e0 Alberto Veronesi. La replica \u00e8 prevista per il 1\u00b0 marzo (ore 18).<\/p>\n<p>Il 20, 21 e 22 marzo sar\u00e0 la volta di Nabucco di Giuseppe Verdi (opera in quattro atti, libretto di Temistocle Solera), con la regia di Carlo Antonio De Lucia. Maestro concertatore e direttore d\u2019orchestra sar\u00e0 Francesco Ledda.<\/p>\n<p>Infine, il cartellone 2015 chiuder\u00e0 con Madama Butterfly di Giacomo Puccini, (opera in tre atti, libretto di Giuseppe Giacosa e Luigi Illica), in calendario il 25 e 26 aprile. La regia dell\u2019opera \u00e8 di Hiroki Ihara. Maestro concertatore e direttore d\u2019orchestra \u00e8 Daniele Agiman.<\/p>\n<p>Info biglietteria: 0832 241468&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2015\/01\/31\/presentata-la-stagione-lirica-del-politeama-greco\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2015\/01\/31\/presentata-la-stagione-lirica-del-politeama-greco\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>L&#8217;UFFICIO &#8211; STAMPA DELLA PROVINCIA DI LECCE COMUNICA CHE &#8220;E\u2019 stata presentata questa mattina, nel foyer del Teatro Politeama Greco a Lecce, la 46^ Stagione Lirica Tradizionale della Provincia di Lecce. L\u2019edizione 2015 \u00e8 stata illustrata in conferenza stampa da Antonio Gabellone, presidente della Provincia di Lecce, Paolo Perrone, sindaco del Comune di Lecce, Simona [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":44053,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/44052"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=44052"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/44052\/revisions"}],"predecessor-version":[{"id":44054,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/44052\/revisions\/44054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/44053"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=44052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=44052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=44052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}